{"id":414982,"date":"2023-02-27T17:41:58","date_gmt":"2023-02-27T16:41:58","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=414982"},"modified":"2023-02-27T17:41:58","modified_gmt":"2023-02-27T16:41:58","slug":"digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/","title":{"rendered":"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022"},"content":{"rendered":"<p><a href=\"https:\/\/www.digikey.fr\/?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">Digi-Key\u00a0Electronics<\/a> a annonc\u00e9 avoir consid\u00e9rablement \u00e9tendu son portefeuille en 2022 en ajoutant plus de 550\u00a0nouveaux fournisseurs dans le cadre de ses activit\u00e9s principales, de la\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/resources\/sell-on-dk?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">marketplace Digi-Key<\/a>\u00a0et du programme\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/resources\/sell-on-dk?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">Fulfilled by Digi-Key<\/a>. L&rsquo;entreprise a \u00e9galement ajout\u00e9 plus de 75\u00a0000\u00a0nouvelles r\u00e9f\u00e9rences \u00e0 son unit\u00e9 commerciale principale en\u00a02022.<br \/>\n\u00ab\u00a0En cette ann\u00e9e o\u00f9 l&rsquo;industrie \u00e9lectronique a retrouv\u00e9 un peu plus de normalit\u00e9, Digi-Key a poursuivi son engagement \u00e0 \u00eatre le distributeur du secteur \u00e0 proposer le plus grand choix de fournisseurs et l&rsquo;offre de produits la plus \u00e9tendue\u00a0\u00bb, a d\u00e9clar\u00e9 David\u00a0Stein, vice-pr\u00e9sident de la gestion des fournisseurs mondiaux chez Digi-Key. \u00ab\u00a0En 2022, nous avons continu\u00e9 \u00e0 am\u00e9liorer notre offre en proposant les toutes derni\u00e8res technologies et en renfor\u00e7ant notre position de leader gr\u00e2ce \u00e0 notre s\u00e9lection la plus compl\u00e8te de composants \u00e9lectroniques dans tous les groupes de produits.\u00a0\u00bb<br \/>\nParmi les fournisseurs cl\u00e9s ajout\u00e9s au portefeuille Digi-Key en 2022 figurent\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/supplier-centers\/airborn\/?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">AirBorn<\/a>, Endress+Hauser,\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/supplier-centers\/epc-space\/?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">EPC\u00a0Space<\/a>,\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/supplier-centers\/isabellenhuette\/?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">Isabellenhutte<\/a>\u00a0et\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/supplier-centers\/schneider-electric\/?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">Schneider\u00a0Electric<\/a>. Les fournisseurs de longue date, comme\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/supplier-centers\/amphenol\/?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">Amphenol<\/a>, continuent \u00e9galement d&rsquo;\u00e9tendre leurs offres en ajoutant de nouveaux produits issus de diff\u00e9rentes divisions.<br \/>\nDigi-Key continue \u00e9galement de diversifier ses produits et ses fournisseurs dans de nouvelles cat\u00e9gories de produits via sa\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/resources\/sell-on-dk?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">marketplace\u00a0Digi-Key<\/a>, une source unique pour tous les aspects de l&rsquo;innovation technologique, qu&rsquo;il s&rsquo;agisse de circuits imprim\u00e9s nus, de solutions IoT, d&rsquo;automatisation industrielle, de test et de mesure, et de pratiquement tout ce qui est li\u00e9 \u00e0 l&rsquo;innovation technologique, et ce, gr\u00e2ce \u00e0 une exp\u00e9rience d&rsquo;achat exceptionnelle. Un produit marketplace est typiquement exp\u00e9di\u00e9 sous 1 \u00e0 5\u00a0jours directement par le fournisseur. <br \/>\nEn utilisant l&rsquo;entrep\u00f4t et le centre logistique de pointe de Digi-Key, le programme\u00a0<a href=\"https:\/\/www.digikey.fr\/fr\/resources\/sell-on-dk?utm_source=referral&amp;utm_medium=pressrelease&amp;utm_campaign=pressrelease\">Fulfilled by Digi-Key<\/a>\u00a0offre les capacit\u00e9s d&rsquo;un entrep\u00f4t\u00a03PL, ainsi que l&rsquo;acc\u00e8s \u00e0 une base de clients mondiaux de longue date et \u00e0 un site Web de transaction et d&rsquo;ex\u00e9cution \u00e0 la demande de classe mondiale, pour commercialiser, vendre, s\u00e9lectionner, emballer et exp\u00e9dier les produits d&rsquo;un fournisseur dans le monde entier.<\/p>\n<h3><a href=\"https:\/\/www.digikey.fr\/\">digikey.fr<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Digi-Key\u00a0Electronics a annonc\u00e9 avoir consid\u00e9rablement \u00e9tendu son portefeuille en 2022 en ajoutant plus de 550\u00a0nouveaux fournisseurs dans le cadre de ses activit\u00e9s principales, de la\u00a0marketplace Digi-Key\u00a0et du programme\u00a0Fulfilled by Digi-Key. L&rsquo;entreprise a \u00e9galement ajout\u00e9 plus de 75\u00a0000\u00a0nouvelles r\u00e9f\u00e9rences \u00e0 son unit\u00e9 commerciale principale en\u00a02022. \u00ab\u00a0En cette ann\u00e9e o\u00f9 l&rsquo;industrie \u00e9lectronique a retrouv\u00e9 un peu plus [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":414983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[886],"tags":[],"domains":[47],"ppma_author":[1154],"class_list":["post-414982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseur...<\/title>\n<meta name=\"description\" content=\"Digi-Key\u00a0Electronics a annonc\u00e9 avoir consid\u00e9rablement \u00e9tendu son portefeuille en 2022 en ajoutant plus de 550\u00a0nouveaux fournisseurs dans le cadre de ses...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/414982\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022\" \/>\n<meta property=\"og:description\" content=\"Digi-Key\u00a0Electronics a annonc\u00e9 avoir consid\u00e9rablement \u00e9tendu son portefeuille en 2022 en ajoutant plus de 550\u00a0nouveaux fournisseurs dans le cadre de ses activit\u00e9s principales, de la\u00a0marketplace Digi-Key\u00a0et du programme\u00a0Fulfilled by Digi-Key. L&rsquo;entreprise a \u00e9galement ajout\u00e9 plus de 75\u00a0000\u00a0nouvelles r\u00e9f\u00e9rences \u00e0 son unit\u00e9 commerciale principale en\u00a02022. \u00ab\u00a0En cette ann\u00e9e o\u00f9 l&rsquo;industrie \u00e9lectronique a retrouv\u00e9 un peu plus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/414982\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-27T16:41:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/2023\/02\/ECI1715_DK_actu-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\"},\"headline\":\"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022\",\"datePublished\":\"2023-02-27T16:41:58+00:00\",\"dateModified\":\"2023-02-27T16:41:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Actualit\u00e9 g\u00e9n\u00e9rale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/\",\"url\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/\",\"name\":\"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022 -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2023-02-27T16:41:58+00:00\",\"dateModified\":\"2023-02-27T16:41:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"},\"sameAs\":[\"http:\/\/ECINews\"]}]}<\/script>","yoast_head_json":{"title":"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseur...","description":"Digi-Key\u00a0Electronics a annonc\u00e9 avoir consid\u00e9rablement \u00e9tendu son portefeuille en 2022 en ajoutant plus de 550\u00a0nouveaux fournisseurs dans le cadre de ses...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/414982\/","og_locale":"fr_FR","og_type":"article","og_title":"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022","og_description":"Digi-Key\u00a0Electronics a annonc\u00e9 avoir consid\u00e9rablement \u00e9tendu son portefeuille en 2022 en ajoutant plus de 550\u00a0nouveaux fournisseurs dans le cadre de ses activit\u00e9s principales, de la\u00a0marketplace Digi-Key\u00a0et du programme\u00a0Fulfilled by Digi-Key. L&rsquo;entreprise a \u00e9galement ajout\u00e9 plus de 75\u00a0000\u00a0nouvelles r\u00e9f\u00e9rences \u00e0 son unit\u00e9 commerciale principale en\u00a02022. \u00ab\u00a0En cette ann\u00e9e o\u00f9 l&rsquo;industrie \u00e9lectronique a retrouv\u00e9 un peu plus [&hellip;]","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/414982\/","og_site_name":"EENewsEurope","article_published_time":"2023-02-27T16:41:58+00:00","og_image":[{"width":1080,"height":772,"url":"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/2023\/02\/ECI1715_DK_actu-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/#article","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762"},"headline":"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022","datePublished":"2023-02-27T16:41:58+00:00","dateModified":"2023-02-27T16:41:58+00:00","mainEntityOfPage":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/"},"wordCount":365,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Actualit\u00e9 g\u00e9n\u00e9rale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/","url":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/","name":"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022 -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2023-02-27T16:41:58+00:00","dateModified":"2023-02-27T16:41:58+00:00","breadcrumb":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdn.eenewseurope.com\/fr\/digi-key-electronics-a-ajoute-plus-de-550-nouveaux-fournisseurs-et-75-000-references-en-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Digi-Key Electronics a ajout\u00e9 plus de 550 nouveaux fournisseurs et 75 000 r\u00e9f\u00e9rences en 2022"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75","url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","caption":"Alain Dieul"},"sameAs":["http:\/\/ECINews"]}]}},"authors":[{"term_id":1154,"user_id":36,"is_guest":0,"slug":"alain-dieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/414982"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=414982"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/414982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/414983"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=414982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=414982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=414982"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=414982"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=414982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}