{"id":41230,"date":"2020-11-05T06:40:44","date_gmt":"2020-11-05T06:40:44","guid":{"rendered":"https:\/\/\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/"},"modified":"2020-11-05T06:40:44","modified_gmt":"2020-11-05T06:40:44","slug":"diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/","title":{"rendered":"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles"},"content":{"rendered":"<p>Pour les d\u00e9veloppeurs de syst\u00e8mes destin\u00e9s aux v\u00e9hicules \u00e9lectriques (d\u00e9veloppeurs EV) qui doivent augmenter l&rsquo;efficacit\u00e9 syst\u00e8me tout en maintenant une qualit\u00e9 \u00e9lev\u00e9e, les composants certifi\u00e9s AEC-Q101 de Microchip permettent de maximiser la fiabilit\u00e9 et la robustesse du syst\u00e8me et de garantir une dur\u00e9e de vie de l\u2019application stable et durable. Les&nbsp;multiples&nbsp;performances in\u00e9gal\u00e9es des composants permettent aux d\u00e9veloppeurs d\u2019avoir moins recours \u00e0 des circuits de protection externes, r\u00e9duisant ainsi les co\u00fbts syst\u00e8me et leur complexit\u00e9.<\/p>\n<p>\u00ab&nbsp;En tant que fournisseur de longue date de l\u2019industrie automobile, le d\u00e9veloppement permanent de nouvelles solutions d\u2019alimentation qualifi\u00e9es pour l\u2019automobile par Microchip montre la voie pour la transformation des syst\u00e8mes d\u2019alimentation sur les v\u00e9hicules \u00e9lectriques&nbsp;\u00bb, explique Leon Gross, vice-pr\u00e9sident du d\u00e9partement des produits discrets chez Microchip. \u00ab&nbsp;Notre objectif est de fournir des solutions automobiles qui aident nos clients \u00e0 op\u00e9rer facilement la transition vers les composants au carbure de silicium (SiC) tout en minimisant les risques pour la qualit\u00e9, tout comme les probl\u00e8mes d\u2019approvisionnement et de support technique.&nbsp;\u00bb<\/p>\n<p>Gr\u00e2ce aux tests effectu\u00e9s par Microchip et par des organismes tiers, des indicateurs de fiabilit\u00e9 critiques ont montr\u00e9 que les composants de Microchip affichent des performances sup\u00e9rieures par rapport \u00e0 d\u2019autres composants SiC. Contrairement aux autres composants SiC,&nbsp;qui se d\u00e9gradent quand ils sont utilis\u00e9s en conditions extr\u00eames, les composants Microchip ne montrent aucune alt\u00e9ration en termes de performances, augmentant ainsi la dur\u00e9e de vie de l\u2019application. Les solutions SiC de Microchip sont leaders du march\u00e9 sur le plan de la fiabilit\u00e9 et de la robustesse.&nbsp;<\/p>\n<p>Les tests de robustesse des diodes Schottky SiC de la soci\u00e9t\u00e9 montrent une r\u00e9sistance \u00e0 l\u2019\u00e9nergie 20&nbsp;% sup\u00e9rieure dans les commutations inductives sans blocage (UIS,&nbsp;Unclamped Inductive Switching), et des courants de fuites parmi les plus faibles \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es, ce qui augmente la dur\u00e9e de vie du syst\u00e8me en permettant un fonctionnement plus fiable.&nbsp;<\/p>\n<p><strong><u>Outils de d\u00e9veloppement<\/u><\/strong><\/p>\n<p>Les composants SBD SiC certifi\u00e9s AEC-Q101 de Microchip sont compatibles avec les mod\u00e8les de simulation SPICE et PLECS ainsi qu\u2019avec le simulateur MPLAB Mindi Analog Simulator. Il existe \u00e9galement un mod\u00e8le de syst\u00e8me de r\u00e9f\u00e9rence PLECS qui utilise les SBD de Microchip (1200&nbsp;V, 50&nbsp;A) appartenant \u00e0 l\u2019\u00e9tage d\u2019alimentation&nbsp;: le&nbsp;syst\u00e8me de r\u00e9f\u00e9rence \u00e0 correction de facteur de puissance (PFC) triphas\u00e9 Vienna.<\/p>\n<p><a href=\"http:\/\/www.microchip.com\/\">www.microchip.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Face \u00e0 la multiplication des v\u00e9hicules \u00e9lectriques dans le monde, des technologies d\u2019alimentation innovantes comme la technologie SiC (carbure de silicium) sont requises pour les syst\u00e8mes automobiles \u00e0 haute tension, des moteurs aux stations de chargement \u00e0 bord des v\u00e9hicules en passant par les convertisseurs DC-DC. Microchip Technology Inc. annonce des composants d\u2019alimentation SBD, des diodes Schottky SiC 700 V et 1200 V r\u00e9cemment certifi\u00e9es, offrant aux d\u00e9veloppeurs de syst\u00e8mes de v\u00e9hicules \u00e9lectriques des solutions qui respectent les normes de qualit\u00e9 automobile strictes tout en proposant un large \u00e9ventail d\u2019options de tensions, de courants et de bo\u00eetiers.<\/p>\n","protected":false},"author":9,"featured_media":41231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-41230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Diodes Schottky au carbure de silicium 700 V et 1200 V pour app...<\/title>\n<meta name=\"description\" content=\"Face \u00e0 la multiplication des v\u00e9hicules \u00e9lectriques dans le monde, des technologies d\u2019alimentation innovantes comme la technologie SiC (carbure de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/41230\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles\" \/>\n<meta property=\"og:description\" content=\"Face \u00e0 la multiplication des v\u00e9hicules \u00e9lectriques dans le monde, des technologies d\u2019alimentation innovantes comme la technologie SiC (carbure de silicium) sont requises pour les syst\u00e8mes automobiles \u00e0 haute tension, des moteurs aux stations de chargement \u00e0 bord des v\u00e9hicules en passant par les convertisseurs DC-DC. Microchip Technology Inc. annonce des composants d\u2019alimentation SBD, des diodes Schottky SiC 700 V et 1200 V r\u00e9cemment certifi\u00e9es, offrant aux d\u00e9veloppeurs de syst\u00e8mes de v\u00e9hicules \u00e9lectriques des solutions qui respectent les normes de qualit\u00e9 automobile strictes tout en proposant un large \u00e9ventail d\u2019options de tensions, de courants et de bo\u00eetiers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/41230\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-05T06:40:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8895_microchip_0-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles\",\"datePublished\":\"2020-11-05T06:40:44+00:00\",\"dateModified\":\"2020-11-05T06:40:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/\"},\"wordCount\":455,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/\",\"name\":\"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-11-05T06:40:44+00:00\",\"dateModified\":\"2020-11-05T06:40:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Diodes Schottky au carbure de silicium 700 V et 1200 V pour app...","description":"Face \u00e0 la multiplication des v\u00e9hicules \u00e9lectriques dans le monde, des technologies d\u2019alimentation innovantes comme la technologie SiC (carbure de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/41230\/","og_locale":"fr_FR","og_type":"article","og_title":"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles","og_description":"Face \u00e0 la multiplication des v\u00e9hicules \u00e9lectriques dans le monde, des technologies d\u2019alimentation innovantes comme la technologie SiC (carbure de silicium) sont requises pour les syst\u00e8mes automobiles \u00e0 haute tension, des moteurs aux stations de chargement \u00e0 bord des v\u00e9hicules en passant par les convertisseurs DC-DC. Microchip Technology Inc. annonce des composants d\u2019alimentation SBD, des diodes Schottky SiC 700 V et 1200 V r\u00e9cemment certifi\u00e9es, offrant aux d\u00e9veloppeurs de syst\u00e8mes de v\u00e9hicules \u00e9lectriques des solutions qui respectent les normes de qualit\u00e9 automobile strictes tout en proposant un large \u00e9ventail d\u2019options de tensions, de courants et de bo\u00eetiers.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/41230\/","og_site_name":"EENewsEurope","article_published_time":"2020-11-05T06:40:44+00:00","og_image":[{"width":2560,"height":1422,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8895_microchip_0-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles","datePublished":"2020-11-05T06:40:44+00:00","dateModified":"2020-11-05T06:40:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/"},"wordCount":455,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/","url":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/","name":"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-11-05T06:40:44+00:00","dateModified":"2020-11-05T06:40:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/diodes-schottky-au-carbure-de-silicium-700-v-et-1200-v-pour-applications-automobiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Diodes Schottky au carbure de silicium 700 V et 1200 V pour applications automobiles"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/41230"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=41230"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/41230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/41231"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=41230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=41230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=41230"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=41230"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=41230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}