{"id":40358,"date":"2020-11-16T08:49:44","date_gmt":"2020-11-16T08:49:44","guid":{"rendered":"https:\/\/\/synopsys-rachete-moortec-pour-concurrencer-mentor\/"},"modified":"2020-11-16T08:49:44","modified_gmt":"2020-11-16T08:49:44","slug":"synopsys-rachete-moortec-pour-concurrencer-mentor","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/","title":{"rendered":"Synopsys rach\u00e8te Moortec pour concurrencer Mentor"},"content":{"rendered":"<p><!-- Global site tag (gtag.js) - Google Analytics --><br \/>\n  window.dataLayer = window.dataLayer || [];<br \/>\n  function gtag(){dataLayer.push(arguments);}<br \/>\n  gtag(&lsquo;js&rsquo;, new Date());  gtag(&lsquo;config&rsquo;, &lsquo;UA-160857065-1&rsquo;);<\/p>\n<p><span class=\"tlid-translation translation\" lang=\"fr\">Synopsys a achet\u00e9 Moortec, concepteur d&rsquo;IP bas\u00e9 \u00e0 Plymouth, pour sa technologie de surveillance int\u00e9gr\u00e9e dans les puces, sp\u00e9cialis\u00e9e dans les capteurs de process, de tension et de temp\u00e9rature (PVT). La valeur de la transaction n&rsquo;a pas \u00e9t\u00e9 divulgu\u00e9e car Synopsys affirme qu&rsquo;elle n&rsquo;est pas importante pour ses rapports financiers.<\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"fr\">Les capteurs Moortec constituent un \u00e9l\u00e9ment cl\u00e9 de la nouvelle plate-forme Silicon Lifecycle Management (SLM) de Synopsys. Cela permettra \u00e0 Synopsys de concurrencer l&rsquo;activit\u00e9 Mentor de Siemens avec des donn\u00e9es provenant de puces complexes sur des processus de pointe. En juin, Mentor a acquis UltraSoC, bas\u00e9 \u00e0 Cambridge, qui fournit \u00e9galement une surveillance int\u00e9gr\u00e9e \u00e0 la puce, mais de donn\u00e9es plut\u00f4t que de valeurs physiques.<\/span><\/p>\n<p><a href=\"https:\/\/www.eenewseurope.com\/news\/siemens-takes-over-uk-chip-level-analytics-expert-ultrasoc\">SIEMENS TAKES OVER UK CHIP-LEVEL ANALYTICS EXPERT ULTRASOC<\/a>&nbsp;&nbsp;<\/p>\n<p><span class=\"tlid-translation translation\" lang=\"fr\">Les donn\u00e9es des capteurs environnementaux de Moortec sont essentielles pour bien comprendre l&rsquo;activit\u00e9 et le fonctionnement des puces et permettront aux moteurs d&rsquo;analyse de la plate-forme SLM de conduire des optimisations plus d\u00e9taill\u00e9es et pr\u00e9cises \u00e0 chaque \u00e9tape du cycle de vie des semiconducteurs, en commen\u00e7ant par la mise en \u0153uvre de la conception et en progressant dans la fabrication, les tests de production, la mise ne fonctionnement et culminant avec des op\u00e9rations sur le terrain. C&rsquo;est la m\u00eame strat\u00e9gie que les outils Tessent de Mentor.<\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"fr\">\u00abNous continuons de respecter notre feuille de route d&rsquo;innovation pour fournir des solutions d&rsquo;optimisation du cycle de vie des semiconducteurs silicium qui r\u00e9pondent aux besoins en constante \u00e9volution de l&rsquo;industrie dynamique des semi-onducteurs\u00bb, a d\u00e9clar\u00e9 Sassine Ghazi, directeur de l&rsquo;exploitation de Synopsys. \u00abCette acquisition acc\u00e9l\u00e8re l&rsquo;expansion de notre plate-forme SLM en fournissant \u00e0 nos clients une solution compl\u00e8te d&rsquo;analyse de donn\u00e9es pour les composants fabriqu\u00e9s avec les processus les plus avanc\u00e9s.\u00bb<\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"fr\">La surveillance dans la puce est d\u00e9sormais une n\u00e9cessit\u00e9 au niveau des n\u0153uds de processus avanc\u00e9s car elle permet la gestion critique de conditions physiques et fonctionnelles de plus en plus variables en temps r\u00e9el, augmentant ainsi les performances et la fiabilit\u00e9. Les capteurs PVT int\u00e9gr\u00e9s \u00e0 la puce et les sous-syst\u00e8mes de contr\u00f4le de Moortec ont \u00e9t\u00e9 utilis\u00e9s dans des centaines de conceptions de puces sur tous les n\u0153uds de processus courants jusqu&rsquo;\u00e0 5 nm.<\/span><\/p>\n<p><span class=\"tlid-translation translation\" lang=\"fr\">En plus de fournir des informations en temps r\u00e9el sur la puce, les donn\u00e9es des capteurs Moortec seront d\u00e9sormais extraites et transmises aux moteurs d&rsquo;analyse de la plate-forme. Les donn\u00e9es environnementales fournies par ces capteurs sont un \u00e9l\u00e9ment essentiel pour bien comprendre les activit\u00e9s complexes au sein de la puce. La combinaison de ces informations avec les donn\u00e9es d&rsquo;autres moniteurs structurels et fonctionnels fournit les donn\u00e9es riches n\u00e9cessaires pour obtenir les meilleures optimisations tout au long du cycle de vie.<\/span><\/p>\n<p><strong>Lire aussi:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.synopsys.com\">www.synopsys.com<\/a>; <a href=\"http:\/\/www.moortec.com\">www.moortec.com<\/a><\/p>\n<p><strong>Related articles<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/chip-sensor-fabric-moves-6nm\">IN-CHIP SENSOR FABRIC MOVES TO 6nm<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewsanalog.com\/news\/moortec-recasts-chip-thermal-sensor-tsmc-n5-process\">MOORTEC RECASTS IN-CHIP THERMAL SENSOR FOR TSMC N5 PROCESS<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/chip-technology-highly-distributed-real-time-thermal-analysis\">IN-CHIP TECHNOLOGY FOR HIGHLY DISTRIBUTED REAL-TIME THERMAL ANALYSIS<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/ultrasoc-deal-siemens-restructure\">ULTRASOC DEAL TRIGGERS SIEMENS TEST CHANGES<\/a><\/li>\n<\/ul>\n<p><strong>Other articles on eeNews Europe&nbsp;<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/sondrel-tapes-out-its-largest-chip\">Sondrel tapes out its largest chip<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/tech-war-despite-us-election\">Tech war is on, says Infineon<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/tsmc-confirms-5nm-fab-us\">TSMC confirms 5nm fab in US<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/congatec-looks-acquisitions-after-private-equity-sale\">congatec looks to acquisitions after private equity sale<\/a><\/li>\n<li><a href=\"https:\/\/www.eenewseurope.com\/news\/tuv-sud-launches-technical-advisory-service-uk-approvals\">T\u00dcV S\u00dcD launches&nbsp;Technical Advisory Service for UK approvals<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Synopsys ach\u00e8te Moortec, d\u00e9veloppeur britannique d&rsquo;IP de surveillance int\u00e9gr\u00e9e \u00e0 la puce, pour renforcer sa nouvelle plateforme de gestion du cycle de vie de circuits int\u00e9gr\u00e9s.<\/p>\n","protected":false},"author":12,"featured_media":40359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[880],"tags":[899,911],"domains":[47],"ppma_author":[1144],"class_list":["post-40358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-economiques","tag-eda-cad-tools-fr","tag-testandmeasurement-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Synopsys rach\u00e8te Moortec pour concurrencer Mentor ...<\/title>\n<meta name=\"description\" content=\"Synopsys ach\u00e8te Moortec, d\u00e9veloppeur britannique d&#039;IP de surveillance int\u00e9gr\u00e9e \u00e0 la puce, pour renforcer sa nouvelle plateforme de gestion du cycle de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/40358\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Synopsys rach\u00e8te Moortec pour concurrencer Mentor\" \/>\n<meta property=\"og:description\" content=\"Synopsys ach\u00e8te Moortec, d\u00e9veloppeur britannique d&#039;IP de surveillance int\u00e9gr\u00e9e \u00e0 la puce, pour renforcer sa nouvelle plateforme de gestion du cycle de vie de circuits int\u00e9gr\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/40358\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-16T08:49:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/2020-11-12-moortec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andre Rousselot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andre Rousselot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/\"},\"author\":{\"name\":\"Andre Rousselot\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/9d52edb517ca8d9017312e8e246b9433\"},\"headline\":\"Synopsys rach\u00e8te Moortec pour concurrencer Mentor\",\"datePublished\":\"2020-11-16T08:49:44+00:00\",\"dateModified\":\"2020-11-16T08:49:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/\"},\"wordCount\":602,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"EDA &amp; CAD tools\",\"TestandMeasurement\"],\"articleSection\":[\"Actualit\u00e9s \u00e9conomiques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/\",\"url\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/\",\"name\":\"Synopsys rach\u00e8te Moortec pour concurrencer Mentor -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-11-16T08:49:44+00:00\",\"dateModified\":\"2020-11-16T08:49:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Synopsys rach\u00e8te Moortec pour concurrencer Mentor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/9d52edb517ca8d9017312e8e246b9433\",\"name\":\"Andre Rousselot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/8046680f16f52d2ae022297dc9e36ff3\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/428720feffa09baddfe5e7cd3f84b526?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/428720feffa09baddfe5e7cd3f84b526?s=96&d=mm&r=g\",\"caption\":\"Andre Rousselot\"}}]}<\/script>","yoast_head_json":{"title":"Synopsys rach\u00e8te Moortec pour concurrencer Mentor ...","description":"Synopsys ach\u00e8te Moortec, d\u00e9veloppeur britannique d'IP de surveillance int\u00e9gr\u00e9e \u00e0 la puce, pour renforcer sa nouvelle plateforme de gestion du cycle de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/40358\/","og_locale":"fr_FR","og_type":"article","og_title":"Synopsys rach\u00e8te Moortec pour concurrencer Mentor","og_description":"Synopsys ach\u00e8te Moortec, d\u00e9veloppeur britannique d'IP de surveillance int\u00e9gr\u00e9e \u00e0 la puce, pour renforcer sa nouvelle plateforme de gestion du cycle de vie de circuits int\u00e9gr\u00e9s.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/40358\/","og_site_name":"EENewsEurope","article_published_time":"2020-11-16T08:49:44+00:00","og_image":[{"width":595,"height":446,"url":"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/2020-11-12-moortec.jpg","type":"image\/jpeg"}],"author":"Andre Rousselot","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andre Rousselot","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/#article","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/"},"author":{"name":"Andre Rousselot","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/9d52edb517ca8d9017312e8e246b9433"},"headline":"Synopsys rach\u00e8te Moortec pour concurrencer Mentor","datePublished":"2020-11-16T08:49:44+00:00","dateModified":"2020-11-16T08:49:44+00:00","mainEntityOfPage":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/"},"wordCount":602,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["EDA &amp; CAD tools","TestandMeasurement"],"articleSection":["Actualit\u00e9s \u00e9conomiques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/","url":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/","name":"Synopsys rach\u00e8te Moortec pour concurrencer Mentor -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-11-16T08:49:44+00:00","dateModified":"2020-11-16T08:49:44+00:00","breadcrumb":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdn.eenewseurope.com\/fr\/synopsys-rachete-moortec-pour-concurrencer-mentor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Synopsys rach\u00e8te Moortec pour concurrencer Mentor"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/9d52edb517ca8d9017312e8e246b9433","name":"Andre Rousselot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/8046680f16f52d2ae022297dc9e36ff3","url":"https:\/\/secure.gravatar.com\/avatar\/428720feffa09baddfe5e7cd3f84b526?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/428720feffa09baddfe5e7cd3f84b526?s=96&d=mm&r=g","caption":"Andre Rousselot"}}]}},"authors":[{"term_id":1144,"user_id":12,"is_guest":0,"slug":"rousselot","display_name":"Andre Rousselot","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/428720feffa09baddfe5e7cd3f84b526?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/40358"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=40358"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/40358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/40359"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=40358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=40358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=40358"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=40358"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=40358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}