{"id":392753,"date":"2022-08-18T10:28:00","date_gmt":"2022-08-18T08:28:00","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=392753"},"modified":"2022-08-18T10:28:00","modified_gmt":"2022-08-18T08:28:00","slug":"rohde-schwarz-participe-a-6g-anna","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/rohde-schwarz-participe-a-6g-anna\/","title":{"rendered":"Rohde &#038; Schwarz participe \u00e0 6G-ANNA"},"content":{"rendered":"<p>Le projet phare intitul\u00e9 6G-ANNA a \u00e9t\u00e9 lanc\u00e9 pour une dur\u00e9e de trois ans par le minist\u00e8re f\u00e9d\u00e9ral allemand de l&rsquo;\u00e9ducation et de la recherche (Bundesministerium f\u00fcr Bildung und Forschung, BMBF). Gr\u00e2ce \u00e0 la collaboration des 29 entreprises et instituts de recherche, le consortium dirig\u00e9 par Nokia vise \u00e0 faire progresser le d\u00e9veloppement, la normalisation et la mise en \u0153uvre des technologies de communication mobile de prochaine g\u00e9n\u00e9ration. Rohde &amp; Schwarz participe \u00e0 ce projet en s&rsquo;appuyant sur l&rsquo;ensemble de ses travaux de recherche que l&rsquo;entreprise m\u00e8ne sur la 6G et les technologies connexes.<\/p>\n<p>Alors que la 5G est toujours en cours de d\u00e9ploiement en Allemagne, le BMBF a d\u00e9j\u00e0 lanc\u00e9 des programmes visant \u00e0 fa\u00e7onner et mettre en \u0153uvre la 6G. Le nouveau projet phare baptis\u00e9 6G-ANNA (6G Access, Network of Networks and Automation) fait partie d&rsquo;une plus vaste initiative intitul\u00e9e \u00ab\u00a06G Platform Germany\u00a0\u00bb. Lanc\u00e9 le 1er juillet 2022 pour une dur\u00e9e de 3 ans, le projet 6G-ANNA, dirig\u00e9 par Nokia, est financ\u00e9 par le BMBF \u00e0 hauteur de 38,4 millions d&rsquo;euros. Rohde &amp; Schwarz fait partie des partenaires industriels du consortium qui est constitu\u00e9 d&rsquo;entreprises renomm\u00e9es telles qu&rsquo;Airbus, Bosch, Ericsson, Siemens et Vodafone, ainsi que de jeunes entreprises innovantes, d&rsquo;instituts de recherche et d&rsquo;universit\u00e9s r\u00e9put\u00e9es.<br \/>\nRohde &amp; Schwarz s&rsquo;est d\u00e8s l&rsquo;origine \u00e9troitement impliqu\u00e9 dans le domaine de la recherche au-del\u00e0 de la 5G et dans le d\u00e9veloppement de la 6G. L&rsquo;entreprise soutient activement les activit\u00e9s de recherche fondamentale actuellement conduites au sein des organisations relatives \u00e0 la 6G, les universit\u00e9s et les instituts de recherche en Europe, aux \u00c9tats-Unis et au Japon. Elle est d\u00e9j\u00e0 tr\u00e8s investie en mati\u00e8re de recherche li\u00e9e aux diverses technologies qui devraient jouer un r\u00f4le essentiel dans le d\u00e9veloppement de la 6G, telles que la communication (sub-)THz, la communication et la d\u00e9tection conjointes (JCAS), l&rsquo;intelligence artificielle (AI) et le machine learning (ML) ou les surfaces intelligentes reconfigurables (RIS). La premi\u00e8re sp\u00e9cification de la 6G \u00e9tablie au niveau mondial est attendue dans les six \u00e0 huit prochaines ann\u00e9es. Le lancement commercial de la technologie devrait d\u00e9buter vers 2030.<\/p>\n<p><a href=\"https:\/\/www.rohde-schwarz.com\/6G\">https:\/\/www.rohde-schwarz.com\/6G<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re f\u00e9d\u00e9ral allemand de l&rsquo;\u00e9ducation et de la recherche a d&rsquo;ores et d\u00e9j\u00e0 lanc\u00e9 des programmes visant \u00e0 fa\u00e7onner et mettre en \u0153uvre la 6G en Allemagne.<\/p>\n","protected":false},"author":36,"featured_media":392754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[886],"tags":[1076],"domains":[47],"ppma_author":[1154],"class_list":["post-392753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr","tag-communications-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Rohde &amp; Schwarz participe \u00e0 6G-ANNA ...<\/title>\n<meta name=\"description\" content=\"Le minist\u00e8re f\u00e9d\u00e9ral allemand de l&#039;\u00e9ducation et de la recherche a d&#039;ores et d\u00e9j\u00e0 lanc\u00e9 des programmes visant \u00e0 fa\u00e7onner et mettre en \u0153uvre la 6G en...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/392753\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rohde &amp; Schwarz participe \u00e0 6G-ANNA\" \/>\n<meta property=\"og:description\" content=\"Le minist\u00e8re f\u00e9d\u00e9ral allemand de l&#039;\u00e9ducation et de la recherche a d&#039;ores et d\u00e9j\u00e0 lanc\u00e9 des programmes visant \u00e0 fa\u00e7onner et mettre en \u0153uvre la 6G en Allemagne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/392753\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T08:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2022\/08\/ECI1369_Rohde-Schwarz_actu-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1028\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\"},\"headline\":\"Rohde &#038; Schwarz participe \u00e0 6G-ANNA\",\"datePublished\":\"2022-08-18T08:28:00+00:00\",\"dateModified\":\"2022-08-18T08:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"communications\"],\"articleSection\":[\"Actualit\u00e9 g\u00e9n\u00e9rale\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/\",\"name\":\"Rohde & Schwarz participe \u00e0 6G-ANNA -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-08-18T08:28:00+00:00\",\"dateModified\":\"2022-08-18T08:28:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rohde &#038; Schwarz participe \u00e0 6G-ANNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"},\"sameAs\":[\"http:\/\/ECINews\"]}]}<\/script>","yoast_head_json":{"title":"Rohde & Schwarz participe \u00e0 6G-ANNA ...","description":"Le minist\u00e8re f\u00e9d\u00e9ral allemand de l'\u00e9ducation et de la recherche a d'ores et d\u00e9j\u00e0 lanc\u00e9 des programmes visant \u00e0 fa\u00e7onner et mettre en \u0153uvre la 6G en...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/392753\/","og_locale":"fr_FR","og_type":"article","og_title":"Rohde & Schwarz participe \u00e0 6G-ANNA","og_description":"Le minist\u00e8re f\u00e9d\u00e9ral allemand de l'\u00e9ducation et de la recherche a d'ores et d\u00e9j\u00e0 lanc\u00e9 des programmes visant \u00e0 fa\u00e7onner et mettre en \u0153uvre la 6G en Allemagne.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/392753\/","og_site_name":"EENewsEurope","article_published_time":"2022-08-18T08:28:00+00:00","og_image":[{"width":1080,"height":1028,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/2022\/08\/ECI1369_Rohde-Schwarz_actu-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762"},"headline":"Rohde &#038; Schwarz participe \u00e0 6G-ANNA","datePublished":"2022-08-18T08:28:00+00:00","dateModified":"2022-08-18T08:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/"},"wordCount":391,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["communications"],"articleSection":["Actualit\u00e9 g\u00e9n\u00e9rale"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/","url":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/","name":"Rohde & Schwarz participe \u00e0 6G-ANNA -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-08-18T08:28:00+00:00","dateModified":"2022-08-18T08:28:00+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/rohde-schwarz-participe-a-6g-anna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Rohde &#038; Schwarz participe \u00e0 6G-ANNA"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75","url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","caption":"Alain Dieul"},"sameAs":["http:\/\/ECINews"]}]}},"authors":[{"term_id":1154,"user_id":36,"is_guest":0,"slug":"alain-dieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/392753"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=392753"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/392753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/392754"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=392753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=392753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=392753"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=392753"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=392753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}