{"id":38895,"date":"2020-12-11T00:31:44","date_gmt":"2020-12-11T00:31:44","guid":{"rendered":"https:\/\/\/relais-compact-500vdc-pour-electronique-de-charge\/"},"modified":"2020-12-11T00:31:44","modified_gmt":"2020-12-11T00:31:44","slug":"relais-compact-500vdc-pour-electronique-de-charge","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/","title":{"rendered":"Relais compact 500VDC pour \u00e9lectronique de charge"},"content":{"rendered":"<p>Le G2RG-X allie une impressionnante capacit\u00e9 de commutation (500&nbsp;Vcc, 10&nbsp;A) \u00e0 une conception compacte et un faible encombrement de 13,5&nbsp;mm&nbsp;x 29&nbsp;mm pour une hauteur de 26,5&nbsp;mm. La performance exceptionnelle de ce petit composant r\u00e9sulte de la structure de contr\u00f4le d&rsquo;arc d\u00e9velopp\u00e9e par Omron et d&rsquo;un intervalle de contact de 3&nbsp;mm. Parmi ses autres fonctionnalit\u00e9s, on note \u00e9galement un haut niveau d&rsquo;isolation, avec une distance de 8&nbsp;mm et une tension de tension de tenue au choc de 10&nbsp;kV entre la bobine et les contacts.&nbsp; Le G2RG-X pr\u00e9sente une faible consommation de tout juste 0,8&nbsp;W et ne comporte qu&rsquo;une bobine au lieu des deux bobines dans des solutions alternatives, ce qui r\u00e9duit d&rsquo;autant la perte d&rsquo;\u00e9nergie \u00e0 l&rsquo;int\u00e9rieur du dispositif. Con\u00e7u pour le raccordement \u00e0 2&nbsp;p\u00f4les, ce relais prend en charge 10&nbsp;000&nbsp;op\u00e9rations dans cette configuration. Il est assorti des certifications UL et T\u00dcV.&nbsp;<\/p>\n<p><a href=\"http:\/\/components.omron.eu\u00a0\u00a0\">components.omron.eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Omron Electronic Components Europe vient d&rsquo;annoncer la sortie d&rsquo;un relais d&rsquo;alimentation compact de 500\u00a0Vcc destin\u00e9 aux syst\u00e8mes de pr\u00e9charge des v\u00e9hicules \u00e9lectriques, batteries de secours des panneaux solaires et d&rsquo;autres applications de courant continu de haute intensit\u00e9.  Caract\u00e9ris\u00e9 par sa haute capacit\u00e9 de commutation et sa forte isolation, le nouvel G2RG-X convient parfaitement au contr\u00f4le des courants d&rsquo;appel, pour prot\u00e9ger, par exemple, les circuits p\u00e9riph\u00e9riques au d\u00e9but du rechargement des batteries, et dans le fonctionnement des syst\u00e8mes de stockage d&rsquo;\u00e9nergie, des convertisseurs, des servom\u00e9canismes, des blocs d&rsquo;alimentation et des alimentations ininterrompues. <\/p>\n","protected":false},"author":9,"featured_media":164388,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-38895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Relais compact 500VDC pour \u00e9lectronique de charge ...<\/title>\n<meta name=\"description\" content=\"Omron Electronic Components Europe vient d&#039;annoncer la sortie d&#039;un relais d&#039;alimentation compact de 500\u00a0Vcc destin\u00e9 aux syst\u00e8mes de pr\u00e9charge des...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38895\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Relais compact 500VDC pour \u00e9lectronique de charge\" \/>\n<meta property=\"og:description\" content=\"Omron Electronic Components Europe vient d&#039;annoncer la sortie d&#039;un relais d&#039;alimentation compact de 500\u00a0Vcc destin\u00e9 aux syst\u00e8mes de pr\u00e9charge des v\u00e9hicules \u00e9lectriques, batteries de secours des panneaux solaires et d&#039;autres applications de courant continu de haute intensit\u00e9. Caract\u00e9ris\u00e9 par sa haute capacit\u00e9 de commutation et sa forte isolation, le nouvel G2RG-X convient parfaitement au contr\u00f4le des courants d&#039;appel, pour prot\u00e9ger, par exemple, les circuits p\u00e9riph\u00e9riques au d\u00e9but du rechargement des batteries, et dans le fonctionnement des syst\u00e8mes de stockage d&#039;\u00e9nergie, des convertisseurs, des servom\u00e9canismes, des blocs d&#039;alimentation et des alimentations ininterrompues.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38895\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-11T00:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8975_omron-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1644\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Relais compact 500VDC pour \u00e9lectronique de charge\",\"datePublished\":\"2020-12-11T00:31:44+00:00\",\"dateModified\":\"2020-12-11T00:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/\"},\"wordCount\":185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/\",\"name\":\"Relais compact 500VDC pour \u00e9lectronique de charge -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-12-11T00:31:44+00:00\",\"dateModified\":\"2020-12-11T00:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Relais compact 500VDC pour \u00e9lectronique de charge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Relais compact 500VDC pour \u00e9lectronique de charge ...","description":"Omron Electronic Components Europe vient d'annoncer la sortie d'un relais d'alimentation compact de 500\u00a0Vcc destin\u00e9 aux syst\u00e8mes de pr\u00e9charge des...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38895\/","og_locale":"fr_FR","og_type":"article","og_title":"Relais compact 500VDC pour \u00e9lectronique de charge","og_description":"Omron Electronic Components Europe vient d'annoncer la sortie d'un relais d'alimentation compact de 500\u00a0Vcc destin\u00e9 aux syst\u00e8mes de pr\u00e9charge des v\u00e9hicules \u00e9lectriques, batteries de secours des panneaux solaires et d'autres applications de courant continu de haute intensit\u00e9. Caract\u00e9ris\u00e9 par sa haute capacit\u00e9 de commutation et sa forte isolation, le nouvel G2RG-X convient parfaitement au contr\u00f4le des courants d'appel, pour prot\u00e9ger, par exemple, les circuits p\u00e9riph\u00e9riques au d\u00e9but du rechargement des batteries, et dans le fonctionnement des syst\u00e8mes de stockage d'\u00e9nergie, des convertisseurs, des servom\u00e9canismes, des blocs d'alimentation et des alimentations ininterrompues.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38895\/","og_site_name":"EENewsEurope","article_published_time":"2020-12-11T00:31:44+00:00","og_image":[{"width":2560,"height":1644,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8975_omron-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Relais compact 500VDC pour \u00e9lectronique de charge","datePublished":"2020-12-11T00:31:44+00:00","dateModified":"2020-12-11T00:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/"},"wordCount":185,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/","url":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/","name":"Relais compact 500VDC pour \u00e9lectronique de charge -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-12-11T00:31:44+00:00","dateModified":"2020-12-11T00:31:44+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/relais-compact-500vdc-pour-electronique-de-charge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Relais compact 500VDC pour \u00e9lectronique de charge"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38895"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=38895"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/164388"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=38895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=38895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=38895"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=38895"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=38895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}