{"id":38885,"date":"2020-12-08T20:31:44","date_gmt":"2020-12-08T20:31:44","guid":{"rendered":"https:\/\/\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/"},"modified":"2020-12-08T20:31:44","modified_gmt":"2020-12-08T20:31:44","slug":"interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/","title":{"rendered":"Interrupteurs pour les applications de capteurs de position et de vitesse"},"content":{"rendered":"<p>Les interrupteurs Reed MITI-7 et MISM-7 conviennent parfaitement aux applications de capteurs de position et de vitesse. Une version \u00e0 montage en surface du MITI-7 baptis\u00e9e MISM-7 est \u00e9galement disponible. Toutes deux se caract\u00e9risent par une capacit\u00e9 de coupure de 170 VCC \u00e0 10 W, une r\u00e9sistance d&rsquo;isolement \u00e9lev\u00e9e (1012 ohms min.), ainsi qu&rsquo;une faible r\u00e9sistance de contact (&lt;150 milliohms).<br \/>\n\u00ab La s\u00e9rie MITI-7 est produite sur un \u00e9quipement enti\u00e8rement automatis\u00e9 dot\u00e9 de commandes de pr\u00e9cision \u00bb, explique Max Shi, Global Product Manager au sein de la division Sensors de Littelfuse. \u00ab La capacit\u00e9 accrue et les normes de qualit\u00e9 sup\u00e9rieure associ\u00e9es \u00e0 cet \u00e9quipement nous aident \u00e0 proposer ces interrupteurs Reed au march\u00e9 mondial \u00e0 des tarifs bien plus comp\u00e9titifs. \u00bb&nbsp;<\/p>\n<p><a href=\"http:\/\/www.littelfuse.com\">www.<\/a><a href=\"http:\/\/littelfuse.com\/\" target=\"_blank\" rel=\"noopener\">littelfuse.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Littelfuse, Inc. annonce le lancement de l&rsquo;interrupteur Reed MITI-7 Ultra-Miniature, un interrupteur de type A (unipolaire, unidirectionnel normalement ouvert ou ferm\u00e9 ou SPST-NO) encapsul\u00e9 dans une ampoule de verre \u00e9tanche de 7 mm de long. La s\u00e9rie MITI-7 propose des options de sensibilit\u00e9 comprises entre 6 AT et 20 AT, une plage bien sup\u00e9rieure \u00e0 celle offerte par les interrupteurs magn\u00e9tiques existants de taille \u00e9quivalente (entre 6 AT et 10 AT). Un nouvel \u00e9quipement d&rsquo;assemblage automatis\u00e9 a permis \u00e0 Littelfuse de doper la capacit\u00e9 de production de ces interrupteurs compacts qui aident les concepteurs de circuits \u00e0 gagner de l&rsquo;espace sur les cartes imprim\u00e9es d\u00e9j\u00e0 bien encombr\u00e9es.<\/p>\n","protected":false},"author":9,"featured_media":164358,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-38885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Interrupteurs pour les applications de capteurs de position et ...<\/title>\n<meta name=\"description\" content=\"Littelfuse, Inc. annonce le lancement de l&#039;interrupteur Reed MITI-7 Ultra-Miniature, un interrupteur de type A (unipolaire, unidirectionnel normalement...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38885\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interrupteurs pour les applications de capteurs de position et de vitesse\" \/>\n<meta property=\"og:description\" content=\"Littelfuse, Inc. annonce le lancement de l&#039;interrupteur Reed MITI-7 Ultra-Miniature, un interrupteur de type A (unipolaire, unidirectionnel normalement ouvert ou ferm\u00e9 ou SPST-NO) encapsul\u00e9 dans une ampoule de verre \u00e9tanche de 7 mm de long. La s\u00e9rie MITI-7 propose des options de sensibilit\u00e9 comprises entre 6 AT et 20 AT, une plage bien sup\u00e9rieure \u00e0 celle offerte par les interrupteurs magn\u00e9tiques existants de taille \u00e9quivalente (entre 6 AT et 10 AT). Un nouvel \u00e9quipement d&#039;assemblage automatis\u00e9 a permis \u00e0 Littelfuse de doper la capacit\u00e9 de production de ces interrupteurs compacts qui aident les concepteurs de circuits \u00e0 gagner de l&#039;espace sur les cartes imprim\u00e9es d\u00e9j\u00e0 bien encombr\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38885\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T20:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8982_littelfuse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1537\" \/>\n\t<meta property=\"og:image:height\" content=\"1257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Interrupteurs pour les applications de capteurs de position et de vitesse\",\"datePublished\":\"2020-12-08T20:31:44+00:00\",\"dateModified\":\"2020-12-08T20:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/\",\"name\":\"Interrupteurs pour les applications de capteurs de position et de vitesse -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-12-08T20:31:44+00:00\",\"dateModified\":\"2020-12-08T20:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interrupteurs pour les applications de capteurs de position et de vitesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Interrupteurs pour les applications de capteurs de position et ...","description":"Littelfuse, Inc. annonce le lancement de l'interrupteur Reed MITI-7 Ultra-Miniature, un interrupteur de type A (unipolaire, unidirectionnel normalement...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38885\/","og_locale":"fr_FR","og_type":"article","og_title":"Interrupteurs pour les applications de capteurs de position et de vitesse","og_description":"Littelfuse, Inc. annonce le lancement de l'interrupteur Reed MITI-7 Ultra-Miniature, un interrupteur de type A (unipolaire, unidirectionnel normalement ouvert ou ferm\u00e9 ou SPST-NO) encapsul\u00e9 dans une ampoule de verre \u00e9tanche de 7 mm de long. La s\u00e9rie MITI-7 propose des options de sensibilit\u00e9 comprises entre 6 AT et 20 AT, une plage bien sup\u00e9rieure \u00e0 celle offerte par les interrupteurs magn\u00e9tiques existants de taille \u00e9quivalente (entre 6 AT et 10 AT). Un nouvel \u00e9quipement d'assemblage automatis\u00e9 a permis \u00e0 Littelfuse de doper la capacit\u00e9 de production de ces interrupteurs compacts qui aident les concepteurs de circuits \u00e0 gagner de l'espace sur les cartes imprim\u00e9es d\u00e9j\u00e0 bien encombr\u00e9es.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38885\/","og_site_name":"EENewsEurope","article_published_time":"2020-12-08T20:31:44+00:00","og_image":[{"width":1537,"height":1257,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8982_littelfuse.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Interrupteurs pour les applications de capteurs de position et de vitesse","datePublished":"2020-12-08T20:31:44+00:00","dateModified":"2020-12-08T20:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/","url":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/","name":"Interrupteurs pour les applications de capteurs de position et de vitesse -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-12-08T20:31:44+00:00","dateModified":"2020-12-08T20:31:44+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/interrupteurs-pour-les-applications-de-capteurs-de-position-et-de-vitesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Interrupteurs pour les applications de capteurs de position et de vitesse"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38885"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=38885"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/164358"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=38885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=38885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=38885"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=38885"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=38885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}