{"id":38729,"date":"2020-12-16T08:31:44","date_gmt":"2020-12-16T08:31:44","guid":{"rendered":"https:\/\/\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/"},"modified":"2020-12-16T08:31:44","modified_gmt":"2020-12-16T08:31:44","slug":"5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/","title":{"rendered":"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande"},"content":{"rendered":"<p>Ce record confirme la possibilit\u00e9 d&rsquo;utiliser le spectre des ondes millim\u00e9triques 5G, non seulement pour le d\u00e9ploiement du r\u00e9seau en milieu urbain (\u00e0 grande vitesse ou \u00e0 haute densit\u00e9), mais aussi pour une couverture FWA 5G plus large. Cette performance s&rsquo;appuie sur celle atteinte en septembre dernier, lorsque la connexion du r\u00e9seau TIM avait d\u00e9pass\u00e9 de mani\u00e8re stable une vitesse de 4 gigabits par seconde en d\u00e9bit descendant sur un r\u00e9seau 5G.<\/p>\n<p>La solution innovante, test\u00e9e sur un r\u00e9seau en direct, a \u00e9t\u00e9 rendue possible gr\u00e2ce \u00e0 la nouvelle radio int\u00e9gr\u00e9e \u00e0 antenne haute puissance Ericsson 5G mmWave AIR 5322, install\u00e9e sur le site mobile de la Via Oriolo Romano \u00e0 Rome. Pour atteindre ce record, un appareil 5G de nouvelle g\u00e9n\u00e9ration d\u00e9j\u00e0 sur le march\u00e9 a \u00e9t\u00e9 utilis\u00e9. Il est compos\u00e9 du nouvel AurusAI de Casa Systems, le premier \u00e9quipement client (CPE) 5G mmWave haute puissance du secteur, et \u00e9quip\u00e9 d&rsquo;un modem Qualcomm Snapdragon X55 5G -Syst\u00e8me RF avec module d&rsquo;antenne mmWave \u00e0 port\u00e9e \u00e9tendue Qualcomm QTM527.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TIM, Ericsson et Qualcomm Technologies ont \u00e0 nouveau battu le record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande gr\u00e2ce \u00e0 la technologie 5G appliqu\u00e9e \u00e0 l&rsquo;acc\u00e8s fixe sans fil (FWA). Une vitesse de 1 Gbps sur les fr\u00e9quences \u00e0 ondes millim\u00e9triques (mmWave) de 26 GHz sur une distance de 6,5 kilom\u00e8tres (1Gbps avec le protocole UDP, 700Mbps Speedtest Ookla TCP) a en effet \u00e9t\u00e9 atteinte sur le r\u00e9seau en direct de TIM.<\/p>\n","protected":false},"author":9,"featured_media":163890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-38729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>5G : un nouveau record mondial de vitesse de d\u00e9bit sur une lon...<\/title>\n<meta name=\"description\" content=\"TIM, Ericsson et Qualcomm Technologies ont \u00e0 nouveau battu le record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande gr\u00e2ce \u00e0...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38729\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande\" \/>\n<meta property=\"og:description\" content=\"TIM, Ericsson et Qualcomm Technologies ont \u00e0 nouveau battu le record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande gr\u00e2ce \u00e0 la technologie 5G appliqu\u00e9e \u00e0 l&#039;acc\u00e8s fixe sans fil (FWA). Une vitesse de 1 Gbps sur les fr\u00e9quences \u00e0 ondes millim\u00e9triques (mmWave) de 26 GHz sur une distance de 6,5 kilom\u00e8tres (1Gbps avec le protocole UDP, 700Mbps Speedtest Ookla TCP) a en effet \u00e9t\u00e9 atteinte sur le r\u00e9seau en direct de TIM.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38729\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-16T08:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8994_tim_ericsson_and_qualcomm_actu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"803\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande\",\"datePublished\":\"2020-12-16T08:31:44+00:00\",\"dateModified\":\"2020-12-16T08:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/\",\"name\":\"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2020-12-16T08:31:44+00:00\",\"dateModified\":\"2020-12-16T08:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une lon...","description":"TIM, Ericsson et Qualcomm Technologies ont \u00e0 nouveau battu le record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande gr\u00e2ce \u00e0...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38729\/","og_locale":"fr_FR","og_type":"article","og_title":"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande","og_description":"TIM, Ericsson et Qualcomm Technologies ont \u00e0 nouveau battu le record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande gr\u00e2ce \u00e0 la technologie 5G appliqu\u00e9e \u00e0 l'acc\u00e8s fixe sans fil (FWA). Une vitesse de 1 Gbps sur les fr\u00e9quences \u00e0 ondes millim\u00e9triques (mmWave) de 26 GHz sur une distance de 6,5 kilom\u00e8tres (1Gbps avec le protocole UDP, 700Mbps Speedtest Ookla TCP) a en effet \u00e9t\u00e9 atteinte sur le r\u00e9seau en direct de TIM.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38729\/","og_site_name":"EENewsEurope","article_published_time":"2020-12-16T08:31:44+00:00","og_image":[{"width":803,"height":602,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci8994_tim_ericsson_and_qualcomm_actu.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande","datePublished":"2020-12-16T08:31:44+00:00","dateModified":"2020-12-16T08:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/","url":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/","name":"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2020-12-16T08:31:44+00:00","dateModified":"2020-12-16T08:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/5g-un-nouveau-record-mondial-de-vitesse-de-debit-sur-une-longue-distance-et-en-ultra-large-bande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"5G : un nouveau record mondial de vitesse de d\u00e9bit sur une longue distance et en ultra-large bande"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38729"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=38729"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/163890"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=38729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=38729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=38729"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=38729"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=38729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}