{"id":386704,"date":"2022-06-14T10:03:40","date_gmt":"2022-06-14T08:03:40","guid":{"rendered":"https:\/\/www.ecinews.fr\/?p=386704"},"modified":"2022-06-14T10:03:40","modified_gmt":"2022-06-14T08:03:40","slug":"module-de-diagnostic-des-bus-can-et-can-fd","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/","title":{"rendered":"Module de diagnostic des bus CAN et CAN FD"},"content":{"rendered":"<p>Le nouveau module compl\u00e9mentaire J1939, disponible s\u00e9par\u00e9ment, permet d&rsquo;\u00e9tendre les fonctions de diagnostic de l&rsquo;appareil portatif avec le protocole de r\u00e9seau SAE J1939. La soci\u00e9t\u00e9 publie \u00e9galement un firmware avec prise en charge J1939 pour les modules E\/S configurables de la famille de produits PCAN-MicroMod FD. Il est gratuit et comprend \u00e9galement l&rsquo;extension J1939 FD.<\/p>\n<p>Le PCAN-MicroMod FD ECU et le PCAN-GPS FD seront aussi pr\u00e9sent\u00e9s pour la premi\u00e8re fois par Peak-System. L&rsquo;unit\u00e9 de contr\u00f4le universelle PCAN-MicroMod FD ECU peut \u00eatre utilis\u00e9e pour des applications automobiles enti\u00e8rement d\u00e9finies par l&rsquo;utilisateur. Pour cela, le traitement des E\/S et la transmission des messages de l&rsquo;appareil sont configur\u00e9s \u00e0 l&rsquo;aide d&rsquo;un programme Windows via le bus CAN. Le PCAN-GPS FD est un module de capteurs programmable pour la g\u00e9olocalisation et l&rsquo;orientation offrant une interface CAN FD.<\/p>\n<p><a href=\"https:\/\/www.peak-system.com\">www.peak-system.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Propos\u00e9 par PEAK-System, fournisseur de mat\u00e9riel et de logiciels dans le domaine de la communication automobile et industrielle, le PCAN-Diag FD permet le diagnostic des bus CAN et CAN FD au niveau physique et au niveau protocolaire.<\/p>\n","protected":false},"author":36,"featured_media":386705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[911],"domains":[47],"ppma_author":[1154],"class_list":["post-386704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","tag-testandmeasurement-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Module de diagnostic des bus CAN et CAN FD ...<\/title>\n<meta name=\"description\" content=\"Propos\u00e9 par PEAK-System, fournisseur de mat\u00e9riel et de logiciels dans le domaine de la communication automobile et industrielle, le PCAN-Diag FD permet le...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/386704\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Module de diagnostic des bus CAN et CAN FD\" \/>\n<meta property=\"og:description\" content=\"Propos\u00e9 par PEAK-System, fournisseur de mat\u00e9riel et de logiciels dans le domaine de la communication automobile et industrielle, le PCAN-Diag FD permet le diagnostic des bus CAN et CAN FD au niveau physique et au niveau protocolaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/386704\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T08:03:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/2022\/06\/ECI1262_PEAK-System-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\"},\"headline\":\"Module de diagnostic des bus CAN et CAN FD\",\"datePublished\":\"2022-06-14T08:03:40+00:00\",\"dateModified\":\"2022-06-14T08:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/\"},\"wordCount\":169,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"TestandMeasurement\"],\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/\",\"url\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/\",\"name\":\"Module de diagnostic des bus CAN et CAN FD -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-06-14T08:03:40+00:00\",\"dateModified\":\"2022-06-14T08:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Module de diagnostic des bus CAN et CAN FD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"},\"sameAs\":[\"http:\/\/ECINews\"]}]}<\/script>","yoast_head_json":{"title":"Module de diagnostic des bus CAN et CAN FD ...","description":"Propos\u00e9 par PEAK-System, fournisseur de mat\u00e9riel et de logiciels dans le domaine de la communication automobile et industrielle, le PCAN-Diag FD permet le...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/386704\/","og_locale":"fr_FR","og_type":"article","og_title":"Module de diagnostic des bus CAN et CAN FD","og_description":"Propos\u00e9 par PEAK-System, fournisseur de mat\u00e9riel et de logiciels dans le domaine de la communication automobile et industrielle, le PCAN-Diag FD permet le diagnostic des bus CAN et CAN FD au niveau physique et au niveau protocolaire.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/386704\/","og_site_name":"EENewsEurope","article_published_time":"2022-06-14T08:03:40+00:00","og_image":[{"width":1080,"height":749,"url":"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/2022\/06\/ECI1262_PEAK-System-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/#article","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762"},"headline":"Module de diagnostic des bus CAN et CAN FD","datePublished":"2022-06-14T08:03:40+00:00","dateModified":"2022-06-14T08:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/"},"wordCount":169,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["TestandMeasurement"],"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/","url":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/","name":"Module de diagnostic des bus CAN et CAN FD -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-06-14T08:03:40+00:00","dateModified":"2022-06-14T08:03:40+00:00","breadcrumb":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdn.eenewseurope.com\/fr\/module-de-diagnostic-des-bus-can-et-can-fd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Module de diagnostic des bus CAN et CAN FD"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/e4387676ad67ce722325c7832f3c3762","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/736120675699dbbf0f0f282b9a9cfb75","url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","caption":"Alain Dieul"},"sameAs":["http:\/\/ECINews"]}]}},"authors":[{"term_id":1154,"user_id":36,"is_guest":0,"slug":"alain-dieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/bc93b056d07515be5b8eecd4acf49c5c?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/386704"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=386704"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/386704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/386705"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=386704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=386704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=386704"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=386704"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=386704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}