{"id":38289,"date":"2021-01-07T20:31:44","date_gmt":"2021-01-07T20:31:44","guid":{"rendered":"https:\/\/\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/"},"modified":"2021-01-07T20:31:44","modified_gmt":"2021-01-07T20:31:44","slug":"chassis-pxi-express-intelligents-pour-une-flexibilite-maximale","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/","title":{"rendered":"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale"},"content":{"rendered":"<p align=\"left\">Le ch\u00e2ssis 18 slots 42-925 offre un slot syst\u00e8me PXIe ainsi qu\u2019un slot PXIe de timing et 16 emplacements Hybrides compatibles pour une polyvalence similaire. N\u2019importe quel module compatible PXI, PXIe ou Compact PCI 3U fonctionnera dans n\u2019importe quel slot. Ces ch\u00e2ssis de 4U de hauteur b\u00e9n\u00e9ficient \u00e9galement d\u2019alimentations syst\u00e8me de grande capacit\u00e9 \u00e9valu\u00e9es \u00e0 400W (8 slots) et 1200W (18 slots). Des ventilateurs efficaces et une conception de convection directe assurent un refroidissement maximal du module PXI, permettant aux ch\u00e2ssis de fonctionner sur une plage de temp\u00e9rature ambiante \u00e9tendue de 0\u00b0C \u00e0 +50\u00b0C.&nbsp; Le refroidissement avant-arri\u00e8re ne n\u00e9cessite pas d\u2019espace entre les instruments mont\u00e9s sur rack, ce qui permet une plus grande densit\u00e9 d\u2019instruments. L\u2019\u00e9tat actuel des ch\u00e2ssis peut \u00eatre surveill\u00e9 \u00e0 distance via un port sur la face arri\u00e8re.<br \/>\n\u00ab&nbsp;Les utilisateurs ont besoin d\u2019une flexibilit\u00e9 maximale pour utiliser les modules PXI et PXIe, et ces ch\u00e2ssis hybrides prennent en charge les modules PXIe de derni\u00e8re g\u00e9n\u00e9ration (Gen 3) de tous les fabricants, ainsi que les produits Pickering. Le prix et la performance sont des consid\u00e9rations cl\u00e9s, et je crois que le nouveau ch\u00e2ssis offre un v\u00e9ritable rapport qualit\u00e9\/prix ainsi qu\u2019une garantie de trois ans, la meilleure du march\u00e9.&nbsp;\u00bb commente Lee Huckle, Chef de Produit. Les nouveaux ch\u00e2ssis de Pickering pr\u00e9sentent \u00e9galement d\u2019autres caract\u00e9ristiques utiles telles que le faible bruit de fonctionnement, la capacit\u00e9 d\u2019horloge externe et les poign\u00e9es de montage en rack en standard.&nbsp;<\/p>\n<p style=\"margin-left: 7.1pt\"><a href=\"http:\/\/www.pickeringtest.com\">www.pickeringtest.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con\u00e7us pour des applications de haute performance pour bancs de test mont\u00e9s en rack, les deux nouveaux ch\u00e2ssis PXIe de 8 et 18 emplacements de Pickering Interfaces disposent d\u2019un syst\u00e8me intelligent de gestion du ch\u00e2ssis qui surveille la tension d\u2019alimentation, la temp\u00e9rature interne et la vitesse du ventilateur de refroidissement. Le ch\u00e2ssis 8 slots 42-924 offre sept emplacements Hybrides compatibles pour une flexibilit\u00e9 dans les applications. <\/p>\n","protected":false},"author":9,"featured_media":162556,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-38289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale ...<\/title>\n<meta name=\"description\" content=\"Con\u00e7us pour des applications de haute performance pour bancs de test mont\u00e9s en rack, les deux nouveaux ch\u00e2ssis PXIe de 8 et 18 emplacements de Pickering...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38289\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale\" \/>\n<meta property=\"og:description\" content=\"Con\u00e7us pour des applications de haute performance pour bancs de test mont\u00e9s en rack, les deux nouveaux ch\u00e2ssis PXIe de 8 et 18 emplacements de Pickering Interfaces disposent d\u2019un syst\u00e8me intelligent de gestion du ch\u00e2ssis qui surveille la tension d\u2019alimentation, la temp\u00e9rature interne et la vitesse du ventilateur de refroidissement. Le ch\u00e2ssis 8 slots 42-924 offre sept emplacements Hybrides compatibles pour une flexibilit\u00e9 dans les applications.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38289\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-07T20:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9034_pickering_interfaces.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1351\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale\",\"datePublished\":\"2021-01-07T20:31:44+00:00\",\"dateModified\":\"2021-01-07T20:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/\",\"name\":\"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-01-07T20:31:44+00:00\",\"dateModified\":\"2021-01-07T20:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale ...","description":"Con\u00e7us pour des applications de haute performance pour bancs de test mont\u00e9s en rack, les deux nouveaux ch\u00e2ssis PXIe de 8 et 18 emplacements de Pickering...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38289\/","og_locale":"fr_FR","og_type":"article","og_title":"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale","og_description":"Con\u00e7us pour des applications de haute performance pour bancs de test mont\u00e9s en rack, les deux nouveaux ch\u00e2ssis PXIe de 8 et 18 emplacements de Pickering Interfaces disposent d\u2019un syst\u00e8me intelligent de gestion du ch\u00e2ssis qui surveille la tension d\u2019alimentation, la temp\u00e9rature interne et la vitesse du ventilateur de refroidissement. Le ch\u00e2ssis 8 slots 42-924 offre sept emplacements Hybrides compatibles pour une flexibilit\u00e9 dans les applications.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38289\/","og_site_name":"EENewsEurope","article_published_time":"2021-01-07T20:31:44+00:00","og_image":[{"width":2400,"height":1351,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9034_pickering_interfaces.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale","datePublished":"2021-01-07T20:31:44+00:00","dateModified":"2021-01-07T20:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/","url":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/","name":"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-01-07T20:31:44+00:00","dateModified":"2021-01-07T20:31:44+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/chassis-pxi-express-intelligents-pour-une-flexibilite-maximale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Ch\u00e2ssis PXI Express intelligents pour une flexibilit\u00e9 maximale"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38289"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=38289"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/162556"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=38289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=38289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=38289"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=38289"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=38289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}