{"id":38134,"date":"2021-01-17T17:40:44","date_gmt":"2021-01-17T17:40:44","guid":{"rendered":"https:\/\/\/le-dr-ahmet-ali-nomme-ieee-fellow\/"},"modified":"2021-01-17T17:40:44","modified_gmt":"2021-01-17T17:40:44","slug":"le-dr-ahmet-ali-nomme-ieee-fellow","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/","title":{"rendered":"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow"},"content":{"rendered":"<p>\u00ab&nbsp;Je suis&nbsp;tr\u00e8s fier de recevoir&nbsp;cette distinction.&nbsp;C&rsquo;est un grand honneur d&rsquo;\u00eatre \u00e9lev\u00e9 au rang de&nbsp;Fellow&nbsp;de l&rsquo;IEEE&nbsp;\u00bb, a d\u00e9clar\u00e9 Ahmet Ali. \u00ab&nbsp;Cette nomination&nbsp;est le reflet&nbsp;de la culture d&rsquo;innovation et du leadership d&rsquo;Analog&nbsp;Devices&nbsp;dans les domaines des convertisseurs de donn\u00e9es \u00e0 haut d\u00e9bit,&nbsp;ainsi que des algorithmes analogiques \u00e0 assistance num\u00e9rique. Cet honneur rejaillit en outre sur les formidables&nbsp;\u00e9quipes d&rsquo;ADI avec lesquelles j&rsquo;ai le privil\u00e8ge de travailler sur diff\u00e9rents produits&nbsp;tr\u00e8s innovateurs&nbsp;et couronn\u00e9s de succ\u00e8s.&nbsp;\u00bb<\/p>\n<p>Ahmet Ali a rejoint ADI en 2002 et \u00e9t\u00e9 nomm\u00e9 ADI&nbsp;Fellow&nbsp;en 2015. Bas\u00e9 \u00e0 Greensboro (Caroline du Nord), il d\u00e9tient plus de 50 brevets et est l&rsquo;auteur du manuel&nbsp;High Speed Data&nbsp;Converters. Il est titulaire d&rsquo;un doctorat en ing\u00e9nierie \u00e9lectrique de l&rsquo;Universit\u00e9 de Pennsylvanie.<\/p>\n<p>L&rsquo;Institute of&nbsp;Electrical&nbsp;and Electronics&nbsp;Engineers&nbsp;(IEEE) est la premi\u00e8re association professionnelle au monde&nbsp;; sa vocation est de contribuer au d\u00e9veloppement de la technologie au profit de l&rsquo;humanit\u00e9. Forte de plus de 400&nbsp;000 membres r\u00e9partis dans 160 pays, l&rsquo;IEEE fait r\u00e9f\u00e9rence dans de nombreux domaines techniques, des syst\u00e8mes a\u00e9ronautiques \u00e0 l&rsquo;informatique et aux t\u00e9l\u00e9communications en passant par l&rsquo;ing\u00e9nierie biom\u00e9dicale, la consommation \u00e9lectrique et l&rsquo;\u00e9lectronique grand public.&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ieee.org\/\">www.ieee.org\/<\/a>&nbsp;&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ieeefrance.org\/\">www.ieeefrance.org\/<\/a><br \/>\n<a href=\"http:\/\/%0bwww.analog.com\">www.analog.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Analog Devices, Inc, annonce la nomination du Dr. Ahmed Ali, Technology Fellow, au rang de Fellow de l&rsquo;IEEE en t\u00e9moignage de son leadership dans la conception et l&rsquo;\u00e9talonnage de convertisseurs analogique-num\u00e9rique \u00e0 haut d\u00e9bit. Ce grade, le plus \u00e9lev\u00e9 d\u00e9cern\u00e9 par l&rsquo;Institute of Electrical and Electronics Engineers (IEEE), est reconnu par les membres de la communaut\u00e9 technique comme un honneur prestigieux et un jalon important dans une carri\u00e8re. Le nombre total de membres choisis au cours d&rsquo;une ann\u00e9e ne peut d\u00e9passer un dixi\u00e8me de 1 % de l&rsquo;ensemble des membres votants.<\/p>\n","protected":false},"author":9,"featured_media":162082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-38134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow ...<\/title>\n<meta name=\"description\" content=\"Analog Devices, Inc, annonce la nomination du Dr. Ahmed Ali, Technology Fellow, au rang de Fellow de l&#039;IEEE en t\u00e9moignage de son leadership dans la...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38134\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow\" \/>\n<meta property=\"og:description\" content=\"Analog Devices, Inc, annonce la nomination du Dr. Ahmed Ali, Technology Fellow, au rang de Fellow de l&#039;IEEE en t\u00e9moignage de son leadership dans la conception et l&#039;\u00e9talonnage de convertisseurs analogique-num\u00e9rique \u00e0 haut d\u00e9bit. Ce grade, le plus \u00e9lev\u00e9 d\u00e9cern\u00e9 par l&#039;Institute of Electrical and Electronics Engineers (IEEE), est reconnu par les membres de la communaut\u00e9 technique comme un honneur prestigieux et un jalon important dans une carri\u00e8re. Le nombre total de membres choisis au cours d&#039;une ann\u00e9e ne peut d\u00e9passer un dixi\u00e8me de 1 % de l&#039;ensemble des membres votants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38134\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-17T17:40:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9049_adi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1906\" \/>\n\t<meta property=\"og:image:height\" content=\"1774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow\",\"datePublished\":\"2021-01-17T17:40:44+00:00\",\"dateModified\":\"2021-01-17T17:40:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/\",\"name\":\"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-01-17T17:40:44+00:00\",\"dateModified\":\"2021-01-17T17:40:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow ...","description":"Analog Devices, Inc, annonce la nomination du Dr. Ahmed Ali, Technology Fellow, au rang de Fellow de l'IEEE en t\u00e9moignage de son leadership dans la...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38134\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow","og_description":"Analog Devices, Inc, annonce la nomination du Dr. Ahmed Ali, Technology Fellow, au rang de Fellow de l'IEEE en t\u00e9moignage de son leadership dans la conception et l'\u00e9talonnage de convertisseurs analogique-num\u00e9rique \u00e0 haut d\u00e9bit. Ce grade, le plus \u00e9lev\u00e9 d\u00e9cern\u00e9 par l'Institute of Electrical and Electronics Engineers (IEEE), est reconnu par les membres de la communaut\u00e9 technique comme un honneur prestigieux et un jalon important dans une carri\u00e8re. Le nombre total de membres choisis au cours d'une ann\u00e9e ne peut d\u00e9passer un dixi\u00e8me de 1 % de l'ensemble des membres votants.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38134\/","og_site_name":"EENewsEurope","article_published_time":"2021-01-17T17:40:44+00:00","og_image":[{"width":1906,"height":1774,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9049_adi.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow","datePublished":"2021-01-17T17:40:44+00:00","dateModified":"2021-01-17T17:40:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/","url":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/","name":"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-01-17T17:40:44+00:00","dateModified":"2021-01-17T17:40:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/le-dr-ahmet-ali-nomme-ieee-fellow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Dr Ahmet Ali nomm\u00e9 IEEE Fellow"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38134"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=38134"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/162082"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=38134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=38134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=38134"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=38134"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=38134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}