{"id":38029,"date":"2021-01-28T17:55:44","date_gmt":"2021-01-28T17:55:44","guid":{"rendered":"https:\/\/\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/"},"modified":"2021-01-28T17:55:44","modified_gmt":"2021-01-28T17:55:44","slug":"des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/","title":{"rendered":"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires"},"content":{"rendered":"<p>Cette technologie ouvre la voie au d\u00e9veloppement de robots mobiles offrant une port\u00e9e et une charge utile accrues. Les drones \u00e0 longue port\u00e9e DMI servent aussi \u00e0 certaines applications commerciales o\u00f9 leur temps de vol plus longs permet par exemple de surveiller de grandes fermes solaires, comme la plus grande centrale solaire de Cor\u00e9e, situ\u00e9e \u00e0 Solasido, dans le district de Haenam. Pour effectuer la m\u00eame mission avec un drone \u00e0 batterie, plus de six changements de batterie \u00e9taient n\u00e9cessaires.<\/p>\n<p><strong><u>Conception \u00e0 haute densit\u00e9 d\u2019\u00e9nergie pour optimiser les performances du bloc d&rsquo;alimentation<\/u><\/strong><\/p>\n<p>Le d\u00e9veloppement d&rsquo;une pile \u00e0 hydrog\u00e8ne pour appareils mobiles n\u00e9cessite un niveau d\u2019innovation technologique global qui va de la science des mat\u00e9riaux \u00e0 l&rsquo;optimisation de la conception au niveau de tout le syst\u00e8me. La cl\u00e9 de la mobilit\u00e9 est la miniaturisation, qui permet d&rsquo;am\u00e9liorer le rendement tout en r\u00e9duisant le poids de l\u2019ensemble. Par ailleurs, un rendement \u00e9nerg\u00e9tique \u00e9lev\u00e9 et une bonne autonomie sont n\u00e9cessaires pour assurer un vol prolong\u00e9 et stable. &nbsp;Il est donc n\u00e9cessaire de r\u00e9duire le poids total, de concevoir un groupe motopropulseur associ\u00e9 \u00e0 une densit\u00e9 d&rsquo;\u00e9nergie \u00e9lev\u00e9e et de simplifier la conception du bloc d&rsquo;alimentation dans son ensemble, notamment de ses composants p\u00e9riph\u00e9riques, de mani\u00e8re \u00e0 optimiser le syst\u00e8me.<\/p>\n<p>Au c\u0153ur des objectifs de conception \u00e0 atteindre se trouvent l&rsquo;architecture et la mise en \u0153uvre du r\u00e9seau de distribution d&rsquo;\u00e9nergie (PDN pour Power Distribution Network) du syst\u00e8me. Le bloc d&rsquo;alimentation DP30 dispose de deux modules de puissance, qui fournissent l&rsquo;\u00e9nergie aux rotors du drone et au contr\u00f4leur des deux empilages de pile \u00e0 combustible. Du fait de la large plage de tension et du caract\u00e8re variable (40&nbsp;V \u00e0 74&nbsp;V) de la tension de sortie du bloc d&rsquo;alimentation DP30, les modules de puissance ont \u00e9t\u00e9 con\u00e7us pour fournir une sortie 48&nbsp;V, 12&nbsp;A strictement r\u00e9gul\u00e9e aux moteurs des rotors du drone, ainsi qu&rsquo;une&nbsp;sortie 12&nbsp;V, 8&nbsp;A pour la carte de contr\u00f4le des empilages et les ventilateurs.<\/p>\n<p>Pour obtenir un rendement et une densit\u00e9 d&rsquo;\u00e9nergie \u00e9lev\u00e9s au niveau du r\u00e9seau de distribution d&rsquo;\u00e9nergie, DMI a opt\u00e9 pour des r\u00e9gulateurs abaisseur-\u00e9l\u00e9vateur \u00abBuck-Boost\u00bb Vicor PRM et un r\u00e9gulateur abaisseur \u00abBuck&nbsp;\u00bb Vicor ZVS (Zero Voltage Switching, ou commutation au z\u00e9ro de tension). Les modules PRM supportent la tension en circuit ouvert, qui peut atteindre 74&nbsp;V, de la pile \u00e0 hydrog\u00e8ne, et assurent une r\u00e9gulation stabilis\u00e9e \u00e0 48&nbsp;V.<\/p>\n<p>Dans le r\u00e9seau de distribution d&rsquo;\u00e9nergie c\u00f4t\u00e9 rotors du drone, deux r\u00e9gulateurs abaisseurs-\u00e9l\u00e9vateurs (Buck-Boost) PRM (PRM48AF480T400A00) sont configur\u00e9s en parall\u00e8le pour fournir les 12&nbsp;A n\u00e9cessaires aux rotors. Le r\u00e9seau de distribution d&rsquo;\u00e9nergie du contr\u00f4leur num\u00e9rique de l&#8217;empilage fait appel \u00e0 un module PRM de faible puissance (PRM48AH480T200A00), suivi d&rsquo;un r\u00e9gulateur ZVS convertissant le 48&nbsp;V en 12&nbsp;V (PI3546-00-LGIZ).<\/p>\n<p><strong><u>Diversification des lignes de produits en fonction de la puissance<\/u><\/strong><\/p>\n<p>Outre le bloc d&rsquo;alimentation DP30 de 2,6&nbsp;kW en cours de production, DMI pr\u00e9voit de diversifier sa gamme de produits en fonction de la puissance. La soci\u00e9t\u00e9 devrait d\u00e9velopper des produits de diff\u00e9rentes capacit\u00e9s, allant du bloc d&rsquo;alimentation \u00e0 pile \u00e0 combustible \u00e0 hydrog\u00e8ne de 1,5&nbsp;kW qui devrait \u00eatre commercialis\u00e9 l&rsquo;ann\u00e9e prochaine, jusqu&rsquo;\u00e0 un bloc de 10&nbsp;kW, et lancer des drones correspondants adapt\u00e9s \u00e0 chaque bloc d&rsquo;alimentation.<\/p>\n<p>L&rsquo;approche modulaire de Vicor en mati\u00e8re d&rsquo;alimentation permet l\u2019\u00e9volutivit\u00e9 n\u00e9cessaire \u00e0 la prise en charge de gammes de produits aussi larges. Cela permet \u00e9galement \u00e0 DMI de se concentrer sur d&rsquo;autres probl\u00e8mes techniques, tels que les modifications de la structure de l&#8217;empilage de la pile, les composants du groupe moteur et les p\u00e9riph\u00e9riques, ou la dissipation thermique, qui d\u00e9coulent tous de l&rsquo;augmentation de puissance. Gr\u00e2ce \u00e0 Vicor, DMI est mieux \u00e0 m\u00eame de poursuivre ses principaux objectifs&nbsp;: renforcer la durabilit\u00e9 et la stabilit\u00e9, tout en poursuivant la miniaturisation et l&rsquo;all\u00e9gement de ses piles \u00e0 combustible \u00e0 haute densit\u00e9 d&rsquo;\u00e9nergie.<\/p>\n<p><a href=\"http:\/\/www.vicorpower.com\">www.vicorpower.com<\/a><\/p>\n<p><strong><u>A propos de Doosan Mobility Innovation<\/u><\/strong><\/p>\n<p>Doosan Mobility Innovation (DMI) est une filiale du groupe Doosan, l&rsquo;un des leaders mondiaux des piles \u00e0 hydrog\u00e8ne. L&rsquo;entreprise a \u00e9t\u00e9 cr\u00e9\u00e9e en 2016 pour d\u00e9velopper des piles \u00e0 hydrog\u00e8ne pour appareils mobiles. Le groupe Doosan a construit tout une organisation pour la conception, l&rsquo;approvisionnement et la production, allant des mat\u00e9riaux aux syst\u00e8mes pour les march\u00e9s des piles \u00e0 combustible \u00e0 l\u2019acide phosphorique (PAFC) depuis une cinquantaine d&rsquo;ann\u00e9es, et aussi des piles \u00e0 combustible \u00e0 membrane \u00e0 \u00e9lectrolyte polym\u00e8re solide (PEMFC) depuis une trentaine d&rsquo;ann\u00e9es, pour fournir des piles \u00e0 combustible destin\u00e9es aux automobiles, aux m\u00e9nages, \u00e0 la production d&rsquo;\u00e9lectricit\u00e9 et aux b\u00e2timents. Dans le m\u00eame temps, DMI s&rsquo;est concentr\u00e9e sur le d\u00e9veloppement de piles \u00e0 hydrog\u00e8ne pour appareils mobiles en s&rsquo;appuyant sur la technologie \u00e9prouv\u00e9e des piles \u00e0 hydrog\u00e8ne Doosan et sur son exp\u00e9rience dans le secteur des applications stationnaires. En outre, l&rsquo;entreprise contribue au d\u00e9veloppement du secteur des a\u00e9ronefs sans pilote (UAV), notamment des drones et des drone-taxis.<\/p>\n<p><a href=\"http:\/\/www.doosanmobility.com\/\">www.doosanmobility.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doosan Mobility Innovation (DMI) fournit une aide humanitaire dans des r\u00e9gions recul\u00e9es, gr\u00e2ce \u00e0 des drones aliment\u00e9s par des piles \u00e0 hydrog\u00e8ne innovantes \u00e0 haute densit\u00e9 \u00e9nerg\u00e9tique. Avec deux heures de vol, les drones ont transport\u00e9 des masques et des fournitures d&rsquo;urgence entre les \u00eeles Vierges am\u00e9ricaines et ont livr\u00e9 des d\u00e9fibrillateurs portables au sommet du mont Hallasan (1947 m), la plus haute montagne de Cor\u00e9e du Sud, situ\u00e9e sur l&rsquo;\u00eele de Jeju.<\/p>\n","protected":false},"author":9,"featured_media":161759,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-38029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires ...<\/title>\n<meta name=\"description\" content=\"Doosan Mobility Innovation (DMI) fournit une aide humanitaire dans des r\u00e9gions recul\u00e9es, gr\u00e2ce \u00e0 des drones aliment\u00e9s par des piles \u00e0 hydrog\u00e8ne...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38029\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires\" \/>\n<meta property=\"og:description\" content=\"Doosan Mobility Innovation (DMI) fournit une aide humanitaire dans des r\u00e9gions recul\u00e9es, gr\u00e2ce \u00e0 des drones aliment\u00e9s par des piles \u00e0 hydrog\u00e8ne innovantes \u00e0 haute densit\u00e9 \u00e9nerg\u00e9tique. Avec deux heures de vol, les drones ont transport\u00e9 des masques et des fournitures d&#039;urgence entre les \u00eeles Vierges am\u00e9ricaines et ont livr\u00e9 des d\u00e9fibrillateurs portables au sommet du mont Hallasan (1947 m), la plus haute montagne de Cor\u00e9e du Sud, situ\u00e9e sur l&#039;\u00eele de Jeju.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38029\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-28T17:55:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9060_vicor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2126\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires\",\"datePublished\":\"2021-01-28T17:55:44+00:00\",\"dateModified\":\"2021-01-28T17:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/\"},\"wordCount\":926,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/\",\"name\":\"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-01-28T17:55:44+00:00\",\"dateModified\":\"2021-01-28T17:55:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires ...","description":"Doosan Mobility Innovation (DMI) fournit une aide humanitaire dans des r\u00e9gions recul\u00e9es, gr\u00e2ce \u00e0 des drones aliment\u00e9s par des piles \u00e0 hydrog\u00e8ne...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38029\/","og_locale":"fr_FR","og_type":"article","og_title":"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires","og_description":"Doosan Mobility Innovation (DMI) fournit une aide humanitaire dans des r\u00e9gions recul\u00e9es, gr\u00e2ce \u00e0 des drones aliment\u00e9s par des piles \u00e0 hydrog\u00e8ne innovantes \u00e0 haute densit\u00e9 \u00e9nerg\u00e9tique. Avec deux heures de vol, les drones ont transport\u00e9 des masques et des fournitures d'urgence entre les \u00eeles Vierges am\u00e9ricaines et ont livr\u00e9 des d\u00e9fibrillateurs portables au sommet du mont Hallasan (1947 m), la plus haute montagne de Cor\u00e9e du Sud, situ\u00e9e sur l'\u00eele de Jeju.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38029\/","og_site_name":"EENewsEurope","article_published_time":"2021-01-28T17:55:44+00:00","og_image":[{"width":2126,"height":1063,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9060_vicor.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires","datePublished":"2021-01-28T17:55:44+00:00","dateModified":"2021-01-28T17:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/"},"wordCount":926,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/","url":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/","name":"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-01-28T17:55:44+00:00","dateModified":"2021-01-28T17:55:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/des-drones-a-pile-a-hydrogene-pour-des-missions-humanitaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Des drones \u00e0 pile \u00e0 hydrog\u00e8ne pour des missions humanitaires"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38029"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=38029"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/38029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/161759"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=38029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=38029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=38029"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=38029"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=38029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}