{"id":379409,"date":"2022-04-05T19:20:22","date_gmt":"2022-04-05T17:20:22","guid":{"rendered":"https:\/\/www.eenewseurope.com\/?p=379409"},"modified":"2022-04-05T19:20:22","modified_gmt":"2022-04-05T17:20:22","slug":"capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/","title":{"rendered":"Capteur d&rsquo;image format optique 1\/2,7 pouce a 3 MP&#8230;qui dit mieux"},"content":{"rendered":"<p><span>\u00a0Omnivision d\u00e9veloppe des solutions de semiconducteurs pour\u00a0 <\/span><span>l&rsquo;imagerie num\u00e9rique avanc\u00e9e<\/span><span>\u00a0, la\u00a0<\/span><span>technologie analogique<\/span><span>\u00a0et\u00a0<\/span><span>tactile et d&rsquo;affichage<\/span><span> , a mis sur le march\u00e9 son nouveau <\/span><span>capteur d&rsquo;image CMOS OS03B10<\/span><span> qui offre des images num\u00e9riques de haute qualit\u00e9 et de la vid\u00e9o d\u00e9finition HD <\/span><span>dans un format optique de 3 m\u00e9gapixels (MP) 1\/2,7 pouces.<\/span><\/p>\n<p><span>Le\u00a0<\/span><span>capteur<\/span><span> est dot\u00e9 d&rsquo;un pixel de 2,5 \u00b5m bas\u00e9 sur la technologie propri\u00e9taire <\/span><span>OmniPixel\u00ae3-HS<\/span><span>. Cette solution haute performance et \u00e9conomique utilise un \u00e9clairage frontal haute sensibilit\u00e9 pour une reproduction fid\u00e8le des couleurs dans des conditions lumineuses et sombres (FSI).<\/span><\/p>\n<p><span>Cheney Zhang. , responsable marketing senior, Omnivision explique :\u00a0\u00bbBeaucoup de nos clients utilisent d\u00e9j\u00e0 notre <\/span><span>OS02G10<\/span><span> , un capteur d&rsquo;image 2MP 1\/2,9 pouces bas\u00e9 sur FSI, pour les applications de s\u00e9curit\u00e9 et vid\u00e9o, telles que les cam\u00e9ras IP, les moniteurs pour b\u00e9b\u00e9, les cam\u00e9ras de sonnette, les t\u00e9l\u00e9viseurs intelligents, les dashcams et plus encore\u00a0\u00bb. L&rsquo;\u00a0<\/span><span>OS03B10<\/span><span>\u00a0est compatible broche \u00e0 broche avec\u00a0<\/span><span>l&rsquo;OS02G10<\/span><span> , ce qui permet au fabricants de mettre \u00e0 niveau de mani\u00e8re transparente leurs produits de s\u00e9curit\u00e9 vers un capteur d&rsquo;image 3MP, am\u00e9liorant consid\u00e9rablement la capture d&rsquo;image et la vid\u00e9o HD sans aucune refonte.\u00a0\u00bb<\/span><\/p>\n<p><span>En tirant parti d&rsquo;une architecture de pixels avanc\u00e9e de 2,5 \u00b5m, l&rsquo;\u00a0<\/span><span>OS03B10<\/span><span> atteint une excellente sensibilit\u00e9 \u00e0 la faible luminosit\u00e9, un rapport signal sur bruit,\u00a0 une efficacit\u00e9 quantique et une faible consommation d&rsquo;\u00e9nergie. Il peut capturer des vid\u00e9os au format 16:9 \u00e0 30 images par seconde.\u00a0Les modes par d\u00e9faut et programmables permettent de contr\u00f4ler plus facilement les param\u00e8tres de taille d&rsquo;image, de temps d&rsquo;exposition, de valeur de gain, etc. Il offre \u00e9galement des fonctions de contr\u00f4le d&rsquo;image telles que miroir et retournement, fen\u00eatrage, \u00e9talonnage automatique du niveau de noir, correction des pixels d\u00e9fectueux, noir, annulation du soleil&#8230; L&rsquo;\u00a0<\/span><span>OS03B10<\/span><span>\u00a0prend en charge les interfaces DVP et MIPI.<\/span><\/p>\n<p><a href=\"https:\/\/www.ovt.com\/products\/os03b10\/\" target=\"_blank\" rel=\"noopener\">capteur d&rsquo;image OS03B10\u00a0\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/www.ovt.com\/technologies\/omnipixel-3-hs\/\" target=\"_blank\" rel=\"noopener\">OmniPixel\u00ae3-HS<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Le nouveau capteur d&rsquo;image 3 m\u00e9gapixels OmniPixel\u00ae3-HS de la soci\u00e9t\u00e9 Californienne Omnivisuion, au format optique 1\/2,7 pouces permet aux OEM de passer de 2MP \u00e0 3MP en toute transparence pour des images plus vives et des vid\u00e9os HD de meilleure qualit\u00e9 dans les cam\u00e9ras de surveillance de s\u00e9curit\u00e9, IP et analogiques HD. <\/p>\n","protected":false},"author":11,"featured_media":379414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1143],"class_list":["post-379409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Capteur d&#039;image format optique 1\/2,7 pouce a 3 MP...qui dit mieux ...<\/title>\n<meta name=\"description\" content=\"Le nouveau capteur d&#039;image 3 m\u00e9gapixels OmniPixel\u00ae3-HS de la soci\u00e9t\u00e9 Californienne Omnivisuion, au format optique 1\/2,7 pouces permet aux OEM de passer...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/379409\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capteur d&#039;image format optique 1\/2,7 pouce a 3 MP...qui dit mieux\" \/>\n<meta property=\"og:description\" content=\"Le nouveau capteur d&#039;image 3 m\u00e9gapixels OmniPixel\u00ae3-HS de la soci\u00e9t\u00e9 Californienne Omnivisuion, au format optique 1\/2,7 pouces permet aux OEM de passer de 2MP \u00e0 3MP en toute transparence pour des images plus vives et des vid\u00e9os HD de meilleure qualit\u00e9 dans les cam\u00e9ras de surveillance de s\u00e9curit\u00e9, IP et analogiques HD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/379409\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-05T17:20:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/2022\/04\/Omnipixel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Cardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Capteur d&rsquo;image format optique 1\/2,7 pouce a 3 MP&#8230;qui dit mieux\",\"datePublished\":\"2022-04-05T17:20:22+00:00\",\"dateModified\":\"2022-04-05T17:20:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/\",\"name\":\"Capteur d'image format optique 1\/2,7 pouce a 3 MP...qui dit mieux -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-04-05T17:20:22+00:00\",\"dateModified\":\"2022-04-05T17:20:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capteur d&rsquo;image format optique 1\/2,7 pouce a 3 MP&#8230;qui dit mieux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Capteur d'image format optique 1\/2,7 pouce a 3 MP...qui dit mieux ...","description":"Le nouveau capteur d'image 3 m\u00e9gapixels OmniPixel\u00ae3-HS de la soci\u00e9t\u00e9 Californienne Omnivisuion, au format optique 1\/2,7 pouces permet aux OEM de passer...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/379409\/","og_locale":"fr_FR","og_type":"article","og_title":"Capteur d'image format optique 1\/2,7 pouce a 3 MP...qui dit mieux","og_description":"Le nouveau capteur d'image 3 m\u00e9gapixels OmniPixel\u00ae3-HS de la soci\u00e9t\u00e9 Californienne Omnivisuion, au format optique 1\/2,7 pouces permet aux OEM de passer de 2MP \u00e0 3MP en toute transparence pour des images plus vives et des vid\u00e9os HD de meilleure qualit\u00e9 dans les cam\u00e9ras de surveillance de s\u00e9curit\u00e9, IP et analogiques HD.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/379409\/","og_site_name":"EENewsEurope","article_published_time":"2022-04-05T17:20:22+00:00","og_image":[{"width":500,"height":431,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/2022\/04\/Omnipixel.jpg","type":"image\/jpeg"}],"author":"Daniel Cardon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Capteur d&rsquo;image format optique 1\/2,7 pouce a 3 MP&#8230;qui dit mieux","datePublished":"2022-04-05T17:20:22+00:00","dateModified":"2022-04-05T17:20:22+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/"},"wordCount":353,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/","url":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/","name":"Capteur d'image format optique 1\/2,7 pouce a 3 MP...qui dit mieux -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-04-05T17:20:22+00:00","dateModified":"2022-04-05T17:20:22+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/capteur-dimage-format-optique-1-27-pouce-a-3-mp-qui-dit-mieux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Capteur d&rsquo;image format optique 1\/2,7 pouce a 3 MP&#8230;qui dit mieux"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/379409"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=379409"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/379409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/379414"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=379409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=379409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=379409"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=379409"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=379409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}