{"id":37881,"date":"2021-02-04T07:31:44","date_gmt":"2021-02-04T07:31:44","guid":{"rendered":"https:\/\/\/jeu-de-puces-lora-core\/"},"modified":"2021-02-04T07:31:44","modified_gmt":"2021-02-04T07:31:44","slug":"jeu-de-puces-lora-core","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/jeu-de-puces-lora-core\/","title":{"rendered":"Jeu de puces LoRa Core"},"content":{"rendered":"<p>Le catalogue produits LoRa Core comprend des puces \u00e9metteurs-r\u00e9cepteurs fonctionnant sous le GHz, des puces passerelle et des impl\u00e9mentations de r\u00e9f\u00e9rence, notamment les \u00e9metteurs-r\u00e9cepteurs des s\u00e9ries SX126x, SX127x et LLCC68, ainsi que les puces passerelle s\u00e9rie SX130x, des impl\u00e9mentations de r\u00e9f\u00e9rence de passerelles existantes, et des mod\u00e8les de r\u00e9f\u00e9rence de passerelle LoRa Corecell. Ensemble, ils repr\u00e9sentent les capacit\u00e9s essentielles des dispositifs LoRa de Semtech, notamment la longue port\u00e9e, la faible consommation et une communication d&rsquo;un bout \u00e0 l&rsquo;autre \u00e0 faible co\u00fbt.<\/p>\n<p>Les nouveaux ajouts \u00e0 l&rsquo;offre produits LoRa Core sont un processeur bande de base LoRa (<a href=\"https:\/\/www.semtech.com\/products\/wireless-rf\/lora-gateways\/sx1303\">SX1303<\/a>) et une impl\u00e9mentation de r\u00e9f\u00e9rence de passerelle LoRa Corecell utilisant ce processeur, et dot\u00e9e d&rsquo;une fonction d&rsquo;horodatage fin.<\/p>\n<p>\u00ab&nbsp;Ce nouveau composant passerelle LoRa Core permet la g\u00e9olocalisation par le r\u00e9seau des dispositifs LoRa, sans n\u00e9cessiter de mat\u00e9riel GPS dans chaque n\u0153ud terminal individuel. Gr\u00e2ce \u00e0 sa fonction d&rsquo;horodatage fin qui fournit des informations pr\u00e9cises sur l&rsquo;heure d&rsquo;arriv\u00e9e de chaque message d\u00e9modul\u00e9, ce nouveau jeu de puces permet aux passerelles de fournir une g\u00e9olocalisation gr\u00e2ce au seul r\u00e9seau, bas\u00e9e sur les diff\u00e9rences de temps d&rsquo;arriv\u00e9e (TDOA).<\/p>\n<p>C&rsquo;est id\u00e9al pour de nombreuses applications de tra\u00e7age d&rsquo;actifs \u00e0 co\u00fbt sensible,&nbsp;\u00bb d\u00e9clare Pedro Pachuca, Directeur du groupe Produits sans fil et D\u00e9tection de Semtech.<\/p>\n<p>\u00ab&nbsp;Le nouveau composant LoRa Core va permettre \u00e0 nos clients d&rsquo;acc\u00e9l\u00e9rer le d\u00e9veloppement de leurs applications utilisant le protocole LoRaWAN. Semtech s&rsquo;engage \u00e0 fournir \u00e0 ses clients des solutions pour simplifier leur cycle de d\u00e9veloppement d&rsquo;applications utilisant des dispositifs LoRa.&nbsp;\u00bb<\/p>\n<p>La nouvelle impl\u00e9mentation de r\u00e9f\u00e9rence de la passerelle LoRa Corecell, dot\u00e9e d&rsquo;un horodatage pr\u00e9cis, est disponible pour les r\u00e9gions \u00c9tats-Unis, Europe et Chine. Il permettra aux d\u00e9veloppeurs de produire des passerelles int\u00e9grant LoRa avec une nomenclature optimale et le profil de consommation le plus bas, tout en offrant les meilleures performances en mati\u00e8re de g\u00e9olocalisation bas\u00e9e sur le r\u00e9seau.<\/p>\n<p><a href=\"http:\/\/www.semtech.com\/\" target=\"_blank\" rel=\"noopener\">www.semtech.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Semtech Corporation \u00e9tend sa gamme de produits LoRa Core avec un nouveau jeu de puces. Son catalogue produits LoRa Core fournit une couverture mondiale au r\u00e9seau LoRaWAN et s&rsquo;adresse \u00e0 plusieurs secteurs, notamment le tra\u00e7age d&rsquo;actifs, le b\u00e2timent, la maison, l&rsquo;agriculture, le comptage et l&rsquo;automatisation industrielle. <\/p>\n","protected":false},"author":9,"featured_media":161315,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-37881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Jeu de puces LoRa Core ...<\/title>\n<meta name=\"description\" content=\"Semtech Corporation \u00e9tend sa gamme de produits LoRa Core avec un nouveau jeu de puces. Son catalogue produits LoRa Core fournit une couverture mondiale au...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/37881\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeu de puces LoRa Core\" \/>\n<meta property=\"og:description\" content=\"Semtech Corporation \u00e9tend sa gamme de produits LoRa Core avec un nouveau jeu de puces. Son catalogue produits LoRa Core fournit une couverture mondiale au r\u00e9seau LoRaWAN et s&#039;adresse \u00e0 plusieurs secteurs, notamment le tra\u00e7age d&#039;actifs, le b\u00e2timent, la maison, l&#039;agriculture, le comptage et l&#039;automatisation industrielle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/37881\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T07:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9083_semtech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Jeu de puces LoRa Core\",\"datePublished\":\"2021-02-04T07:31:44+00:00\",\"dateModified\":\"2021-02-04T07:31:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/\"},\"wordCount\":385,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/\",\"name\":\"Jeu de puces LoRa Core -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-02-04T07:31:44+00:00\",\"dateModified\":\"2021-02-04T07:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeu de puces LoRa Core\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Jeu de puces LoRa Core ...","description":"Semtech Corporation \u00e9tend sa gamme de produits LoRa Core avec un nouveau jeu de puces. Son catalogue produits LoRa Core fournit une couverture mondiale au...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/37881\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeu de puces LoRa Core","og_description":"Semtech Corporation \u00e9tend sa gamme de produits LoRa Core avec un nouveau jeu de puces. Son catalogue produits LoRa Core fournit une couverture mondiale au r\u00e9seau LoRaWAN et s'adresse \u00e0 plusieurs secteurs, notamment le tra\u00e7age d'actifs, le b\u00e2timent, la maison, l'agriculture, le comptage et l'automatisation industrielle.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/37881\/","og_site_name":"EENewsEurope","article_published_time":"2021-02-04T07:31:44+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9083_semtech.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Jeu de puces LoRa Core","datePublished":"2021-02-04T07:31:44+00:00","dateModified":"2021-02-04T07:31:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/"},"wordCount":385,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/","url":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/","name":"Jeu de puces LoRa Core -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-02-04T07:31:44+00:00","dateModified":"2021-02-04T07:31:44+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/jeu-de-puces-lora-core\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Jeu de puces LoRa Core"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/37881"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=37881"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/37881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/161315"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=37881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=37881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=37881"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=37881"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=37881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}