{"id":3587,"date":"2021-09-20T06:56:21","date_gmt":"2021-09-20T06:56:21","guid":{"rendered":"https:\/\/\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/"},"modified":"2021-09-20T06:56:21","modified_gmt":"2021-09-20T06:56:21","slug":"egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/","title":{"rendered":"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne"},"content":{"rendered":"<p>Pour compl\u00e9ter cette installation, de nouveaux \u00e9quipements de traitement des eaux us\u00e9es, des \u00e9quipements d\u2019analyse en laboratoire et des \u00e9purateurs de fum\u00e9es respectueux de l&rsquo;environnement ont \u00e9t\u00e9 install\u00e9s.<\/p>\n<p>Quatre lignes ultra sp\u00e9cialis\u00e9es pour r\u00e9pondre \u00e0 tous les besoins<\/p>\n<p>L&rsquo;atelier de galvanoplastie est r\u00e9parti en quatre lignes distinctes.<\/p>\n<p>&#8211; La premi\u00e8re ligne permet de nettoyer divers composants m\u00e9talliques tels que l\u2019acier lamin\u00e9 \u00e0 froid, ASTM F-15, l\u2019acier inox et autres alliages de cuivre. Ce nettoyage est effectu\u00e9 \u00e0 l&rsquo;aide de divers produits chimiques alcalins et acides.<\/p>\n<p>&#8211; La deuxi\u00e8me ligne, la plus importante, assure les traitements de surface suivants : galvanisation au nickel \u00e9lectrolytique, nickel chimique, or \u00e9lectrolytique et galvanisation \u00e9lectrolytique s\u00e9lective d\u2019or.<\/p>\n<p>&#8211; La troisi\u00e8me ligne assure le traitement au cuivre et \u00e0 l&rsquo;\u00e9tain. Le traitement de surface \u00e0 l&rsquo;\u00e9tain est une finition mate pure, qui peut \u00eatre polie par brillantage au moyen d\u2019un proc\u00e9d\u00e9 exclusif d\u2019Egide.<\/p>\n<p>&#8211; La derni\u00e8re ligne permet le traitement de surface par nickel boron et d\u2019or chimique. Cette technologie sp\u00e9cialis\u00e9e de galvanisation est appliqu\u00e9e \u00e0 notre c\u00e9ramique cofritt\u00e9e cuite \u00e0 haute temp\u00e9rature.<\/p>\n<p><a href=\"http:\/\/www.egide-group.com\" target=\"notSet\" rel=\"noopener\">www.egide-group.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Groupe Egide vient d&rsquo;annoncer que les travaux de r\u00e9habilitation de sa ligne de galvanoplastie sont termin\u00e9s sur son site de Cambridge, Maryland, USA. Cette installation ultramoderne est capable de fournir des services de d\u00e9p\u00f4ts \u00e9lectrolytiques d\u2019or, d\u2019\u00e9tain et de cuivre ainsi que de d\u00e9p\u00f4ts d\u2019or et nickel chimique. <\/p>\n","protected":false},"author":9,"featured_media":3588,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-3587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne ...<\/title>\n<meta name=\"description\" content=\"Le Groupe Egide vient d&#039;annoncer que les travaux de r\u00e9habilitation de sa ligne de galvanoplastie sont termin\u00e9s sur son site de Cambridge, Maryland, USA....\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3587\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne\" \/>\n<meta property=\"og:description\" content=\"Le Groupe Egide vient d&#039;annoncer que les travaux de r\u00e9habilitation de sa ligne de galvanoplastie sont termin\u00e9s sur son site de Cambridge, Maryland, USA. Cette installation ultramoderne est capable de fournir des services de d\u00e9p\u00f4ts \u00e9lectrolytiques d\u2019or, d\u2019\u00e9tain et de cuivre ainsi que de d\u00e9p\u00f4ts d\u2019or et nickel chimique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3587\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-20T06:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9754_egide_actu-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne\",\"datePublished\":\"2021-09-20T06:56:21+00:00\",\"dateModified\":\"2021-09-20T06:56:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/\",\"name\":\"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-09-20T06:56:21+00:00\",\"dateModified\":\"2021-09-20T06:56:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne ...","description":"Le Groupe Egide vient d'annoncer que les travaux de r\u00e9habilitation de sa ligne de galvanoplastie sont termin\u00e9s sur son site de Cambridge, Maryland, USA....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3587\/","og_locale":"fr_FR","og_type":"article","og_title":"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne","og_description":"Le Groupe Egide vient d'annoncer que les travaux de r\u00e9habilitation de sa ligne de galvanoplastie sont termin\u00e9s sur son site de Cambridge, Maryland, USA. Cette installation ultramoderne est capable de fournir des services de d\u00e9p\u00f4ts \u00e9lectrolytiques d\u2019or, d\u2019\u00e9tain et de cuivre ainsi que de d\u00e9p\u00f4ts d\u2019or et nickel chimique.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3587\/","og_site_name":"EENewsEurope","article_published_time":"2021-09-20T06:56:21+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9754_egide_actu-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne","datePublished":"2021-09-20T06:56:21+00:00","dateModified":"2021-09-20T06:56:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/","url":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/","name":"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-09-20T06:56:21+00:00","dateModified":"2021-09-20T06:56:21+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/egide-usa-une-nouvelle-ligne-de-galvanoplastie-ultra-moderne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Egide USA : une nouvelle ligne de galvanoplastie ultra-moderne"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3587"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=3587"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/3588"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=3587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=3587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=3587"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=3587"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=3587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}