{"id":3543,"date":"2021-09-24T06:13:21","date_gmt":"2021-09-24T06:13:21","guid":{"rendered":"https:\/\/\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/"},"modified":"2021-09-24T06:13:21","modified_gmt":"2021-09-24T06:13:21","slug":"digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/","title":{"rendered":"Digi-Key Electronics va distribuer les produits d&rsquo;automatisation et de contr\u00f4le Siemens"},"content":{"rendered":"<p>Les puissantes technologies d&rsquo;automatisation, le mat\u00e9riel et les logiciels tourn\u00e9s vers l&rsquo;avenir de Siemens, soutenus par des services de support et de vente internationaux, couvrent l&rsquo;ensemble du processus de production et offrent une interop\u00e9rabilit\u00e9 maximale entre tous les composants d&rsquo;automatisation et de contr\u00f4le.<br \/>\n\u00ab&nbsp;Nous sommes fiers de nous associer \u00e0 Siemens, le leader mondial en mati\u00e8re d&rsquo;automatisation, pour renforcer notre engagement \u00e0 maintenir la plus vaste s\u00e9lection de produits d&rsquo;automatisation au monde&nbsp;\u00bb, a d\u00e9clar\u00e9 Eric&nbsp;Wendt, directeur du d\u00e9veloppement des programmes strat\u00e9giques chez Digi-Key. \u00ab&nbsp;La vaste offre de technologies et de produits de pointe de Siemens, combin\u00e9e \u00e0 notre port\u00e9e et \u00e0 notre stock \u00e9tendus, offre une combinaison puissante.&nbsp;\u00bb<br \/>\n\u00ab&nbsp;Le commerce \u00e9lectronique est l&rsquo;un de nos canaux de distribution d&rsquo;automatisation industrielle qui conna\u00eet la plus forte croissance aux \u00c9tats-Unis, et nous sommes fiers de lancer ce nouveau partenariat avec Digi-Key&nbsp;\u00bb, a d\u00e9clar\u00e9 Marla&nbsp;Davids, vice-pr\u00e9sidente des ventes industrielles num\u00e9riques chez Siemens. \u00ab&nbsp;Nos clients attendent plus que jamais une flexibilit\u00e9 et une simplicit\u00e9 accrues, et Digi-Key propose la s\u00e9lection de produits en ligne et les outils de conception technique uniques qui sont importants pour leur r\u00e9ussite. Nous nous r\u00e9jouissons de poursuivre notre croissance, gr\u00e2ce \u00e0 l&rsquo;accent particulier mis par Digi-Key sur le lancement de nouveaux produits.&nbsp;\u00bb<\/p>\n<p><a href=\"http:\/\/www.digikey.fr\" target=\"notSet\" rel=\"noopener\">www.<\/a><a href=\"https:\/\/www.digikey.fr\/\" target=\"blank\" rel=\"noopener\">digikey.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Digi-Key Electronics annonce avoir conclu un partenariat de distribution avec Siemens, afin de proposer leur vaste gamme de produits d&rsquo;automatisation et de contr\u00f4le. Ce partenariat permet aux clients de Digi-Key du monde entier de b\u00e9n\u00e9ficier des produits fiables, durables et faciles \u00e0 utiliser de Siemens, tels que les alimentations, la technologie d&rsquo;interface homme-machine (IHM), les contr\u00f4leurs logiques programmables (PLC) et les interrupteurs \u00e0 usage intensif.<\/p>\n","protected":false},"author":9,"featured_media":3544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-3543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Digi-Key Electronics va distribuer les produits d&#039;automatisatio...<\/title>\n<meta name=\"description\" content=\"Digi-Key Electronics annonce avoir conclu un partenariat de distribution avec Siemens, afin de proposer leur vaste gamme de produits d&#039;automatisation et de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3543\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digi-Key Electronics va distribuer les produits d&#039;automatisation et de contr\u00f4le Siemens\" \/>\n<meta property=\"og:description\" content=\"Digi-Key Electronics annonce avoir conclu un partenariat de distribution avec Siemens, afin de proposer leur vaste gamme de produits d&#039;automatisation et de contr\u00f4le. Ce partenariat permet aux clients de Digi-Key du monde entier de b\u00e9n\u00e9ficier des produits fiables, durables et faciles \u00e0 utiliser de Siemens, tels que les alimentations, la technologie d&#039;interface homme-machine (IHM), les contr\u00f4leurs logiques programmables (PLC) et les interrupteurs \u00e0 usage intensif.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3543\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-24T06:13:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9760_dk_actu_siemens.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Digi-Key Electronics va distribuer les produits d&rsquo;automatisation et de contr\u00f4le Siemens\",\"datePublished\":\"2021-09-24T06:13:21+00:00\",\"dateModified\":\"2021-09-24T06:13:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/\",\"name\":\"Digi-Key Electronics va distribuer les produits d'automatisation et de contr\u00f4le Siemens -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-09-24T06:13:21+00:00\",\"dateModified\":\"2021-09-24T06:13:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digi-Key Electronics va distribuer les produits d&rsquo;automatisation et de contr\u00f4le Siemens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Digi-Key Electronics va distribuer les produits d'automatisatio...","description":"Digi-Key Electronics annonce avoir conclu un partenariat de distribution avec Siemens, afin de proposer leur vaste gamme de produits d'automatisation et de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3543\/","og_locale":"fr_FR","og_type":"article","og_title":"Digi-Key Electronics va distribuer les produits d'automatisation et de contr\u00f4le Siemens","og_description":"Digi-Key Electronics annonce avoir conclu un partenariat de distribution avec Siemens, afin de proposer leur vaste gamme de produits d'automatisation et de contr\u00f4le. Ce partenariat permet aux clients de Digi-Key du monde entier de b\u00e9n\u00e9ficier des produits fiables, durables et faciles \u00e0 utiliser de Siemens, tels que les alimentations, la technologie d'interface homme-machine (IHM), les contr\u00f4leurs logiques programmables (PLC) et les interrupteurs \u00e0 usage intensif.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3543\/","og_site_name":"EENewsEurope","article_published_time":"2021-09-24T06:13:21+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9760_dk_actu_siemens.jpeg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Digi-Key Electronics va distribuer les produits d&rsquo;automatisation et de contr\u00f4le Siemens","datePublished":"2021-09-24T06:13:21+00:00","dateModified":"2021-09-24T06:13:21+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/","url":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/","name":"Digi-Key Electronics va distribuer les produits d'automatisation et de contr\u00f4le Siemens -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-09-24T06:13:21+00:00","dateModified":"2021-09-24T06:13:21+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/digi-key-electronics-va-distribuer-les-produits-dautomatisation-et-de-controle-siemens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Digi-Key Electronics va distribuer les produits d&rsquo;automatisation et de contr\u00f4le Siemens"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3543"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=3543"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/3543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/3544"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=3543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=3543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=3543"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=3543"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=3543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}