{"id":2411,"date":"2021-10-04T16:50:38","date_gmt":"2021-10-04T16:50:38","guid":{"rendered":"https:\/\/\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/"},"modified":"2021-10-04T16:50:38","modified_gmt":"2021-10-04T16:50:38","slug":"solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/","title":{"rendered":"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles"},"content":{"rendered":"<p>La famille de produits RAA2S425x se caract\u00e9rise par une int\u00e9gration \u00e9lev\u00e9e et des fonctionnalit\u00e9s num\u00e9riques et analogiques avanc\u00e9es qui facilitent consid\u00e9rablement le cycle de conception et r\u00e9duisent la nomenclature et les co\u00fbts de production des syst\u00e8mes des clients.<\/p>\n<p>Les circuits int\u00e9gr\u00e9s RAA2S425x prennent en charge l\u2019ensemble des principales technologies de d\u00e9tection de pression et comportent un \u00e9tage d\u2019entr\u00e9e analogique (AFE) haute performance pour un conditionnement am\u00e9lior\u00e9 des signaux. Les nouveaux dispositifs offrent une compensation \u00e9tendue du d\u00e9calage du capteur analogique (XSOC), ajustable \u00e0 presque tous les ponts r\u00e9sistifs. Ils fournissent des mesures de pression et de temp\u00e9rature avec une grande pr\u00e9cision (0,35 % &#8211; 1,0 %) sur une large plage de temp\u00e9rature (-40 \u00b0C \u00e0 150 \u00b0C).<\/p>\n<p>Les circuits int\u00e9gr\u00e9s RAA2S425x int\u00e8grent un microcontr\u00f4leur embarqu\u00e9 RISC 16 bits qui assure la compensation num\u00e9rique du d\u00e9calage, de la sensibilit\u00e9, de la d\u00e9rive en temp\u00e9rature et de la non-lin\u00e9arit\u00e9. Il dispose d&rsquo;une m\u00e9moire non-volatile (NVM) tr\u00e8s fiable pour stocker les coefficients d&rsquo;\u00e9talonnage et les donn\u00e9es de configuration dans les environnements automobiles difficiles. Le RAA2S425x communique num\u00e9riquement avec l&rsquo;\u00e9quipement d&rsquo;\u00e9talonnage, ce qui r\u00e9duit la sensibilit\u00e9 au bruit. L&rsquo;\u00e9talonnage num\u00e9rique permet aux clients de maintenir des co\u00fbts d&rsquo;assemblage faibles, car il ne n\u00e9cessite pas d&rsquo;ajuster l&rsquo;\u00e9l\u00e9ment de d\u00e9tection. Le RAA2S425x est une solution optimale pour la s\u00e9curit\u00e9 et les applications automobiles difficiles gr\u00e2ce \u00e0 de nombreux avantages dont l&rsquo;int\u00e9gration de circuits de protection contre les surtensions et l&rsquo;inversion de polarit\u00e9, la conformit\u00e9 ASIL-B selon la norme ISO26262, une excellente compatibilit\u00e9 \u00e9lectromagn\u00e9tique et de multiples fonctions de diagnostic sup\u00e9rieures.<\/p>\n<p>\u00ab&nbsp;La famille de produits RAA2S425x illustre les capacit\u00e9s uniques que Renesas apporte aux clients du secteur automobile gr\u00e2ce \u00e0 son solide portefeuille de technologies analogiques et num\u00e9riques \u00bb,&nbsp;a d\u00e9clar\u00e9 Christian Wolf, vice-pr\u00e9sident de la division Automotive Analog Sensor Business chez Renesas.&nbsp;\u00ab&nbsp;La nouvelle solution de d\u00e9tection de pression permet \u00e0 nos clients de r\u00e9duire le temps de conception avec des syst\u00e8mes tr\u00e8s pr\u00e9cis et fiables r\u00e9pondant aux exigences strictes de s\u00e9curit\u00e9 automobile. \u00bb<\/p>\n<p><a href=\"http:\/\/www.renesas.com\" target=\"notSet\" rel=\"noopener\">www.renesas.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renesas Electronics Corporation pr\u00e9sente la famille de circuits int\u00e9gr\u00e9s RAA2S425x pour les syst\u00e8mes de d\u00e9tection de pression automobile. Ces nouveaux dispositifs fournissent une amplification tr\u00e8s pr\u00e9cise et une correction sp\u00e9cifique des signaux de pression issues des syst\u00e8mes de freinage, de transmission et de climatisation des v\u00e9hicules xEV\/EV\/FCEV.<\/p>\n","protected":false},"author":9,"featured_media":2412,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-2411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les appl...<\/title>\n<meta name=\"description\" content=\"Renesas Electronics Corporation pr\u00e9sente la famille de circuits int\u00e9gr\u00e9s RAA2S425x pour les syst\u00e8mes de d\u00e9tection de pression automobile. Ces nouveaux...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/2411\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles\" \/>\n<meta property=\"og:description\" content=\"Renesas Electronics Corporation pr\u00e9sente la famille de circuits int\u00e9gr\u00e9s RAA2S425x pour les syst\u00e8mes de d\u00e9tection de pression automobile. Ces nouveaux dispositifs fournissent une amplification tr\u00e8s pr\u00e9cise et une correction sp\u00e9cifique des signaux de pression issues des syst\u00e8mes de freinage, de transmission et de climatisation des v\u00e9hicules xEV\/EV\/FCEV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/2411\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-04T16:50:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9789_renesas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles\",\"datePublished\":\"2021-10-04T16:50:38+00:00\",\"dateModified\":\"2021-10-04T16:50:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/\"},\"wordCount\":417,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/\",\"name\":\"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-10-04T16:50:38+00:00\",\"dateModified\":\"2021-10-04T16:50:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les appl...","description":"Renesas Electronics Corporation pr\u00e9sente la famille de circuits int\u00e9gr\u00e9s RAA2S425x pour les syst\u00e8mes de d\u00e9tection de pression automobile. Ces nouveaux...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/2411\/","og_locale":"fr_FR","og_type":"article","og_title":"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles","og_description":"Renesas Electronics Corporation pr\u00e9sente la famille de circuits int\u00e9gr\u00e9s RAA2S425x pour les syst\u00e8mes de d\u00e9tection de pression automobile. Ces nouveaux dispositifs fournissent une amplification tr\u00e8s pr\u00e9cise et une correction sp\u00e9cifique des signaux de pression issues des syst\u00e8mes de freinage, de transmission et de climatisation des v\u00e9hicules xEV\/EV\/FCEV.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/2411\/","og_site_name":"EENewsEurope","article_published_time":"2021-10-04T16:50:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9789_renesas.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles","datePublished":"2021-10-04T16:50:38+00:00","dateModified":"2021-10-04T16:50:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/"},"wordCount":417,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/","url":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/","name":"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-10-04T16:50:38+00:00","dateModified":"2021-10-04T16:50:38+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/solution-de-detection-de-pression-tres-precise-pour-les-applications-automobiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Solution de d\u00e9tection de pression tr\u00e8s pr\u00e9cise pour les applications automobiles"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/2411"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=2411"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/2411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/2412"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=2411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=2411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=2411"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=2411"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=2411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}