{"id":232144,"date":"2015-02-03T23:00:00","date_gmt":"2015-02-03T23:00:00","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/"},"modified":"2015-02-03T23:00:00","modified_gmt":"2015-02-03T23:00:00","slug":"stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/","title":{"rendered":"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement"},"content":{"rendered":"<p>Afin de r&eacute;pondre aux conditions et besoins sp&eacute;cifiques de l&rsquo;automobile, ces cartes Flash de ScanDisk d&rsquo;une capacit&eacute; de stockage allant jusqu&rsquo;&agrave; 64 GB sont con&ccedil;ues pour fonctionner entre -40&deg;C et +85&deg;C. Elles r&eacute;sistent aux fortes chutes de tensions soudaines et offrent jusqu&rsquo;&agrave; 2 partitions Boot et 2 partitions utilisateurs. Elles sont conformes aux sp&eacute;cifications eMMC 4,51 (HS200). <\/p>\n<p>De plus en plus, la diff&eacute;renciation entre les mod&egrave;les des constructeurs automobiles ne se fera plus seulement sur les performances, l&rsquo;esth&eacute;tique, le confort ou la consommation de carburant, mais aussi sur l&rsquo;environnement technologique dans l&rsquo;habitacle avec une &eacute;lectronique et des moyens de communications de plus en plus important. Les applications connect&eacute;es jusqu&rsquo;ici r&eacute;serv&eacute;es aux Smartphones vont trouver toute leur place dans les v&eacute;hicules &agrave; venir. Selon les pr&eacute;visions du cabinet Gartner, environ 20 % des v&eacute;hicules en circulation dans le monde seront connect&eacute;s sous une forme ou une autre &agrave; un r&eacute;seau sans fil d&rsquo;ici 2020, ce qui repr&eacute;sente plus de 250 millions de v&eacute;hicules connect&eacute;s en circulation ! <br \/>\n<a href=\"http:\/\/www.sandisk.com\" target=\"_blank\" title=\"www.sandisk.com\" rel=\"noopener\">www.sandisk.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ScanDisk vient d&rsquo;annoncer une nouvelle gamme de cartes m\u00e9moires Flash NAND adapt\u00e9e aux contraintes sp\u00e9cifiques de l&rsquo;automobile et con\u00e7ue pour les applications embarqu\u00e9es des \u00ab v\u00e9hicules connect\u00e9s \u00bb comme la cartographie 3D et la r\u00e9alit\u00e9 augment\u00e9e avanc\u00e9e pour les syst\u00e8mes d\u2019aide \u00e0 la navigation, le divertissement, la technologie intuitive d\u2019assistance \u00e0 la conduite (ADAS), ou encore les enregistreurs d\u2019\u00e9v\u00e9nements<\/p>\n","protected":false},"author":22,"featured_media":232145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1149],"class_list":["post-232144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Stockage flash conforme aux normes automobiles pour l\u2019info-di...<\/title>\n<meta name=\"description\" content=\"ScanDisk vient d&#039;annoncer une nouvelle gamme de cartes m\u00e9moires Flash NAND adapt\u00e9e aux contraintes sp\u00e9cifiques de l&#039;automobile et con\u00e7ue pour les...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/232144\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement\" \/>\n<meta property=\"og:description\" content=\"ScanDisk vient d&#039;annoncer une nouvelle gamme de cartes m\u00e9moires Flash NAND adapt\u00e9e aux contraintes sp\u00e9cifiques de l&#039;automobile et con\u00e7ue pour les applications embarqu\u00e9es des \u00ab v\u00e9hicules connect\u00e9s \u00bb comme la cartographie 3D et la r\u00e9alit\u00e9 augment\u00e9e avanc\u00e9e pour les syst\u00e8mes d\u2019aide \u00e0 la navigation, le divertissement, la technologie intuitive d\u2019assistance \u00e0 la conduite (ADAS), ou encore les enregistreurs d\u2019\u00e9v\u00e9nements\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/232144\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-03T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/import\/scandisk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eeNews Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eeNews Europe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/\"},\"author\":{\"name\":\"eeNews Europe\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\"},\"headline\":\"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement\",\"datePublished\":\"2015-02-03T23:00:00+00:00\",\"dateModified\":\"2015-02-03T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/\",\"name\":\"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2015-02-03T23:00:00+00:00\",\"dateModified\":\"2015-02-03T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\",\"name\":\"eeNews Europe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"caption\":\"eeNews Europe\"}}]}<\/script>","yoast_head_json":{"title":"Stockage flash conforme aux normes automobiles pour l\u2019info-di...","description":"ScanDisk vient d'annoncer une nouvelle gamme de cartes m\u00e9moires Flash NAND adapt\u00e9e aux contraintes sp\u00e9cifiques de l'automobile et con\u00e7ue pour les...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/232144\/","og_locale":"fr_FR","og_type":"article","og_title":"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement","og_description":"ScanDisk vient d'annoncer une nouvelle gamme de cartes m\u00e9moires Flash NAND adapt\u00e9e aux contraintes sp\u00e9cifiques de l'automobile et con\u00e7ue pour les applications embarqu\u00e9es des \u00ab v\u00e9hicules connect\u00e9s \u00bb comme la cartographie 3D et la r\u00e9alit\u00e9 augment\u00e9e avanc\u00e9e pour les syst\u00e8mes d\u2019aide \u00e0 la navigation, le divertissement, la technologie intuitive d\u2019assistance \u00e0 la conduite (ADAS), ou encore les enregistreurs d\u2019\u00e9v\u00e9nements","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/232144\/","og_site_name":"EENewsEurope","article_published_time":"2015-02-03T23:00:00+00:00","og_image":[{"width":250,"height":194,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/import\/scandisk.jpg","type":"image\/jpeg"}],"author":"eeNews Europe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eeNews Europe","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/"},"author":{"name":"eeNews Europe","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4"},"headline":"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement","datePublished":"2015-02-03T23:00:00+00:00","dateModified":"2015-02-03T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/"},"wordCount":223,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/","url":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/","name":"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2015-02-03T23:00:00+00:00","dateModified":"2015-02-03T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/stockage-flash-conforme-aux-normes-automobiles-pour-linfo-divertissement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Stockage flash conforme aux normes automobiles pour l\u2019info-divertissement"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4","name":"eeNews Europe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22","url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","caption":"eeNews Europe"}}]}},"authors":[{"term_id":1149,"user_id":22,"is_guest":0,"slug":"eenews-europe","display_name":"eeNews Europe","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/232144"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=232144"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/232144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/232145"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=232144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=232144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=232144"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=232144"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=232144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}