{"id":231976,"date":"2015-01-15T23:00:00","date_gmt":"2015-01-15T23:00:00","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/"},"modified":"2015-01-15T23:00:00","modified_gmt":"2015-01-15T23:00:00","slug":"des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/","title":{"rendered":"Des oscilloscopes leaders dans l&rsquo;analyse du protocole d&rsquo;interface CAN FD haute vitesse"},"content":{"rendered":"<p>Introduit en 2012, le protocole de bus s&eacute;rie CAN FD am&eacute;liore la performance du Controller Area Network (CAN) avec un d&eacute;bit de donn&eacute;es maximum de 15 Mb\/s. L&rsquo;industrie automobile b&eacute;n&eacute;ficie de cet avantage notamment dans le d&eacute;veloppement de solutions de gestion de moteurs modernes. L&rsquo;option R&amp;S RTx-K9 permet d&eacute;sormais aux utilisateurs d&rsquo;oscilloscopes R&amp;S RTE et R&amp;S RTO d&rsquo;analyser les interfaces de ce type et de d&eacute;clencher sur des d&eacute;tails de protocole. Le d&eacute;codage mat&eacute;riel r&eacute;alis&eacute; avec ces oscilloscopes permet de d&eacute;tecter tr&egrave;s rapidement les erreurs, acc&eacute;l&eacute;rant ainsi la v&eacute;rification de la conception et des processus de mise en service pour les chipsets dot&eacute;s d&rsquo;interfaces CAN FD.<br \/>\nLes utilisateurs peuvent d&eacute;clencher, soit au d&eacute;but ou &agrave; l&rsquo;arr&ecirc;t du datagramme, soit sur des donn&eacute;es sp&eacute;cifiques et utiliser les fonctions de recherche et de navigation hautement performantes, ce qui permet de d&eacute;couvrir les &eacute;v&eacute;nements pertinents dans le protocole de bus CAN FD. Les datagrammes d&eacute;cod&eacute;s sont affich&eacute;s sous forme de signaux bus cod&eacute;s en couleur dans un diagramme de forme d&rsquo;onde ou de tableau. La nouvelle option logicielle de Rohde &amp; Schwarz prend &eacute;galement en charge le standard de l&rsquo;industrie des fichiers CAN-dbc pour d&eacute;crire des configurations de bus. Le R&amp;S RTE et le R&amp;S RTO permettent aux utilisateurs de d&eacute;coder simultan&eacute;ment jusqu&rsquo;&agrave; quatre signaux de bus s&eacute;rie analogiques ou logiques. <br \/>\nPour ses oscilloscopes, Rohde &amp; Schwarz propose de nombreuses solutions suppl&eacute;mentaires parfaitement adapt&eacute;es &agrave; l&rsquo;industrie automobile. Elles comprennent les options de d&eacute;codage et de d&eacute;clenchement CAN \/ LIN et FlexRay pour le d&eacute;bogage lors du d&eacute;veloppement et de l&rsquo;int&eacute;gration des composants. Il existe &eacute;galement une option pour la v&eacute;rification de la conformit&eacute; BroadR-Reach &ndash;une technologie d&eacute;sormais de plus en plus utilis&eacute;e pour la mise en r&eacute;seau de diff&eacute;rents syst&egrave;mes embarqu&eacute;s dans les v&eacute;hicules.<br \/>\nLes options de d&eacute;clenchement et de d&eacute;codage CAN FD R&amp;S RTO-K9 et R&amp;S RTE-K9 sont d&egrave;s &agrave; pr&eacute;sent disponibles aupr&egrave;s de Rohde &amp; Schwarz. <br \/>\n<a title=\"www.rohde-schwarz.com\" target=\"_blank\" href=\"http:\/\/www.rohde-schwarz.com\" rel=\"noopener\">www.rohde-schwarz.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec ses oscilloscopes R&amp;S RTO et R&amp;S RTE, Rohde &amp; Schwarz est un des premiers fournisseurs \u00e0 proposer des solutions d&rsquo;analyse pour le protocole d&rsquo;interface CAN \u00e0 d\u00e9bit de donn\u00e9es flexible (CAN FD). En effet, une nouvelle option permet aux concepteurs d\u2019analyser les interfaces CAN supportant le protocole de bus haute vitesse CAN FD. Ces interfaces sont de plus en plus utilis\u00e9es dans les applications automobiles et de l&rsquo;industrie suite \u00e0 l\u2019augmentation constante des exigences en mati\u00e8re de d\u00e9bits de donn\u00e9es.<\/p>\n","protected":false},"author":22,"featured_media":231977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1149],"class_list":["post-231976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Des oscilloscopes leaders dans l&#039;analyse du protocole d&#039;interfa...<\/title>\n<meta name=\"description\" content=\"Avec ses oscilloscopes R&amp;S RTO et R&amp;S RTE, Rohde &amp; Schwarz est un des premiers fournisseurs \u00e0 proposer des solutions d&#039;analyse pour le protocole...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/231976\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des oscilloscopes leaders dans l&#039;analyse du protocole d&#039;interface CAN FD haute vitesse\" \/>\n<meta property=\"og:description\" content=\"Avec ses oscilloscopes R&amp;S RTO et R&amp;S RTE, Rohde &amp; Schwarz est un des premiers fournisseurs \u00e0 proposer des solutions d&#039;analyse pour le protocole d&#039;interface CAN \u00e0 d\u00e9bit de donn\u00e9es flexible (CAN FD). En effet, une nouvelle option permet aux concepteurs d\u2019analyser les interfaces CAN supportant le protocole de bus haute vitesse CAN FD. Ces interfaces sont de plus en plus utilis\u00e9es dans les applications automobiles et de l&#039;industrie suite \u00e0 l\u2019augmentation constante des exigences en mati\u00e8re de d\u00e9bits de donn\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/231976\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-15T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/import\/eci4594_rohde_schwarz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eeNews Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eeNews Europe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/\"},\"author\":{\"name\":\"eeNews Europe\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\"},\"headline\":\"Des oscilloscopes leaders dans l&rsquo;analyse du protocole d&rsquo;interface CAN FD haute vitesse\",\"datePublished\":\"2015-01-15T23:00:00+00:00\",\"dateModified\":\"2015-01-15T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/\"},\"wordCount\":471,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/\",\"name\":\"Des oscilloscopes leaders dans l'analyse du protocole d'interface CAN FD haute vitesse -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2015-01-15T23:00:00+00:00\",\"dateModified\":\"2015-01-15T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des oscilloscopes leaders dans l&rsquo;analyse du protocole d&rsquo;interface CAN FD haute vitesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\",\"name\":\"eeNews Europe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"caption\":\"eeNews Europe\"}}]}<\/script>","yoast_head_json":{"title":"Des oscilloscopes leaders dans l'analyse du protocole d'interfa...","description":"Avec ses oscilloscopes R&amp;S RTO et R&amp;S RTE, Rohde &amp; Schwarz est un des premiers fournisseurs \u00e0 proposer des solutions d'analyse pour le protocole...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/231976\/","og_locale":"fr_FR","og_type":"article","og_title":"Des oscilloscopes leaders dans l'analyse du protocole d'interface CAN FD haute vitesse","og_description":"Avec ses oscilloscopes R&amp;S RTO et R&amp;S RTE, Rohde &amp; Schwarz est un des premiers fournisseurs \u00e0 proposer des solutions d'analyse pour le protocole d'interface CAN \u00e0 d\u00e9bit de donn\u00e9es flexible (CAN FD). En effet, une nouvelle option permet aux concepteurs d\u2019analyser les interfaces CAN supportant le protocole de bus haute vitesse CAN FD. Ces interfaces sont de plus en plus utilis\u00e9es dans les applications automobiles et de l'industrie suite \u00e0 l\u2019augmentation constante des exigences en mati\u00e8re de d\u00e9bits de donn\u00e9es.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/231976\/","og_site_name":"EENewsEurope","article_published_time":"2015-01-15T23:00:00+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/import\/eci4594_rohde_schwarz.jpg","type":"image\/jpeg"}],"author":"eeNews Europe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eeNews Europe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/"},"author":{"name":"eeNews Europe","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4"},"headline":"Des oscilloscopes leaders dans l&rsquo;analyse du protocole d&rsquo;interface CAN FD haute vitesse","datePublished":"2015-01-15T23:00:00+00:00","dateModified":"2015-01-15T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/"},"wordCount":471,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/","url":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/","name":"Des oscilloscopes leaders dans l'analyse du protocole d'interface CAN FD haute vitesse -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2015-01-15T23:00:00+00:00","dateModified":"2015-01-15T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/des-oscilloscopes-leaders-dans-lanalyse-du-protocole-dinterface-can-fd-haute-vitesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Des oscilloscopes leaders dans l&rsquo;analyse du protocole d&rsquo;interface CAN FD haute vitesse"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4","name":"eeNews Europe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22","url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","caption":"eeNews Europe"}}]}},"authors":[{"term_id":1149,"user_id":22,"is_guest":0,"slug":"eenews-europe","display_name":"eeNews Europe","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/231976"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=231976"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/231976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/231977"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=231976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=231976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=231976"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=231976"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=231976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}