{"id":230996,"date":"2014-09-22T22:00:00","date_gmt":"2014-09-22T22:00:00","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/"},"modified":"2014-09-22T22:00:00","modified_gmt":"2014-09-22T22:00:00","slug":"regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/","title":{"rendered":"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI"},"content":{"rendered":"<p>D&#8217;emploi ais&eacute;, ces convertisseurs continu-continu se caract&eacute;risent par une tension d&rsquo;entr&eacute;e pouvant atteindre 60 V et un haut niveau de fiabilit&eacute; dans les syst&egrave;mes durcis. Leur courant de veille de 27 &mu;A minimise la consommation sous de faibles charges et la fr&eacute;quence de d&eacute;coupage programmable jusqu&rsquo;&agrave; 2,2 MHz permet d&rsquo;utiliser des composants externes plus compacts. L&rsquo;architecture unique de l&rsquo;&eacute;tage de puissance synchrone r&eacute;duit les &eacute;missions rayonn&eacute;es et assure la conformit&eacute; aux r&eacute;glementations de comptabilit&eacute; &eacute;lectromagn&eacute;tique (CEM) dans un large &eacute;ventail d&rsquo;applications automobiles, industrielles et de communications.<br \/>\nLes r&eacute;gulateurs synchrones LM43600\/1\/2\/3 fonctionnent dans une plage de tension d&rsquo;entr&eacute;e comprise entre 3,5 et 36 V, et g&eacute;n&egrave;rent des courants de sortie pouvant atteindre respectivement 0,5 A, 1 A, 2 A et 3 A. Pour leur part, les r&eacute;f&eacute;rences LM46000\/1\/2 fonctionnent sous une tension d&rsquo;entr&eacute;e comprise entre 3,5 et 60 V avec des courants de sortie de respectivement 0,5 A, 1 A et 2 A. Tous ces composants int&egrave;grent des fonctions de compensation et de contr&ocirc;le, ainsi que des MOSFET afin de limiter la nomenclature (BOM) &agrave; seulement sept composants. Le bo&icirc;tier HTSSOP a &eacute;t&eacute; s&eacute;lectionn&eacute; pour tous les mod&egrave;les de la famille, ce qui garantit une totale compatibilit&eacute; de brochage et d&rsquo;encombrement, ainsi qu&rsquo;une grande &eacute;volutivit&eacute;.<br \/>\nCes r&eacute;gulateurs sont enti&egrave;rement pris en charge par WEBENCH, un outil de conception en ligne propri&eacute;taire pour aider les concepteurs &agrave; g&eacute;n&eacute;rer, optimiser et simuler la conception dans une large plage de tension d&rsquo;entr&eacute;e, avant d&rsquo;exporter le design vers un environnement de CAO.<\/p>\n<\/p>\n<p><a href=\"http:\/\/www.ti.com\/lm43600-pr-eu\" target=\"_blank\" title=\"www.ti.com\/lm43600-pr-eu\" rel=\"noopener\">www.ti.com\/lm43600-pr-eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La famille SIMPLE SWITCHER de Texas Instruments s\u2019\u00e9tend avec les sept r\u00e9gulateurs LM43600\/1\/2\/3 et LM46000\/1\/2 con\u00e7us pour simplifier la conception d\u2019alimentations synchrones fonctionnant dans une large plage de tension d\u2019entr\u00e9e et permettre la r\u00e9alisation de produits \u00e0 haut rendement \u00e9nerg\u00e9tique conformes aux r\u00e9glementations relatives aux interf\u00e9rences \u00e9lectromagn\u00e9tiques (EMI).<\/p>\n","protected":false},"author":22,"featured_media":230997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1149],"class_list":["post-230996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI ...<\/title>\n<meta name=\"description\" content=\"La famille SIMPLE SWITCHER de Texas Instruments s\u2019\u00e9tend avec les sept r\u00e9gulateurs LM43600\/1\/2\/3 et LM46000\/1\/2 con\u00e7us pour simplifier la conception...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/230996\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI\" \/>\n<meta property=\"og:description\" content=\"La famille SIMPLE SWITCHER de Texas Instruments s\u2019\u00e9tend avec les sept r\u00e9gulateurs LM43600\/1\/2\/3 et LM46000\/1\/2 con\u00e7us pour simplifier la conception d\u2019alimentations synchrones fonctionnant dans une large plage de tension d\u2019entr\u00e9e et permettre la r\u00e9alisation de produits \u00e0 haut rendement \u00e9nerg\u00e9tique conformes aux r\u00e9glementations relatives aux interf\u00e9rences \u00e9lectromagn\u00e9tiques (EMI).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/230996\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-22T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/import\/eci6970_texas_ti_lm4360_chip_15sep14-3-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eeNews Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eeNews Europe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/\"},\"author\":{\"name\":\"eeNews Europe\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\"},\"headline\":\"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI\",\"datePublished\":\"2014-09-22T22:00:00+00:00\",\"dateModified\":\"2014-09-22T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/\",\"name\":\"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI -\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2014-09-22T22:00:00+00:00\",\"dateModified\":\"2014-09-22T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\",\"name\":\"eeNews Europe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"caption\":\"eeNews Europe\"}}]}<\/script>","yoast_head_json":{"title":"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI ...","description":"La famille SIMPLE SWITCHER de Texas Instruments s\u2019\u00e9tend avec les sept r\u00e9gulateurs LM43600\/1\/2\/3 et LM46000\/1\/2 con\u00e7us pour simplifier la conception...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/230996\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI","og_description":"La famille SIMPLE SWITCHER de Texas Instruments s\u2019\u00e9tend avec les sept r\u00e9gulateurs LM43600\/1\/2\/3 et LM46000\/1\/2 con\u00e7us pour simplifier la conception d\u2019alimentations synchrones fonctionnant dans une large plage de tension d\u2019entr\u00e9e et permettre la r\u00e9alisation de produits \u00e0 haut rendement \u00e9nerg\u00e9tique conformes aux r\u00e9glementations relatives aux interf\u00e9rences \u00e9lectromagn\u00e9tiques (EMI).","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/230996\/","og_site_name":"EENewsEurope","article_published_time":"2014-09-22T22:00:00+00:00","og_image":[{"width":1500,"height":1200,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/import\/eci6970_texas_ti_lm4360_chip_15sep14-3-.jpg","type":"image\/jpeg"}],"author":"eeNews Europe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eeNews Europe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/"},"author":{"name":"eeNews Europe","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4"},"headline":"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI","datePublished":"2014-09-22T22:00:00+00:00","dateModified":"2014-09-22T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/"},"wordCount":341,"publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/","url":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/","name":"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI -","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/en\/#website"},"datePublished":"2014-09-22T22:00:00+00:00","dateModified":"2014-09-22T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/regulateurs-dc-dc-synchrones-conformes-aux-exigences-emi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9gulateurs DC\/DC synchrones conformes aux exigences EMI"}]},{"@type":"WebSite","@id":"https:\/\/www.eenewseurope.com\/en\/#website","url":"https:\/\/www.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/www.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4","name":"eeNews Europe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22","url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","caption":"eeNews Europe"}}]}},"authors":[{"term_id":1149,"user_id":22,"is_guest":0,"slug":"eenews-europe","display_name":"eeNews Europe","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/230996"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=230996"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/230996\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/230997"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=230996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=230996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=230996"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=230996"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=230996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}