{"id":229796,"date":"2014-04-15T22:00:00","date_gmt":"2014-04-15T22:00:00","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/"},"modified":"2014-04-15T22:00:00","modified_gmt":"2014-04-15T22:00:00","slug":"fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/","title":{"rendered":"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg"},"content":{"rendered":"<p>Arnaud Montebourg se f&eacute;licite &eacute;galement de la d&eacute;cision du tribunal de commerce favorable &agrave; la reprise des deux sites vend&eacute;ens de FagorBrandt. L&rsquo;accord trouv&eacute; entre les repreneurs de ces sites et Cevital permet ainsi de sauvegarder pr&egrave;s de 220 emplois suppl&eacute;mentaires. S20 Industries &agrave; La Roche sur Yon et Variance Technologies &agrave; Aizenay continueront ainsi &agrave; fournir la future entit&eacute; Brandt France, qui retrouvera ainsi son nom historique, en &eacute;quipements de lavage et de cuisson pendant une dur&eacute;e limit&eacute;e leur permettant de migrer &agrave; terme vers de nouvelles activit&eacute;s industrielles.<\/p>\n<p>Ces accords assurent non seulement le maintien de la totalit&eacute; des sites industriels du groupe mais permettent la sauvegarde de pr&egrave;s de 1420 emplois sur les 1800 du groupe.<\/p>\n<p>&quot; Je tiens &agrave; remercier tout particuli&egrave;rement les salari&eacute;s de FagorBrandt pour leur extr&ecirc;me responsabilit&eacute; et la confiance qu&rsquo;ils ont su accorder aux organes de la proc&eacute;dure et au Gouvernement. Je salue &eacute;galement Cevital d&rsquo;avoir su entendre les revendications et attentes de ses futurs salari&eacute;s pour permettre une reprise dans les meilleurs conditions possibles. &quot; d&eacute;clare le Ministre qui restera attentif au red&eacute;marrage de chacun des sites et &agrave; l&rsquo;&eacute;volution du dialogue social. Il invite par ailleurs la grande distribution &agrave; soutenir cet engagement industriel en permettant au groupe de reconqu&eacute;rir sa place de leader en France et aux &eacute;quipements des marques Brandt, Sauter, Vedette et De Dietrich de retrouver rapidement leurs places dans les rayons des magasins.<\/p>\n<hr \/>\n<p>\n<\/p>\n<p>Fran&ccedil;ois Rebsamen, Ministre du Travail, de l&rsquo;Emploi et du Dialogue social, qui salue &eacute;galement cette r&eacute;ussite industrielle indique que pour faciliter la phase de d&eacute;marrage, Brandt pourra b&eacute;n&eacute;ficier de l&rsquo;activit&eacute; partielle. Pour permettre aux salari&eacute;s non repris de retrouver au plus vite un emploi, l&rsquo;Etat mobilise un dispositif d&rsquo;accompagnement renforc&eacute;, avec notamment le maintien de r&eacute;mun&eacute;ration dans le cadre du contrat de s&eacute;curisation professionnelle, l&rsquo;accompagnement des salari&eacute;s par des conseillers sp&eacute;cialis&eacute;s d&eacute;di&eacute;s, et un compl&eacute;ment de salaire pendant deux ans en cas de reclassement sur un emploi moins bien r&eacute;mun&eacute;r&eacute;.  <\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arnaud Montebourg, Ministre de l&rsquo;Economie, du Redressement productif et du  Num\u00e9rique accueille avec satisfaction la d\u00e9cision du tribunal de commerce de Nanterre favorable \u00e0 la reprise de FagorBrandt par le groupe industriel alg\u00e9rien Cevital. Cette reprise porte sur deux sites industriels (Orl\u00e9ans, Vend\u00f4me) et les sites de Rueil et  Cergy en r\u00e9gion parisienne, soit plus de 1.200 postes.<\/p>\n","protected":false},"author":22,"featured_media":229797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1149],"class_list":["post-229796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg ...<\/title>\n<meta name=\"description\" content=\"Arnaud Montebourg, Ministre de l&#039;Economie, du Redressement productif et du  Num\u00e9rique accueille avec satisfaction la d\u00e9cision du tribunal de commerce de...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/229796\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg\" \/>\n<meta property=\"og:description\" content=\"Arnaud Montebourg, Ministre de l&#039;Economie, du Redressement productif et du Num\u00e9rique accueille avec satisfaction la d\u00e9cision du tribunal de commerce de Nanterre favorable \u00e0 la reprise de FagorBrandt par le groupe industriel alg\u00e9rien Cevital. Cette reprise porte sur deux sites industriels (Orl\u00e9ans, Vend\u00f4me) et les sites de Rueil et Cergy en r\u00e9gion parisienne, soit plus de 1.200 postes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/229796\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-15T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/import\/electronic-components.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eeNews Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eeNews Europe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/\"},\"author\":{\"name\":\"eeNews Europe\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\"},\"headline\":\"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg\",\"datePublished\":\"2014-04-15T22:00:00+00:00\",\"dateModified\":\"2014-04-15T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/\",\"name\":\"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg -\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2014-04-15T22:00:00+00:00\",\"dateModified\":\"2014-04-15T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\",\"name\":\"eeNews Europe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"caption\":\"eeNews Europe\"}}]}<\/script>","yoast_head_json":{"title":"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg ...","description":"Arnaud Montebourg, Ministre de l'Economie, du Redressement productif et du  Num\u00e9rique accueille avec satisfaction la d\u00e9cision du tribunal de commerce de...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/229796\/","og_locale":"fr_FR","og_type":"article","og_title":"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg","og_description":"Arnaud Montebourg, Ministre de l'Economie, du Redressement productif et du Num\u00e9rique accueille avec satisfaction la d\u00e9cision du tribunal de commerce de Nanterre favorable \u00e0 la reprise de FagorBrandt par le groupe industriel alg\u00e9rien Cevital. Cette reprise porte sur deux sites industriels (Orl\u00e9ans, Vend\u00f4me) et les sites de Rueil et Cergy en r\u00e9gion parisienne, soit plus de 1.200 postes.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/229796\/","og_site_name":"EENewsEurope","article_published_time":"2014-04-15T22:00:00+00:00","og_image":[{"width":750,"height":630,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/import\/electronic-components.jpg","type":"image\/jpeg"}],"author":"eeNews Europe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eeNews Europe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/"},"author":{"name":"eeNews Europe","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4"},"headline":"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg","datePublished":"2014-04-15T22:00:00+00:00","dateModified":"2014-04-15T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/"},"wordCount":422,"publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/","url":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/","name":"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg -","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/en\/#website"},"datePublished":"2014-04-15T22:00:00+00:00","dateModified":"2014-04-15T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/fagorbrandt-une-reprise-satisfaisante-selon-arnaud-montebourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"FagorBrandt : une reprise satisfaisante selon Arnaud Montebourg"}]},{"@type":"WebSite","@id":"https:\/\/www.eenewseurope.com\/en\/#website","url":"https:\/\/www.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/www.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4","name":"eeNews Europe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22","url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","caption":"eeNews Europe"}}]}},"authors":[{"term_id":1149,"user_id":22,"is_guest":0,"slug":"eenews-europe","display_name":"eeNews Europe","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/229796"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=229796"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/229796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/229797"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=229796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=229796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=229796"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=229796"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=229796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}