{"id":226456,"date":"2013-02-28T23:00:00","date_gmt":"2013-02-28T23:00:00","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/recepteur-economique-huit-canaux-pour-ultrasons\/"},"modified":"2013-02-28T23:00:00","modified_gmt":"2013-02-28T23:00:00","slug":"recepteur-economique-huit-canaux-pour-ultrasons","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/","title":{"rendered":"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons"},"content":{"rendered":"<p>Ce circuit AFE int&egrave;gre un amplificateur faible bruit, un amplificateur &agrave; gain variable, un filtre anti-repliement et un convertisseur analogique\/num&eacute;rique 14 bits. Ce dernier affiche des performances particuli&egrave;rement &eacute;lev&eacute;es avec une fr&eacute;quence d&rsquo;&eacute;chantillonnage de 125 M&eacute;ch\/s et un rapport signal\/bruit de 75 dB pour assurer une qualit&eacute; d&rsquo;images ultrasons optimale. Le filtre &agrave; d&eacute;cimation RF int&eacute;gr&eacute; permet de sur-&eacute;chantillonner le convertisseur analogique\/num&eacute;rique avec, &agrave; la cl&eacute;, un rapport signal\/bruit accru et une qualit&eacute; d&rsquo;image am&eacute;lior&eacute;e tout en maintenant les taux de transfert de donn&eacute;es les plus bas en entr&eacute;e\/sortie. L&rsquo;interface s&eacute;rie JESD204B &agrave; 5 Gbits\/s r&eacute;duit jusqu&rsquo;&agrave; 80 % le routage des donn&eacute;es en entr&eacute;e\/sortie dans les syst&egrave;mes ultrasons par rapport &agrave; d&rsquo;autres interfaces standard. De telles am&eacute;liorations simplifient la conception de la carte des produits &agrave; ultrasons et r&eacute;pondent davantage aux exigences des industriels en termes d&rsquo;augmentation du d&eacute;bit, d&rsquo;augmentation du nombre de canaux et d&rsquo;am&eacute;lioration de la r&eacute;solution des images. Le mod&egrave;le AD9674 dispose des m&ecirc;mes fonctionnalit&eacute;s de base mais est disponible avec une interface LVDS standard.<br \/>\nCes deux composants sont encapsul&eacute;s en bo&icirc;tier de 144 billes, d&rsquo;un faible encombrement de 10 x 10 mm, et sont compatibles au niveau brochage avec les r&eacute;f&eacute;rences AD9670\/AD9671, ce qui assure des possibilit&eacute;s de migration ais&eacute;es pour les projets qui requi&egrave;rent un co&ucirc;t r&eacute;duit et des fonctionnalit&eacute;s num&eacute;riques limit&eacute;es. <\/p>\n<\/p>\n<p><a href=\"http:\/\/www.analog.com\/AD9675\" target=\"_blank\" title=\"www.analog.com\/AD9675\" rel=\"noopener\">www.analog.com\/AD9675<\/a><a href=\"http:\/\/www.analog.com\/AD9674\" target=\"_blank\" title=\"www.analog.com\/AD9674\" rel=\"noopener\"><br \/>\nwww.analog.com\/AD9674<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con\u00e7u pour les syst\u00e8mes \u00e0 ultra-sons \u00e0 usages industriel ou m\u00e9dical portables et mont\u00e9s sur chariot de milieu \u00e0 haut de gamme, le convertisseur analogique frontal (AFE) AD9675 d\u2019Analog Devices offre huit canaux avec filtre \u00e0 d\u00e9cimation RF et interface s\u00e9rie JESD204B. Il simplifie les t\u00e2ches de traitement au niveau syst\u00e8me ainsi que la conception de produits, tout en r\u00e9duisant le routage des donn\u00e9es en entr\u00e9e\/sortie.<\/p>\n","protected":false},"author":22,"featured_media":226457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1149],"class_list":["post-226456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons ...<\/title>\n<meta name=\"description\" content=\"Con\u00e7u pour les syst\u00e8mes \u00e0 ultra-sons \u00e0 usages industriel ou m\u00e9dical portables et mont\u00e9s sur chariot de milieu \u00e0 haut de gamme, le convertisseur...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/226456\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons\" \/>\n<meta property=\"og:description\" content=\"Con\u00e7u pour les syst\u00e8mes \u00e0 ultra-sons \u00e0 usages industriel ou m\u00e9dical portables et mont\u00e9s sur chariot de milieu \u00e0 haut de gamme, le convertisseur analogique frontal (AFE) AD9675 d\u2019Analog Devices offre huit canaux avec filtre \u00e0 d\u00e9cimation RF et interface s\u00e9rie JESD204B. Il simplifie les t\u00e2ches de traitement au niveau syst\u00e8me ainsi que la conception de produits, tout en r\u00e9duisant le routage des donn\u00e9es en entr\u00e9e\/sortie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/226456\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-28T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/import\/eci6370_logo_ad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"467\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eeNews Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eeNews Europe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/\"},\"author\":{\"name\":\"eeNews Europe\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\"},\"headline\":\"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons\",\"datePublished\":\"2013-02-28T23:00:00+00:00\",\"dateModified\":\"2013-02-28T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/\",\"name\":\"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons -\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2013-02-28T23:00:00+00:00\",\"dateModified\":\"2013-02-28T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\",\"name\":\"eeNews Europe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"caption\":\"eeNews Europe\"}}]}<\/script>","yoast_head_json":{"title":"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons ...","description":"Con\u00e7u pour les syst\u00e8mes \u00e0 ultra-sons \u00e0 usages industriel ou m\u00e9dical portables et mont\u00e9s sur chariot de milieu \u00e0 haut de gamme, le convertisseur...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/226456\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons","og_description":"Con\u00e7u pour les syst\u00e8mes \u00e0 ultra-sons \u00e0 usages industriel ou m\u00e9dical portables et mont\u00e9s sur chariot de milieu \u00e0 haut de gamme, le convertisseur analogique frontal (AFE) AD9675 d\u2019Analog Devices offre huit canaux avec filtre \u00e0 d\u00e9cimation RF et interface s\u00e9rie JESD204B. Il simplifie les t\u00e2ches de traitement au niveau syst\u00e8me ainsi que la conception de produits, tout en r\u00e9duisant le routage des donn\u00e9es en entr\u00e9e\/sortie.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/226456\/","og_site_name":"EENewsEurope","article_published_time":"2013-02-28T23:00:00+00:00","og_image":[{"width":467,"height":339,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/import\/eci6370_logo_ad.jpg","type":"image\/jpeg"}],"author":"eeNews Europe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eeNews Europe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/"},"author":{"name":"eeNews Europe","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4"},"headline":"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons","datePublished":"2013-02-28T23:00:00+00:00","dateModified":"2013-02-28T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/"},"wordCount":337,"publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/","url":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/","name":"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons -","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/en\/#website"},"datePublished":"2013-02-28T23:00:00+00:00","dateModified":"2013-02-28T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/recepteur-economique-huit-canaux-pour-ultrasons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9cepteur \u00e9conomique huit canaux pour ultrasons"}]},{"@type":"WebSite","@id":"https:\/\/www.eenewseurope.com\/en\/#website","url":"https:\/\/www.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/www.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4","name":"eeNews Europe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eenewseurope.com\/en\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22","url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","caption":"eeNews Europe"}}]}},"authors":[{"term_id":1149,"user_id":22,"is_guest":0,"slug":"eenews-europe","display_name":"eeNews Europe","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/226456"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=226456"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/226456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/226457"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=226456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=226456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=226456"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=226456"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=226456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}