{"id":222539,"date":"2011-09-26T22:00:00","date_gmt":"2011-09-26T22:00:00","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/dac-cmos-pour-les-systemes-optiques\/"},"modified":"2011-09-26T22:00:00","modified_gmt":"2011-09-26T22:00:00","slug":"dac-cmos-pour-les-systemes-optiques","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/dac-cmos-pour-les-systemes-optiques\/","title":{"rendered":"DAC CMOS pour les syst\u00e8mes optiques"},"content":{"rendered":"<p>Le fait de disposer de convertisseurs aussi performants dans la technologie standard de traitement CMOS pr&eacute;sente l&rsquo;avantage d&rsquo;assurer une int&eacute;gration sur une seule puce avec un DSP complexe et des interfaces de trameur OTN s&eacute;rie &agrave; grande vitesse destin&eacute;s &agrave; former un &eacute;metteur-r&eacute;cepteur DP-QPSK &agrave; 100 Gbits\/s. Pour un tel dispositif dot&eacute; de 4 ADC et de 4 canaux DAC fonctionnant &agrave; 65 G&eacute;ch\/s, le volume de donn&eacute;es (2 Tbits\/s) converti entre analogique et num&eacute;rique (et vice versa) exige une solution monopuce. L&#8217;emploi de DAC &agrave; haute r&eacute;solution et grande vitesse pour la transmission &agrave; la ligne optique, en lieu et place des interfaces num&eacute;riques standard, assure un certain nombre d&rsquo;avantages. La gestion des asym&eacute;tries entre les quatre voies de composants du signal se fait dans le domaine num&eacute;rique, ce qui permet un contr&ocirc;le tr&egrave;s stable en cas de variations de traitement, de temp&eacute;rature ou de tension dans l&rsquo;&eacute;metteur-r&eacute;cepteur. Ce traitement du signal dans le domaine num&eacute;rique permet &eacute;galement de compenser les non-lin&eacute;arit&eacute;s de la cha&icirc;ne optique de transmission et d&rsquo;att&eacute;nuer les r&eacute;flexions des signaux sur les E\/S de l&rsquo;appareil. L&rsquo;int&eacute;gration du DAC &agrave; 4 canaux dans un &eacute;metteur-r&eacute;cepteur supprime &eacute;galement la n&eacute;cessit&eacute; de disposer d&rsquo;un multiplexeur\/encodeur s&eacute;par&eacute;.<br \/>\nPour les syst&egrave;mes de transport optique qui prendront en charge des d&eacute;bits plus &eacute;lev&eacute;s (par exemple, &agrave; 400 Gbits\/s), des sch&eacute;mas de modulation d&rsquo;ordre sup&eacute;rieur peuvent aussi &ecirc;tre employ&eacute;s. Le DAC &agrave; 65 G&eacute;ch\/s en 40 nm de Fujitsu et les convertisseurs de donn&eacute;es ult&eacute;rieurs, en cours de d&eacute;veloppement, qui pr&eacute;sentent des taux d&rsquo;&eacute;chantillonnage encore plus &eacute;lev&eacute;s dans des n&oelig;uds de proc&eacute;d&eacute; plus petits, constituent des vecteurs essentiels de la technologie pour ces syst&egrave;mes de prochaine g&eacute;n&eacute;ration. Outre fournir une feuille de route viable pour les syst&egrave;mes de transport optique longue port&eacute;e de prochaine g&eacute;n&eacute;ration, la famille de DAC et d&rsquo;ADC &agrave; grande vitesse de Fujitsu prend &eacute;galement en charge des applications de produits dans des domaines tels que les essais et les mesures, l&rsquo;acc&egrave;s optique et l&rsquo;interconnexion courte port&eacute;e &agrave; tr&egrave;s haut d&eacute;bit.<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/intranet.tim-europe.com\/owa\/redaction@tim-europe.com\/redir.aspx?C=adcbda8ee7ed45bd924b7ad5bbd9d922&amp;URL=http%3a%2f%2femea.fujitsu.com%2fsemiconductor\" rel=\"noopener\">http:\/\/emea.fujitsu.com\/semiconductor<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fujitsu Semiconductor Europe d\u00e9voile son DAC \u00e0 8 bits et 4 canaux de premi\u00e8re g\u00e9n\u00e9ration dans une technologie CMOS \u00e0 40 nm. Avec des taux d&rsquo;\u00e9chantillonnage compris entre 55 et 65 GSa\/s par canal, un faible encombrement et une basse puissance (0,75 W\/canal), cette technologie est compatible avec les syst\u00e8mes de transport optique longue port\u00e9e qui assurent des liaisons de donn\u00e9es de 100 Gbits\/s et plus sur une seule lambda. Compl\u00e9tant l&rsquo;ADC CHAIS de Fujitsu \u00e0 40 nm, de 55 \u00e0 65 G\u00e9ch\/s pour les r\u00e9cepteurs coh\u00e9rents de 100 Gbits\/s, le nouveau DAC propose \u00e9galement des taux d&rsquo;\u00e9chantillonnage ultra-rapides, une haute r\u00e9solution, un faible bruit et la g\u00e9n\u00e9ration d&rsquo;un signal \u00e0 large bande passante pour les signaux OTU4.<\/p>\n","protected":false},"author":22,"featured_media":222540,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1149],"class_list":["post-222539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>DAC CMOS pour les syst\u00e8mes optiques ...<\/title>\n<meta name=\"description\" content=\"Fujitsu Semiconductor Europe d\u00e9voile son DAC \u00e0 8 bits et 4 canaux de premi\u00e8re g\u00e9n\u00e9ration dans une technologie CMOS \u00e0 40 nm. Avec des taux...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/222539\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAC CMOS pour les syst\u00e8mes optiques\" \/>\n<meta property=\"og:description\" content=\"Fujitsu Semiconductor Europe d\u00e9voile son DAC \u00e0 8 bits et 4 canaux de premi\u00e8re g\u00e9n\u00e9ration dans une technologie CMOS \u00e0 40 nm. Avec des taux d&#039;\u00e9chantillonnage compris entre 55 et 65 GSa\/s par canal, un faible encombrement et une basse puissance (0,75 W\/canal), cette technologie est compatible avec les syst\u00e8mes de transport optique longue port\u00e9e qui assurent des liaisons de donn\u00e9es de 100 Gbits\/s et plus sur une seule lambda. Compl\u00e9tant l&#039;ADC CHAIS de Fujitsu \u00e0 40 nm, de 55 \u00e0 65 G\u00e9ch\/s pour les r\u00e9cepteurs coh\u00e9rents de 100 Gbits\/s, le nouveau DAC propose \u00e9galement des taux d&#039;\u00e9chantillonnage ultra-rapides, une haute r\u00e9solution, un faible bruit et la g\u00e9n\u00e9ration d&#039;un signal \u00e0 large bande passante pour les signaux OTU4.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/222539\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-26T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/import\/eci2305_fujitsu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eeNews Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eeNews Europe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/\"},\"author\":{\"name\":\"eeNews Europe\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\"},\"headline\":\"DAC CMOS pour les syst\u00e8mes optiques\",\"datePublished\":\"2011-09-26T22:00:00+00:00\",\"dateModified\":\"2011-09-26T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/\",\"name\":\"DAC CMOS pour les syst\u00e8mes optiques -\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\"},\"datePublished\":\"2011-09-26T22:00:00+00:00\",\"dateModified\":\"2011-09-26T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAC CMOS pour les syst\u00e8mes optiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#website\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4\",\"name\":\"eeNews Europe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g\",\"caption\":\"eeNews Europe\"}}]}<\/script>","yoast_head_json":{"title":"DAC CMOS pour les syst\u00e8mes optiques ...","description":"Fujitsu Semiconductor Europe d\u00e9voile son DAC \u00e0 8 bits et 4 canaux de premi\u00e8re g\u00e9n\u00e9ration dans une technologie CMOS \u00e0 40 nm. Avec des taux...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/222539\/","og_locale":"fr_FR","og_type":"article","og_title":"DAC CMOS pour les syst\u00e8mes optiques","og_description":"Fujitsu Semiconductor Europe d\u00e9voile son DAC \u00e0 8 bits et 4 canaux de premi\u00e8re g\u00e9n\u00e9ration dans une technologie CMOS \u00e0 40 nm. Avec des taux d'\u00e9chantillonnage compris entre 55 et 65 GSa\/s par canal, un faible encombrement et une basse puissance (0,75 W\/canal), cette technologie est compatible avec les syst\u00e8mes de transport optique longue port\u00e9e qui assurent des liaisons de donn\u00e9es de 100 Gbits\/s et plus sur une seule lambda. Compl\u00e9tant l'ADC CHAIS de Fujitsu \u00e0 40 nm, de 55 \u00e0 65 G\u00e9ch\/s pour les r\u00e9cepteurs coh\u00e9rents de 100 Gbits\/s, le nouveau DAC propose \u00e9galement des taux d'\u00e9chantillonnage ultra-rapides, une haute r\u00e9solution, un faible bruit et la g\u00e9n\u00e9ration d'un signal \u00e0 large bande passante pour les signaux OTU4.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/222539\/","og_site_name":"EENewsEurope","article_published_time":"2011-09-26T22:00:00+00:00","og_image":[{"width":2100,"height":1500,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/import\/eci2305_fujitsu.jpg","type":"image\/jpeg"}],"author":"eeNews Europe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"eeNews Europe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/"},"author":{"name":"eeNews Europe","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4"},"headline":"DAC CMOS pour les syst\u00e8mes optiques","datePublished":"2011-09-26T22:00:00+00:00","dateModified":"2011-09-26T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/"},"wordCount":472,"publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/","url":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/","name":"DAC CMOS pour les syst\u00e8mes optiques -","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/#website"},"datePublished":"2011-09-26T22:00:00+00:00","dateModified":"2011-09-26T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/dac-cmos-pour-les-systemes-optiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"DAC CMOS pour les syst\u00e8mes optiques"}]},{"@type":"WebSite","@id":"https:\/\/www.ecinews.fr\/fr\/#website","url":"https:\/\/www.ecinews.fr\/fr\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.ecinews.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecinews.fr\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecinews.fr\/fr\/#organization","name":"EENewsEurope","url":"https:\/\/www.ecinews.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/9eff4051fa9dac8230052de45e32b0f4","name":"eeNews Europe","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecinews.fr\/fr\/#\/schema\/person\/image\/fae8f0cb15861c4ae0ed4872e2c9fc22","url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","caption":"eeNews Europe"}}]}},"authors":[{"term_id":1149,"user_id":22,"is_guest":0,"slug":"eenews-europe","display_name":"eeNews Europe","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5081509054e28b04ecd976976e723ce0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/222539"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=222539"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/222539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/222540"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=222539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=222539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=222539"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=222539"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=222539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}