{"id":17551,"date":"2021-02-16T16:45:44","date_gmt":"2021-02-16T16:45:44","guid":{"rendered":"https:\/\/\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/"},"modified":"2021-02-16T16:45:44","modified_gmt":"2021-02-16T16:45:44","slug":"livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/","title":{"rendered":"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN"},"content":{"rendered":"<p>L&rsquo;\u00e9valuation des march\u00e9s verticaux a constitu\u00e9 un \u00e9l\u00e9ment cl\u00e9 pour l&rsquo;\u00e9laboration de ce livre blanc. ABI Research a constat\u00e9 que le protocole LoRaWAN \u00e9tait la principale technologie de r\u00e9seau \u00e9tendu \u00e0 faible consommation (LPWA), non soumise \u00e0 une licence, utilis\u00e9e sur les grands march\u00e9s verticaux de l&rsquo;IoT, notamment les compteurs, les villes intelligentes, le tra\u00e7age d&rsquo;actifs et la logistique, ainsi que l&rsquo;automatisation des b\u00e2timents commerciaux et des habitations. En plus d&rsquo;un aper\u00e7u des march\u00e9s verticaux, ce livre blanc explore cinq cas de d\u00e9ploiement du r\u00e9seau LoRaWAN, bas\u00e9s sur des architectures multi-RAN&nbsp;:<\/p>\n<ul>\n<li>Orange permet la gestion de dispositifs et de donn\u00e9es pour technologies r\u00e9seau LPWA cellulaire ou non cellulaire, gr\u00e2ce \u00e0 sa plateforme Orange Live Objects.<\/li>\n<li>JRI-MySirius utilise des capteurs s&rsquo;appuyant sur le protocole LoRaWAN et sur une plateforme d&rsquo;application cloud pour assurer la surveillance de temp\u00e9rature cl\u00e9s en main d&rsquo;actifs fixes ou mobiles.<\/li>\n<li>Ercogener a d\u00e9velopp\u00e9 une solution de tra\u00e7age d&rsquo;actifs d&rsquo;un bout \u00e0 l&rsquo;autre, utilisant le protocole LoRaWAN, et exploit\u00e9e par la SNCF (Soci\u00e9t\u00e9 Nationale des Chemins de Fer fran\u00e7ais).<\/li>\n<li>La passerelle programmable de MultiTech est la premi\u00e8re passerelle int\u00e9grant LoRa\u00ae pour applications IoT industrielles, qui offre une connectivit\u00e9 Ethernet, 2G, 3G, 4G-LTE, Wi-Fi, Bluetooth\/BLE et GNSS.<\/li>\n<li>Chevron a mis en place une infrastructure r\u00e9seau LoRaWAN pour num\u00e9riser une s\u00e9rie de champs p\u00e9trolif\u00e8res et gaziers.<\/li>\n<\/ul>\n<p>\u00ab&nbsp;L&rsquo;avenir de la connectivit\u00e9 IoT n\u00e9cessite des solutions polyvalentes r\u00e9pondant aux besoins d&rsquo;un large \u00e9ventail d&rsquo;applications IoT verticales, de cas d&rsquo;utilisation et de types de dispositifs diff\u00e9rents,&nbsp;\u00bb d\u00e9clare Marc Pegulu, Vice-Pr\u00e9sident Applications IoT au sein du groupe Produits sans fil et D\u00e9tection de Semtech. \u00ab&nbsp;LoRa et le protocole ouvert LoRaWAN permettent une interop\u00e9rabilit\u00e9 et une connexion transparente entre les nombreux dispositifs susceptibles de coexister au sein d&rsquo;un m\u00eame environnement. En tant que fournisseur de technologie, notre travail consiste \u00e0 cr\u00e9er des solutions qui facilitent le d\u00e9ploiement et l&rsquo;utilisation par les gens.&nbsp;\u00bb<\/p>\n<p>L&rsquo;\u00e9tude conclut que les dispositifs LoRa vont jouer un r\u00f4le important en tant que principale technologie r\u00e9seau LPWA, aujourd&rsquo;hui et \u00e0 l&rsquo;avenir, dans la mesure o\u00f9 l&rsquo;IoT ne cesse de connecter des dispositifs physiques au monde num\u00e9rique. Parmi les autres points cl\u00e9s mis en \u00e9vidence dans ce livre blanc, citons&nbsp;:<\/p>\n<ul>\n<li>Les technologies r\u00e9seaux 5G et non cellulaires vont coexister&nbsp;: \u00c0 l&rsquo;avenir, les r\u00e9seaux LoRaWAN et 5G vont coexister sous la forme de r\u00e9seaux hybrides ou d&rsquo;architectures multi-RAN.<\/li>\n<li>La mise en place de la 5G int\u00e9grale prendra plus de temps que pr\u00e9vu&nbsp;: La 5G est incapable de faire face \u00e0 un IoT massif \u00e0 court terme. Les r\u00e9seaux 5G et le mat\u00e9riel supportant les sp\u00e9cifications Version&nbsp;17 ne seront pas disponibles commercialement avant d\u00e9but 2024.<\/li>\n<\/ul>\n<ul>\n<li>La technologie LoRa est leader dans le domaine LPWA&nbsp;: D&rsquo;ici 2026, LoRa devrait \u00eatre la principale technologie r\u00e9seau LPWA non-cellulaire, et repr\u00e9sentera plus d&rsquo;un quart de toutes les connexions r\u00e9seau LPWA, et plus de la moiti\u00e9 de toutes les connexions LPWA non-cellulaires. En 2026, le nombre total de connexions LPWA non cellulaires devrait atteindre 1,3&nbsp;milliard.<\/li>\n<li>La technologie LoRa va au-del\u00e0 des applications d&rsquo;entreprise&nbsp;: Les applications grand public s&rsquo;appuyant sur LoRa commencent \u00e0 d\u00e9coller. L&rsquo;architecture traditionnelle est confront\u00e9e \u00e0 la concurrence des technologies r\u00e9seaux LPWA, qui permettent une connectivit\u00e9 directe entre les dispositifs et le Cloud, pour un nombre croissant de dispositifs domestiques intelligents.<\/li>\n<\/ul>\n<p>T\u00e9l\u00e9chargez&nbsp;<a href=\"https:\/\/info.semtech.com\/abi-research-white-paper\">LoRaWAN et architecture multi-RAN pour connecter le prochain milliard de dispositifs IoT<\/a>&nbsp;pour en savoir plus, et consultez aussi <a href=\"https:\/\/info.semtech.com\/iot-network-comparison-infographic\">l&rsquo;infographie sur la comparaison des technologies<\/a> r\u00e9seaux r\u00e9alis\u00e9s par Semtech.<\/p>\n<p><strong><u>\u00c0 propos de la plateforme LoRa <\/u><\/strong><\/p>\n<p>La plateforme dispositif-Cloud, LoRa de Semtech est une solution longue port\u00e9e et faible consommation adopt\u00e9e partout dans le monde pour les applications IoT. Elle permet le d\u00e9veloppement et le d\u00e9ploiement rapide de r\u00e9seaux, de passerelles, de capteurs, de modules et de services IoT longue port\u00e9e, \u00e9conomiques et ultra-basse consommation, dans le monde entier. Les dispositifs LoRa Semtech fournissent la couche communication du protocole LoRaWAN, qui est g\u00e9r\u00e9 par LoRa Alliance, une alliance IoT ouverte pour les applications LPWAN (Low Power Wide Area Network) utilis\u00e9e pour d\u00e9ployer des r\u00e9seaux IoT dans plus de 100 pays. Semtech est un membre fondateur de LoRa Alliance. Pour en savoir plus sur le r\u00f4le de LoRa dans l&rsquo;IoT, visitez le site Semtech <a href=\"https:\/\/www.semtech.com\/lora\" target=\"_blank\" rel=\"noopener\">LoRa<\/a>.<\/p>\n<p><a href=\"http:\/\/www.semtech.com\/\">www.semtech.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Semtech Corporation a annonc\u00e9 la publication du livre blanc LoRaWAN et architecture multi-RAN pour connecter le prochain milliard de dispositifs IoT, co-\u00e9crit avec le cabinet d\u2019analystes ABI Research. Ce livre blanc explore la croissance rapide de la connectivit\u00e9 massive \u00e0 l&rsquo;Internet des objets (IoT), ainsi que les applications issues du monde r\u00e9el susceptibles de profiter des architectures multi-RAN. <\/p>\n","protected":false},"author":9,"featured_media":17552,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-17551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Livre blanc sur la croissance de la technologie LoRa et du prot...<\/title>\n<meta name=\"description\" content=\"Semtech Corporation a annonc\u00e9 la publication du livre blanc LoRaWAN et architecture multi-RAN pour connecter le prochain milliard de dispositifs IoT,...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17551\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN\" \/>\n<meta property=\"og:description\" content=\"Semtech Corporation a annonc\u00e9 la publication du livre blanc LoRaWAN et architecture multi-RAN pour connecter le prochain milliard de dispositifs IoT, co-\u00e9crit avec le cabinet d\u2019analystes ABI Research. Ce livre blanc explore la croissance rapide de la connectivit\u00e9 massive \u00e0 l&#039;Internet des objets (IoT), ainsi que les applications issues du monde r\u00e9el susceptibles de profiter des architectures multi-RAN.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17551\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-16T16:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9110_semtech-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN\",\"datePublished\":\"2021-02-16T16:45:44+00:00\",\"dateModified\":\"2021-02-16T16:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/\"},\"wordCount\":808,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/\",\"name\":\"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-02-16T16:45:44+00:00\",\"dateModified\":\"2021-02-16T16:45:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Livre blanc sur la croissance de la technologie LoRa et du prot...","description":"Semtech Corporation a annonc\u00e9 la publication du livre blanc LoRaWAN et architecture multi-RAN pour connecter le prochain milliard de dispositifs IoT,...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17551\/","og_locale":"fr_FR","og_type":"article","og_title":"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN","og_description":"Semtech Corporation a annonc\u00e9 la publication du livre blanc LoRaWAN et architecture multi-RAN pour connecter le prochain milliard de dispositifs IoT, co-\u00e9crit avec le cabinet d\u2019analystes ABI Research. Ce livre blanc explore la croissance rapide de la connectivit\u00e9 massive \u00e0 l'Internet des objets (IoT), ainsi que les applications issues du monde r\u00e9el susceptibles de profiter des architectures multi-RAN.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17551\/","og_site_name":"EENewsEurope","article_published_time":"2021-02-16T16:45:44+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9110_semtech-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN","datePublished":"2021-02-16T16:45:44+00:00","dateModified":"2021-02-16T16:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/"},"wordCount":808,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/","url":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/","name":"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-02-16T16:45:44+00:00","dateModified":"2021-02-16T16:45:44+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/livre-blanc-sur-la-croissance-de-la-technologie-lora-et-du-protocole-ouvert-lorawan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Livre blanc sur la croissance de la technologie LoRa et du protocole ouvert LoRaWAN"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17551"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=17551"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/17552"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=17551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=17551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=17551"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=17551"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=17551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}