{"id":17459,"date":"2021-02-15T18:33:52","date_gmt":"2021-02-15T18:33:52","guid":{"rendered":"https:\/\/\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/"},"modified":"2021-02-15T18:33:52","modified_gmt":"2021-02-15T18:33:52","slug":"guerre-electronique-thales-et-airbus-selectionnes-par-la-dga","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/","title":{"rendered":"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA"},"content":{"rendered":"<p>Ce contrat de 10 ans permettra d&rsquo;\u00e9quiper les trois arm\u00e9es d&rsquo;un syst\u00e8me d&rsquo;information et d&rsquo;un ensemble de capteurs communs d\u00e9sign\u00e9 programme \u00e0 fort impact (PEM1), aux c\u00f4t\u00e9s de CONTACT et SCORPION. Ce syst\u00e8me tactique conjoint SIGINT dotera le commandement des forces arm\u00e9es fran\u00e7aises d&rsquo;une capacit\u00e9 \u00e9largie de mesures d&rsquo;appui \u00e9lectronique tactique (MES).<\/p>\n<p>Le programme tactique SIGINT am\u00e9liorera les capacit\u00e9s de guerre \u00e9lectronique des unit\u00e9s de premi\u00e8re ligne, en fournissant un ensemble d&rsquo;actifs portables ou mont\u00e9s sur v\u00e9hicule avec les derni\u00e8res technologies de communication.&nbsp;Le nouveau syst\u00e8me de surveillance et de localisation des communications ennemies appuiera les man\u0153uvres tactiques sur le th\u00e9\u00e2tre des op\u00e9rations, contribuant \u00e0 assurer la s\u00e9curit\u00e9 de nos forces.&nbsp;Il \u00e9quipera les v\u00e9hicules de soutien \u00e9lectronique du 54e R\u00e9giment de transmissions de l&rsquo;arm\u00e9e fran\u00e7aise (programme SCORPION), des navires de guerre de premi\u00e8re ligne de la Marine nationale et de l&rsquo;avion de patrouille maritime Atlantique 2, et pourrait \u00eatre d\u00e9ploy\u00e9 pour prot\u00e9ger les bases a\u00e9riennes lors d&rsquo;op\u00e9rations militaires outre-mer.<\/p>\n<p>Thales s&rsquo;appuiera sur l&rsquo;expertise SIGINT d\u00e9velopp\u00e9e par le Groupe sur plusieurs programmes existant &nbsp;et sur ses capacit\u00e9s en mati\u00e8re de communications de bout en bout, de radiocommunications et de s\u00e9curit\u00e9 des communications.<\/p>\n<p>Airbus apportera son expertise dans les syst\u00e8mes ELINT strat\u00e9giques, en s&rsquo;appuyant sur son exp\u00e9rience sur des programmes tels que RAMSES et&nbsp; PARADOS. Ces syst\u00e8mes sont actuellement en service op\u00e9rationnel aupr\u00e8s de la DRM5, de l&rsquo;arm\u00e9e fran\u00e7aise, de l&rsquo;arm\u00e9e de l&rsquo;air et de l&rsquo;espace et de la marine fran\u00e7aise.&nbsp;Airbus s&rsquo;appuiera \u00e9galement sur son savoir-faire en mati\u00e8re d&rsquo;int\u00e9gration de syst\u00e8mes complexes et de s\u00e9curit\u00e9.<\/p>\n<hr \/>\n<p>La premi\u00e8re phase du programme fournira aux trois forces arm\u00e9es une capacit\u00e9 op\u00e9rationnelle initiale pour la surveillance des signaux, avec des tranches optionnelles ult\u00e9rieures pour augmenter consid\u00e9rablement le nombre d&rsquo;unit\u00e9s en service.&nbsp;De nouvelles fonctions (analyse de donn\u00e9es pour le syst\u00e8me d&rsquo;information, capacit\u00e9s de d\u00e9tection et d&rsquo;analyse technique \u00e9tendues, etc.) seront ajout\u00e9es progressivement sur la dur\u00e9e du contrat pour doter les forces arm\u00e9es fran\u00e7aises d&rsquo;un ensemble de dispositifs \u00e9lectroniques de pointe.<\/p>\n<p><a href=\"https:\/\/www.thalesgroup.com\/fr\">https:\/\/www.thalesgroup.com\/fr<\/a><\/p>\n<p><a href=\"https:\/\/www.airbus.com\/\">https:\/\/www.airbus.com\/<\/a><\/p>\n<p><a href=\"https:\/\/www.defense.gouv.fr\/dga\">https:\/\/www.defense.gouv.fr\/dga<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La DGA a attribu\u00e9 \u00e0 Thales et Airbus un contrat pour le nouveau syst\u00e8me commun de renseignement tactique des signaux (SIGINT) afin de mettre \u00e0 niveau les capacit\u00e9s de surveillance des signaux critiques, de radiogoniom\u00e9trie et d&rsquo;analyse spectrale des forces fran\u00e7aises.<\/p>\n","protected":false},"author":11,"featured_media":17460,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1143],"class_list":["post-17459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA ...<\/title>\n<meta name=\"description\" content=\"La DGA a attribu\u00e9 \u00e0 Thales et Airbus un contrat pour le nouveau syst\u00e8me commun de renseignement tactique des signaux (SIGINT) afin de mettre \u00e0 niveau les...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17459\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA\" \/>\n<meta property=\"og:description\" content=\"La DGA a attribu\u00e9 \u00e0 Thales et Airbus un contrat pour le nouveau syst\u00e8me commun de renseignement tactique des signaux (SIGINT) afin de mettre \u00e0 niveau les capacit\u00e9s de surveillance des signaux critiques, de radiogoniom\u00e9trie et d&#039;analyse spectrale des forces fran\u00e7aises.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17459\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-15T18:33:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/thales_airbus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"291\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Cardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA\",\"datePublished\":\"2021-02-15T18:33:52+00:00\",\"dateModified\":\"2021-02-15T18:33:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/\",\"name\":\"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-02-15T18:33:52+00:00\",\"dateModified\":\"2021-02-15T18:33:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA ...","description":"La DGA a attribu\u00e9 \u00e0 Thales et Airbus un contrat pour le nouveau syst\u00e8me commun de renseignement tactique des signaux (SIGINT) afin de mettre \u00e0 niveau les...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17459\/","og_locale":"fr_FR","og_type":"article","og_title":"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA","og_description":"La DGA a attribu\u00e9 \u00e0 Thales et Airbus un contrat pour le nouveau syst\u00e8me commun de renseignement tactique des signaux (SIGINT) afin de mettre \u00e0 niveau les capacit\u00e9s de surveillance des signaux critiques, de radiogoniom\u00e9trie et d'analyse spectrale des forces fran\u00e7aises.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17459\/","og_site_name":"EENewsEurope","article_published_time":"2021-02-15T18:33:52+00:00","og_image":[{"width":562,"height":291,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/thales_airbus.jpg","type":"image\/jpeg"}],"author":"Daniel Cardon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA","datePublished":"2021-02-15T18:33:52+00:00","dateModified":"2021-02-15T18:33:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/","url":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/","name":"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-02-15T18:33:52+00:00","dateModified":"2021-02-15T18:33:52+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/guerre-electronique-thales-et-airbus-selectionnes-par-la-dga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Guerre \u00e9lectronique: Thales et Airbus s\u00e9lectionn\u00e9s par la DGA"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17459"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=17459"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/17459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/17460"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=17459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=17459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=17459"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=17459"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=17459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}