{"id":159873,"date":"2022-01-04T16:59:11","date_gmt":"2022-01-04T16:59:11","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/plateforme-flexible-dacquisition-de-donnees\/"},"modified":"2022-01-04T16:59:11","modified_gmt":"2022-01-04T16:59:11","slug":"plateforme-flexible-dacquisition-de-donnees","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/plateforme-flexible-dacquisition-de-donnees\/","title":{"rendered":"Plateforme flexible d\u2019acquisition de donn\u00e9es"},"content":{"rendered":"<p>Le FPGA Cyclone V SoC embarqu\u00e9 poss\u00e8de 85&nbsp;000 \u00e9l\u00e9ments logiques et comprend un processeur MPCore Cortex ARM&nbsp;A9 \u00e0 double c\u0153ur pour prendre en charge une large gamme d\u2019applications. La plateforme est particuli\u00e8rement adapt\u00e9e aux applications de pr\u00e9cision sur des march\u00e9s tels que l\u2019instrumentation, les soins de sant\u00e9, l\u2019\u00e9nergie et l\u2019industrie, l\u2019a\u00e9rospatiale, l\u2019automobile et les communications.<\/p>\n<p>La carte supporte des connecteurs FMC et PMOD \u00e0 faible nombre de broches (LPC) pour une extensibilit\u00e9 ais\u00e9e. Ces connecteurs permettent au FPGA de s\u2019interfacer avec des composants analogiques et num\u00e9riques tels que des capteurs, des amplificateurs, des convertisseurs de donn\u00e9es, des actionneurs et d\u2019autres \u00e9l\u00e9ments de la cha\u00eene.<\/p>\n<p>Pour les applications n\u00e9cessitant des mesures pr\u00e9cises, les tests entre le FPGA et les convertisseurs de donn\u00e9es de pr\u00e9cision peuvent \u00eatre effectu\u00e9s \u00e0 l\u2019aide de cartes mezzanine avec des connecteurs FMC LPC. De m\u00eame, l\u2019\u00e9valuation peut \u00eatre r\u00e9alis\u00e9e \u00e0 l\u2019aide de convertisseurs de donn\u00e9es, de capteurs, de composants RF, etc.<\/p>\n<p>La plateforme DataStorm DAQ comprend des mod\u00e8les de d\u00e9monstration et des outils, tels que du code HDL, des pilotes de p\u00e9riph\u00e9riques et des exemples de projets de r\u00e9f\u00e9rence pour un prototypage rapide et un temps de d\u00e9veloppement r\u00e9duit. Plusieurs cartes mezzanine sont prises en charge avec une suite compl\u00e8te d\u2019outils et de d\u00e9monstrations.<\/p>\n<p><a href=\"http:\/\/www.arrow.com\" target=\"notSet\" rel=\"noopener\">www.arrow.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Propos\u00e9e par Arrow Electronics, cette plateforme permet de relever les d\u00e9fis de conception pos\u00e9s par l\u2019augmentation des exigences des syst\u00e8mes en mati\u00e8re de vitesse et de pr\u00e9cision et par les probl\u00e8mes li\u00e9s \u00e0 la synchronisation et \u00e0 l\u2019int\u00e9grit\u00e9 des donn\u00e9es. DataStorm DAQ est une plateforme de d\u00e9veloppement bas\u00e9e sur un Intel Cyclone V SoC, con\u00e7ue pour acc\u00e9l\u00e9rer le prototypage ou le d\u00e9veloppement de validation de concept. <\/p>\n","protected":false},"author":9,"featured_media":159874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-159873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Plateforme flexible d\u2019acquisition de donn\u00e9es ...<\/title>\n<meta name=\"description\" content=\"Propos\u00e9e par Arrow Electronics, cette plateforme permet de relever les d\u00e9fis de conception pos\u00e9s par l\u2019augmentation des exigences des syst\u00e8mes en...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159873\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plateforme flexible d\u2019acquisition de donn\u00e9es\" \/>\n<meta property=\"og:description\" content=\"Propos\u00e9e par Arrow Electronics, cette plateforme permet de relever les d\u00e9fis de conception pos\u00e9s par l\u2019augmentation des exigences des syst\u00e8mes en mati\u00e8re de vitesse et de pr\u00e9cision et par les probl\u00e8mes li\u00e9s \u00e0 la synchronisation et \u00e0 l\u2019int\u00e9grit\u00e9 des donn\u00e9es. DataStorm DAQ est une plateforme de d\u00e9veloppement bas\u00e9e sur un Intel Cyclone V SoC, con\u00e7ue pour acc\u00e9l\u00e9rer le prototypage ou le d\u00e9veloppement de validation de concept.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159873\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-04T16:59:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9954_arrow.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Plateforme flexible d\u2019acquisition de donn\u00e9es\",\"datePublished\":\"2022-01-04T16:59:11+00:00\",\"dateModified\":\"2022-01-04T16:59:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/\",\"name\":\"Plateforme flexible d\u2019acquisition de donn\u00e9es -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-01-04T16:59:11+00:00\",\"dateModified\":\"2022-01-04T16:59:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plateforme flexible d\u2019acquisition de donn\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Plateforme flexible d\u2019acquisition de donn\u00e9es ...","description":"Propos\u00e9e par Arrow Electronics, cette plateforme permet de relever les d\u00e9fis de conception pos\u00e9s par l\u2019augmentation des exigences des syst\u00e8mes en...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159873\/","og_locale":"fr_FR","og_type":"article","og_title":"Plateforme flexible d\u2019acquisition de donn\u00e9es","og_description":"Propos\u00e9e par Arrow Electronics, cette plateforme permet de relever les d\u00e9fis de conception pos\u00e9s par l\u2019augmentation des exigences des syst\u00e8mes en mati\u00e8re de vitesse et de pr\u00e9cision et par les probl\u00e8mes li\u00e9s \u00e0 la synchronisation et \u00e0 l\u2019int\u00e9grit\u00e9 des donn\u00e9es. DataStorm DAQ est une plateforme de d\u00e9veloppement bas\u00e9e sur un Intel Cyclone V SoC, con\u00e7ue pour acc\u00e9l\u00e9rer le prototypage ou le d\u00e9veloppement de validation de concept.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159873\/","og_site_name":"EENewsEurope","article_published_time":"2022-01-04T16:59:11+00:00","og_image":[{"width":1200,"height":937,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9954_arrow.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Plateforme flexible d\u2019acquisition de donn\u00e9es","datePublished":"2022-01-04T16:59:11+00:00","dateModified":"2022-01-04T16:59:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/"},"wordCount":259,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/","url":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/","name":"Plateforme flexible d\u2019acquisition de donn\u00e9es -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-01-04T16:59:11+00:00","dateModified":"2022-01-04T16:59:11+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/plateforme-flexible-dacquisition-de-donnees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Plateforme flexible d\u2019acquisition de donn\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159873"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=159873"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/159874"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=159873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=159873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=159873"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=159873"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=159873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}