{"id":159337,"date":"2022-01-12T15:00:22","date_gmt":"2022-01-12T15:00:22","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/"},"modified":"2022-01-12T15:00:22","modified_gmt":"2022-01-12T15:00:22","slug":"computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/","title":{"rendered":"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration"},"content":{"rendered":"<p>Le plus impressionnant est le fait que les ing\u00e9nieurs peuvent d\u00e9sormais tirer parti de l&rsquo;architecture hybride innovante d&rsquo;Intel en mati\u00e8re de performances. Offrant jusqu&rsquo;\u00e0 14 c\u0153urs\/20 threads sur les BGA et 16 c\u0153urs\/24 threads sur les variants pour PC de bureau (mont\u00e9s sur LGA), les processeurs Intel Core de 12e g\u00e9n\u00e9ration permettent \u00e0 la nouvelle g\u00e9n\u00e9ration d\u2019applications IoT et p\u00e9riph\u00e9riques de faire un bond en avant au niveau multit\u00e2che et \u00e9volutivit\u00e9. Ils b\u00e9n\u00e9ficient de jusqu&rsquo;\u00e0 6 ou 8 c\u0153urs de performance optimis\u00e9s (P-cores) (BGA\/LGA) plus jusqu&rsquo;\u00e0 8 c\u0153urs d&rsquo;efficacit\u00e9 basse consommation (E-cores) et d&rsquo;une prise en charge de la m\u00e9moire DDR5 pour acc\u00e9l\u00e9rer les applications multithread et ex\u00e9cuter plus efficacement les t\u00e2ches d\u2019arri\u00e8re-plan.<\/p>\n<p>En outre, il a \u00e9t\u00e9 estim\u00e9 que les processeurs BGA mobiles avec jusqu&rsquo;\u00e0 96 unit\u00e9s d&rsquo;ex\u00e9cution du GPU int\u00e9gr\u00e9 Intel Iris Xe apportent des am\u00e9liorations extraordinaires allant jusqu&rsquo;\u00e0 129 % en termes de performances graphiques pour une exp\u00e9rience utilisateur immersive et peuvent \u00e9galement traiter des charges de travail parall\u00e9lis\u00e9es, telles que des algorithmes d&rsquo;intelligence artificielle (IA), par rapport aux processeurs Intel Core de 11e g\u00e9n\u00e9ration.<\/p>\n<p>Optimis\u00e9s pour de meilleures performances clients embarqu\u00e9es, les graphiques des modules bas\u00e9s sur le processeur LGA offrent d\u00e9sormais des performances jusqu&rsquo;\u00e0 94 % plus rapides et ses performances d&rsquo;inf\u00e9rence de classification d&rsquo;images ont presque tripl\u00e9 avec un d\u00e9bit jusqu&rsquo;\u00e0 181 % plus \u00e9lev\u00e9. [3] De plus, les modules offrent une bande passante massive permettant de connecter des GPU discrets pour des performances graphiques et d&rsquo;IA maximales bas\u00e9es sur les GPGPU. Par rapport aux versions BGA, ces modules et tous les autres p\u00e9riph\u00e9riques b\u00e9n\u00e9ficient d\u2019un doublement de la vitesse des voies car ils sont dot\u00e9s de la technologie d&rsquo;interface PCIe 5.0 ultra-rapide en plus de la technologie PCIe 4.0 du processeur. En outre, les chipsets de bureau proposent jusqu\u2019\u00e0 8 voies PCIe 3.0 pour une connectivit\u00e9 suppl\u00e9mentaire et les variants mobiles BGA offrent \u00e9galement jusqu&rsquo;\u00e0 16 voies PCIe 4.0 hors processeur et jusqu&rsquo;\u00e0 8 voies PCIe 3.0 hors chipset.<\/p>\n<p>Les march\u00e9s industriels concern\u00e9s par les variants BGA et LGA se trouvent partout o\u00f9 des ordinateurs embarqu\u00e9s et p\u00e9riph\u00e9riques haut de gamme sont d\u00e9ploy\u00e9s. Cela inclut, par exemple, les ordinateurs de p\u00e9riph\u00e9rie et les passerelles IoT int\u00e9grant de multiples machines virtuelles pour les usines intelligentes et l&rsquo;automatisation des processus, l&rsquo;inspection de la qualit\u00e9 et la vision industrielle bas\u00e9es sur l&rsquo;IA, la robotique collaborative en temps r\u00e9el et les v\u00e9hicules logistiques autonomes pour les entrep\u00f4ts et les exp\u00e9ditions. Les applications ext\u00e9rieures typiques comprennent les v\u00e9hicules autonomes et les machines mobiles, la s\u00e9curit\u00e9 vid\u00e9o et les applications de passerelle dans les transports et les villes intelligentes, ainsi que les cloudlets 5G et les p\u00e9riph\u00e9riques n\u00e9cessitant une inspection des paquets prise en charge par l&rsquo;IA.<\/p>\n<p>\u201cTirant parti de l&rsquo;architecture hybride innovante d&rsquo;Intel en mati\u00e8re de performances, avec des performances impressionnantes des P-cores &#8211; en combinaison avec les E-cores basse consommation. Intel Thread Director attribue chaque charge de travail aux c\u0153urs appropri\u00e9s pour des performances optimales. Les processeurs s\u00e9lectionn\u00e9s conviennent \u00e9galement aux applications temps r\u00e9el difficiles avec Intel TCC et TSN. Associ\u00e9s \u00e0 une prise en charge compl\u00e8te de la technologie d&rsquo;hyperviseur de Real-Time Systems, ils constituent la plate-forme id\u00e9ale pour consolider une multitude de charges de travail diff\u00e9rentes sur une seule plate-forme p\u00e9riph\u00e9rique. Comme cela s&rsquo;applique aussi bien aux sc\u00e9narios basse consommation qu&rsquo;aux sc\u00e9narios haute performance, cela permet des conceptions hautement durables avec une faible empreinte \u00e9cologique\u00a0\u00bb, explique Christian Eder, directeur du marketing chez congatec.<\/p>\n<p>Tous ces modules sont livr\u00e9s avec des packs complets de support carte pour tous ces principaux RTOS, y compris le support d&rsquo;hyperviseur de Real-Time Systems ainsi que Linux, Windows et Android.<\/p>\n<p><a href=\"https:\/\/www.congatec.com\/en\/products\/com-hpc\/conga-hpccals\/\" target=\"_blank\" rel=\"noopener\">www.congatec.com\/en\/products\/com-hpc\/conga-hpccals\/<\/a><\/p>\n<p><a href=\"http:\/\/www.congatec.com\/en\/products\/com-hpc\/conga-hpccalp\/\" target=\"_blank\" rel=\"noopener\">www.congatec.com\/en\/products\/com-hpc\/conga-hpccalp\/<\/a><\/p>\n<p><a href=\"http:\/\/www.congatec.com\/en\/products\/com-express-type-6\/conga-tc670\/\" target=\"_blank\" rel=\"noopener\">www.congatec.com\/en\/products\/com-express-type-6\/conga-tc670\/<\/a> &nbsp;<\/p>\n<p class=\"xxstandard1\"><a href=\"http:\/\/www.congatec.com\" target=\"_blank\" rel=\"noopener\">www.congatec.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Congatec pr\u00e9sente les processeurs mobiles et PC de bureau Intel Core de 12\u00e8me g\u00e9n\u00e9ration (anciennement appel\u00e9s Alder Lake) sur 10 nouveaux Computer-on-Modules COM-HPC Client et COM Express. Dot\u00e9s des derniers c\u0153urs haute performance d&rsquo;Intel, les nouveaux modules COM-HPC taille A et C ainsi que les formats COM Express Type 6 offrent des gains de performance et des am\u00e9liorations majeures pour le monde des syst\u00e8mes informatiques embarqu\u00e9s et p\u00e9riph\u00e9riques. <\/p>\n","protected":false},"author":9,"featured_media":159338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-159337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8...<\/title>\n<meta name=\"description\" content=\"Congatec pr\u00e9sente les processeurs mobiles et PC de bureau Intel Core de 12\u00e8me g\u00e9n\u00e9ration (anciennement appel\u00e9s Alder Lake) sur 10 nouveaux...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159337\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration\" \/>\n<meta property=\"og:description\" content=\"Congatec pr\u00e9sente les processeurs mobiles et PC de bureau Intel Core de 12\u00e8me g\u00e9n\u00e9ration (anciennement appel\u00e9s Alder Lake) sur 10 nouveaux Computer-on-Modules COM-HPC Client et COM Express. Dot\u00e9s des derniers c\u0153urs haute performance d&#039;Intel, les nouveaux modules COM-HPC taille A et C ainsi que les formats COM Express Type 6 offrent des gains de performance et des am\u00e9liorations majeures pour le monde des syst\u00e8mes informatiques embarqu\u00e9s et p\u00e9riph\u00e9riques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159337\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T15:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9961_congatec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2126\" \/>\n\t<meta property=\"og:image:height\" content=\"1535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration\",\"datePublished\":\"2022-01-12T15:00:22+00:00\",\"dateModified\":\"2022-01-12T15:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/\"},\"wordCount\":720,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/\",\"name\":\"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-01-12T15:00:22+00:00\",\"dateModified\":\"2022-01-12T15:00:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8...","description":"Congatec pr\u00e9sente les processeurs mobiles et PC de bureau Intel Core de 12\u00e8me g\u00e9n\u00e9ration (anciennement appel\u00e9s Alder Lake) sur 10 nouveaux...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159337\/","og_locale":"fr_FR","og_type":"article","og_title":"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration","og_description":"Congatec pr\u00e9sente les processeurs mobiles et PC de bureau Intel Core de 12\u00e8me g\u00e9n\u00e9ration (anciennement appel\u00e9s Alder Lake) sur 10 nouveaux Computer-on-Modules COM-HPC Client et COM Express. Dot\u00e9s des derniers c\u0153urs haute performance d'Intel, les nouveaux modules COM-HPC taille A et C ainsi que les formats COM Express Type 6 offrent des gains de performance et des am\u00e9liorations majeures pour le monde des syst\u00e8mes informatiques embarqu\u00e9s et p\u00e9riph\u00e9riques.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159337\/","og_site_name":"EENewsEurope","article_published_time":"2022-01-12T15:00:22+00:00","og_image":[{"width":2126,"height":1535,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9961_congatec.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration","datePublished":"2022-01-12T15:00:22+00:00","dateModified":"2022-01-12T15:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/"},"wordCount":720,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/","url":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/","name":"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-01-12T15:00:22+00:00","dateModified":"2022-01-12T15:00:22+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/computer-on-modules-equipes-de-processeurs-intel-core-de-12eme-generation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Computer-on-Modules \u00e9quip\u00e9s de processeurs Intel Core de 12\u00e8me g\u00e9n\u00e9ration"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159337"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=159337"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/159338"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=159337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=159337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=159337"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=159337"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=159337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}