{"id":159329,"date":"2022-01-09T20:19:30","date_gmt":"2022-01-09T20:19:30","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/chargeurs-de-batteries-polyvalents-modeles-nimh\/"},"modified":"2022-01-09T20:19:30","modified_gmt":"2022-01-09T20:19:30","slug":"chargeurs-de-batteries-polyvalents-modeles-nimh","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/","title":{"rendered":"Chargeurs de batteries polyvalents mod\u00e8les NiMH"},"content":{"rendered":"<p>Les fonctions de protection de s\u00fbret\u00e9 comprennent une indication d&rsquo;erreur en cas d\u2019inversion de polarit\u00e9, de court-circuit, de charge de blocs de batteries avec un mauvais nombre d&rsquo;\u00e9l\u00e9ments, ou de fin de minuterie de s\u00e9curit\u00e9.<\/p>\n<p>Gr\u00e2ce au kit d&rsquo;outils Configurable Battery Charger (CBC) dot\u00e9 d&rsquo;une interface PC, les chargeurs peuvent \u00eatre configur\u00e9s via leur c\u00e2ble de sortie avec diff\u00e9rents param\u00e8tres de charge personnalis\u00e9s, notamment dV, dT\/dt, 0&nbsp;dV, minuterie, minuterie de s\u00e9curit\u00e9, seuil de dV, et r\u00e9glage du gradient de temp\u00e9rature. Le CBC est \u00e9galement configurable sur le terrain. D&rsquo;autres sp\u00e9cifications personnalis\u00e9es sont disponibles sur demande, y compris des connecteurs sp\u00e9ciaux, des cordons, un logo imprim\u00e9, bo\u00eetier ou ch\u00e2ssis ouvert, indice IP et certificats.<\/p>\n<p>Les nouveaux chargeurs NiMH sont adapt\u00e9s \u00e0 un large \u00e9ventail d&rsquo;applications, allant du m\u00e9dical \u00e0 l&rsquo;industriel, en passant par le grand public. Cinq versions standard (3&nbsp;\u00e0&nbsp;6, 4&nbsp;\u00e0&nbsp;8, 5&nbsp;\u00e0&nbsp;10, 6&nbsp;\u00e0&nbsp;12, et 10&nbsp;\u00e0&nbsp;20 cellules) sont actuellement disponibles.<\/p>\n<p><a href=\"http:\/\/www.mascot.com\" target=\"_blank\" rel=\"noopener\">www.mascot.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;expert norv\u00e9gien de la conception d\u2019alimentations Mascot \u00e9largit sa gamme de chargeurs polyvalents et performants, Blueline 3743 et 3546, pour y inclure des versions NiMH. Ces deux nouveaux mod\u00e8les sont configurables et disposent d\u2019une logique intelligente pour optimiser les performances de la batterie, notamment une d\u00e9tection robuste de sensibilit\u00e9 -dV, une faible temp\u00e9rature des cellules en fin de charge rapide et une charge d&rsquo;appoint qui garantit que toutes les cellules soient compl\u00e8tement charg\u00e9es et \u00e9quilibr\u00e9es. La puissance maximale est de 15 W pour le chargeur 3743 et de 27 W pour le 3546.<\/p>\n","protected":false},"author":9,"featured_media":159330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-159329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Chargeurs de batteries polyvalents mod\u00e8les NiMH ...<\/title>\n<meta name=\"description\" content=\"L&#039;expert norv\u00e9gien de la conception d\u2019alimentations Mascot \u00e9largit sa gamme de chargeurs polyvalents et performants, Blueline 3743 et 3546, pour y...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159329\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chargeurs de batteries polyvalents mod\u00e8les NiMH\" \/>\n<meta property=\"og:description\" content=\"L&#039;expert norv\u00e9gien de la conception d\u2019alimentations Mascot \u00e9largit sa gamme de chargeurs polyvalents et performants, Blueline 3743 et 3546, pour y inclure des versions NiMH. Ces deux nouveaux mod\u00e8les sont configurables et disposent d\u2019une logique intelligente pour optimiser les performances de la batterie, notamment une d\u00e9tection robuste de sensibilit\u00e9 -dV, une faible temp\u00e9rature des cellules en fin de charge rapide et une charge d&#039;appoint qui garantit que toutes les cellules soient compl\u00e8tement charg\u00e9es et \u00e9quilibr\u00e9es. La puissance maximale est de 15 W pour le chargeur 3743 et de 27 W pour le 3546.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159329\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-09T20:19:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9963_mascot-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Chargeurs de batteries polyvalents mod\u00e8les NiMH\",\"datePublished\":\"2022-01-09T20:19:30+00:00\",\"dateModified\":\"2022-01-09T20:19:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/\"},\"wordCount\":191,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/\",\"name\":\"Chargeurs de batteries polyvalents mod\u00e8les NiMH -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-01-09T20:19:30+00:00\",\"dateModified\":\"2022-01-09T20:19:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chargeurs de batteries polyvalents mod\u00e8les NiMH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Chargeurs de batteries polyvalents mod\u00e8les NiMH ...","description":"L'expert norv\u00e9gien de la conception d\u2019alimentations Mascot \u00e9largit sa gamme de chargeurs polyvalents et performants, Blueline 3743 et 3546, pour y...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159329\/","og_locale":"fr_FR","og_type":"article","og_title":"Chargeurs de batteries polyvalents mod\u00e8les NiMH","og_description":"L'expert norv\u00e9gien de la conception d\u2019alimentations Mascot \u00e9largit sa gamme de chargeurs polyvalents et performants, Blueline 3743 et 3546, pour y inclure des versions NiMH. Ces deux nouveaux mod\u00e8les sont configurables et disposent d\u2019une logique intelligente pour optimiser les performances de la batterie, notamment une d\u00e9tection robuste de sensibilit\u00e9 -dV, une faible temp\u00e9rature des cellules en fin de charge rapide et une charge d'appoint qui garantit que toutes les cellules soient compl\u00e8tement charg\u00e9es et \u00e9quilibr\u00e9es. La puissance maximale est de 15 W pour le chargeur 3743 et de 27 W pour le 3546.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159329\/","og_site_name":"EENewsEurope","article_published_time":"2022-01-09T20:19:30+00:00","og_image":[{"width":2560,"height":1898,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9963_mascot-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Chargeurs de batteries polyvalents mod\u00e8les NiMH","datePublished":"2022-01-09T20:19:30+00:00","dateModified":"2022-01-09T20:19:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/"},"wordCount":191,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/","url":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/","name":"Chargeurs de batteries polyvalents mod\u00e8les NiMH -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-01-09T20:19:30+00:00","dateModified":"2022-01-09T20:19:30+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/chargeurs-de-batteries-polyvalents-modeles-nimh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Chargeurs de batteries polyvalents mod\u00e8les NiMH"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159329"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=159329"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/159329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/159330"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=159329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=159329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=159329"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=159329"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=159329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}