{"id":158323,"date":"2022-01-28T08:50:57","date_gmt":"2022-01-28T08:50:57","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/"},"modified":"2022-01-28T08:50:57","modified_gmt":"2022-01-28T08:50:57","slug":"antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/","title":{"rendered":"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz"},"content":{"rendered":"<p>Le spectre LTE 450 est relativement nouveau, avec 65 d\u00e9ploiements en Am\u00e9rique du Nord, en Am\u00e9rique du Sud, en Europe, en Afrique et en Asie, et le LTE 450 est disponible dans 25 d&rsquo;entre eux. On s&rsquo;attend \u00e0 ce que cela augmente, \u00e0 mesure que le spectre est attribu\u00e9 \u00e0 davantage de r\u00e9gions.<br \/>\nLe LTE 450 MHz est utilis\u00e9 par les fournisseurs de r\u00e9seaux priv\u00e9s dans les secteurs des services publics, de la s\u00e9curit\u00e9 publique et des transports. Ils l&rsquo;utilisent pour le trafic M2M, les r\u00e9seaux intelligents, les villes intelligentes, la recharge des v\u00e9hicules \u00e9lectriques et les r\u00e9seaux ruraux \u00e0 large bande. L&rsquo;Europe est en t\u00eate du d\u00e9ploiement avec les services publics utilisant le LTE 450 MHz pour les communications critiques et l&rsquo;infrastructure de lecture automatis\u00e9e des compteurs reliant les zones \u00e9loign\u00e9es.<br \/>\nLa bande 450 MHz se compare favorablement \u00e0 900 MHz pour ces applications, car \u00e0 900 MHz, il faut quatre fois plus de stations de base pour couvrir la m\u00eame zone g\u00e9ographique. L&rsquo;antenne Atta est id\u00e9ale pour assurer la connectivit\u00e9 des appareils sur ces r\u00e9seaux, en particulier les compteurs et les t\u00e9l\u00e9phones intelligents robustes, et les appareils mobiles portables utilisant des modules Cat 4.<\/p>\n<p>Selon Michael Castle, Product Marketing Manager chez Antenova, \u00ab\u00a0La fr\u00e9quence de 450 MHz permet une bonne propagation de l&rsquo;antenne et une couverture plus fiable ainsi qu&rsquo;une large couverture pour chaque station de base avec des co\u00fbts d&rsquo;infrastructure r\u00e9duits, et une antenne flexible offre aux concepteurs un certain nombre d&rsquo;options pour la conception du produit. L&rsquo;antenne peut \u00eatre pli\u00e9, incurv\u00e9 ou plac\u00e9 \u00e0 plat dans un design, ou cach\u00e9 \u00e0 l&rsquo;int\u00e9rieur du bo\u00eetier d&rsquo;un petit appareil. L&rsquo;antenne Atta est disponible en \u00e9chantillons ou en quantit\u00e9s de production, c&rsquo;est donc un bon choix pour les OEM et les projets de conception sans fil sp\u00e9cialis\u00e9s.<br \/>\n<a href=\"http:\/\/www.antenova.com\/atta\/\" target=\"_blank\" rel=\"noopener\">www.antenova.com\/atta\/<\/a><\/p>\n<p><u>\u00c0 propos d&rsquo;Ant\u00e9nova<\/u><br \/>\nAntenova Ltd est l&rsquo;un des principaux d\u00e9veloppeurs et fournisseurs d&rsquo;antennes int\u00e9gr\u00e9es hautes performances et de solutions RF pour la communication sans fil, l&rsquo;\u00e9lectronique grand public et les appareils M2M sans fil. La large gamme d&rsquo;antennes standard et de modules RF d&rsquo;Antenova est parfaitement adapt\u00e9e pour GSM, CDMA, 3G, 4G, LTE, 5G-NR, 5G, NB-IoT, GPS, GNSS, Wi-Fi, Bluetooth, ZigBee, LP-WAN, LoRa , Sigfox, Weightless-P et ISM, pour les applications M2M et IoT. Antenova fournit des conseils de conception et une assistance technique complets, y compris des services de conception, d&rsquo;ing\u00e9nierie, d&rsquo;int\u00e9gration et de test d&rsquo;antennes personnalis\u00e9es pour garantir les meilleures solutions d&rsquo;antennes les plus performantes possibles pour les appareils des clients.<br \/>\n<a href=\"http:\/\/www.antenova.com\" target=\"_blank\" rel=\"noopener\">www.antenova.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antenova Ltd, le fabricant britannique d&rsquo;antennes et de modules d&rsquo;antenne RF pour le M2M et l&rsquo;IoT, a d\u00e9voil\u00e9 sa derni\u00e8re antenne, Atta, num\u00e9ro de pi\u00e8ce SRFI079, pour les d\u00e9ploiements LTE et sans fil intelligents dans les bandes 410 MHz et 450 MHz. L&rsquo;antenne Atta est une forme de circuit imprim\u00e9 flexible (FPC) et mesure 101,0 x 20,0 x 0,15 mm. Il est fourni avec un contre-connecteur I-PEX pour une int\u00e9gration directe \u00e0 une carte de circuit imprim\u00e9, et une pastille autocollante pour le fixer facilement en position. Il est donc facile \u00e0 int\u00e9grer dans un design.<\/p>\n","protected":false},"author":9,"featured_media":158324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-158323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-products","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE ...<\/title>\n<meta name=\"description\" content=\"Antenova Ltd, le fabricant britannique d&#039;antennes et de modules d&#039;antenne RF pour le M2M et l&#039;IoT, a d\u00e9voil\u00e9 sa derni\u00e8re antenne, Atta, num\u00e9ro de pi\u00e8ce...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158323\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz\" \/>\n<meta property=\"og:description\" content=\"Antenova Ltd, le fabricant britannique d&#039;antennes et de modules d&#039;antenne RF pour le M2M et l&#039;IoT, a d\u00e9voil\u00e9 sa derni\u00e8re antenne, Atta, num\u00e9ro de pi\u00e8ce SRFI079, pour les d\u00e9ploiements LTE et sans fil intelligents dans les bandes 410 MHz et 450 MHz. L&#039;antenne Atta est une forme de circuit imprim\u00e9 flexible (FPC) et mesure 101,0 x 20,0 x 0,15 mm. Il est fourni avec un contre-connecteur I-PEX pour une int\u00e9gration directe \u00e0 une carte de circuit imprim\u00e9, et une pastille autocollante pour le fixer facilement en position. Il est donc facile \u00e0 int\u00e9grer dans un design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158323\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-28T08:50:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9986_atta_antenna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1043\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz\",\"datePublished\":\"2022-01-28T08:50:57+00:00\",\"dateModified\":\"2022-01-28T08:50:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"New Products\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/\",\"name\":\"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-01-28T08:50:57+00:00\",\"dateModified\":\"2022-01-28T08:50:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE ...","description":"Antenova Ltd, le fabricant britannique d'antennes et de modules d'antenne RF pour le M2M et l'IoT, a d\u00e9voil\u00e9 sa derni\u00e8re antenne, Atta, num\u00e9ro de pi\u00e8ce...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158323\/","og_locale":"fr_FR","og_type":"article","og_title":"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz","og_description":"Antenova Ltd, le fabricant britannique d'antennes et de modules d'antenne RF pour le M2M et l'IoT, a d\u00e9voil\u00e9 sa derni\u00e8re antenne, Atta, num\u00e9ro de pi\u00e8ce SRFI079, pour les d\u00e9ploiements LTE et sans fil intelligents dans les bandes 410 MHz et 450 MHz. L'antenne Atta est une forme de circuit imprim\u00e9 flexible (FPC) et mesure 101,0 x 20,0 x 0,15 mm. Il est fourni avec un contre-connecteur I-PEX pour une int\u00e9gration directe \u00e0 une carte de circuit imprim\u00e9, et une pastille autocollante pour le fixer facilement en position. Il est donc facile \u00e0 int\u00e9grer dans un design.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158323\/","og_site_name":"EENewsEurope","article_published_time":"2022-01-28T08:50:57+00:00","og_image":[{"width":1043,"height":870,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9986_atta_antenna.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz","datePublished":"2022-01-28T08:50:57+00:00","dateModified":"2022-01-28T08:50:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/"},"wordCount":472,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["New Products"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/","url":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/","name":"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-01-28T08:50:57+00:00","dateModified":"2022-01-28T08:50:57+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/antenne-embarquee-pour-appareils-distants-dans-les-bandes-lte-410-450-mhz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Antenne embarqu\u00e9e pour appareils distants dans les bandes LTE 410\/450 MHz"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158323"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=158323"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/158324"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=158323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=158323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=158323"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=158323"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=158323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}