{"id":158311,"date":"2022-01-25T18:00:35","date_gmt":"2022-01-25T18:00:35","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/"},"modified":"2022-01-25T18:00:35","modified_gmt":"2022-01-25T18:00:35","slug":"modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/","title":{"rendered":"Modules de chargeur sans fil pour appareils fins et compacts"},"content":{"rendered":"<p>Les alimentations sans fil sont de plus en plus adopt\u00e9es dans les smartphones, les montres intelligentes et autres appareils compacts. En utilisant la technologie d\u2019alimentation sans fil, les appareils peuvent am\u00e9liorer la r\u00e9sistance \u00e0 l\u2019eau et \u00e0 la poussi\u00e8re en \u00e9liminant le besoin de contacts avec un terminal. Cependant, les normes existantes de basse fr\u00e9quence pour la transmission de puissance, associ\u00e9es \u00e0 des conceptions d\u2019antennes restrictives, limitent le degr\u00e9 de miniaturisation susceptible d\u2019\u00eatre atteint. Ces facteurs limitatifs acc\u00e9l\u00e8rent la demande de normes et de m\u00e9thodes pouvant \u00eatre universellement adopt\u00e9es dans des appareils compacts. De plus, l\u2019efficacit\u00e9 de la transmission de puissance peut varier en fonction de la forme, de la taille et de la distance de l\u2019antenne. Par cons\u00e9quent, il est souvent n\u00e9cessaire de r\u00e9p\u00e9ter les \u00e9tapes de prototypage, d\u2019ajustement et d\u2019\u00e9valuation sur le syst\u00e8me, ce qui repr\u00e9sente une lourde charge de d\u00e9veloppement pour la conception et la disposition des antennes.<\/p>\n<p>Pour y r\u00e9pondre, ROHM a d\u00e9velopp\u00e9 des modules de charge sans fil de 13,56 MHz permettant aux utilisateurs d\u2019ajouter facilement des fonctionnalit\u00e9s de puissance \u00e0 des appareils fins et compacts. Mesurant seulement 20 mm\u00b2 \u00e0 30 mm\u00b2 chacun, le BP3621 (\u00e9metteur) et le BP3622 (r\u00e9cepteur) incorporent une disposition d\u2019antenne optimis\u00e9e (en bobine). Cela permet la configuration d\u2019un syst\u00e8me de charge sans fil compact utilisant la bande de fr\u00e9quences des 13,56 MHz pour fournir jusqu\u2019\u00e0 200 mW. La structure d\u2019arri\u00e8re de carte enti\u00e8rement plate facilite le montage dans des appareils minces et compacts, ce qui contribue \u00e0 une plus grande flexibilit\u00e9 dans la conception du ch\u00e2ssis, contrairement aux solutions conventionnelles. De plus, l\u2019utilisation des modules d\u2019\u00e9metteur et de r\u00e9cepteur en tant que bin\u00f4mes peut r\u00e9duire consid\u00e9rablement la charge de d\u00e9veloppement pour les \u00e9tapes de prototypage, d\u2019ajustement, d\u2019\u00e9valuation et d\u2019autres processus n\u00e9cessaires pour obtenir une charge sans fil \u00e0 haute efficacit\u00e9. Dans le m\u00eame temps, l\u2019antenne int\u00e9gr\u00e9e prend en charge la communication bidirectionnelle de donn\u00e9es et le fonctionnement de l\u2019\u00e9tiquette type 3 du forum NFC, \u00e9largissant ainsi l\u2019applicabilit\u00e9.<\/p>\n<p><a href=\"http:\/\/www.rohm.com\" target=\"notSet\" rel=\"noopener\">www.rohm.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROHM a d\u00e9velopp\u00e9 des modules de chargeur sans fil compacts avec une carte d\u2019antenne int\u00e9gr\u00e9e : le BP3621 (\u00e9metteur) et le BP3622 (r\u00e9cepteur). Les nouveaux modules permettent d\u2019ajouter une fonctionnalit\u00e9 d\u2019alimentation sans fil \u00e0 de petits appareils tels que des \u00e9tiquettes\/cartes intelligentes ou des p\u00e9riph\u00e9riques PC<\/p>\n","protected":false},"author":9,"featured_media":158312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-158311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-products","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Modules de chargeur sans fil pour appareils fins et compacts ...<\/title>\n<meta name=\"description\" content=\"ROHM a d\u00e9velopp\u00e9 des modules de chargeur sans fil compacts avec une carte d\u2019antenne int\u00e9gr\u00e9e : le BP3621 (\u00e9metteur) et le BP3622 (r\u00e9cepteur). Les...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158311\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modules de chargeur sans fil pour appareils fins et compacts\" \/>\n<meta property=\"og:description\" content=\"ROHM a d\u00e9velopp\u00e9 des modules de chargeur sans fil compacts avec une carte d\u2019antenne int\u00e9gr\u00e9e : le BP3621 (\u00e9metteur) et le BP3622 (r\u00e9cepteur). Les nouveaux modules permettent d\u2019ajouter une fonctionnalit\u00e9 d\u2019alimentation sans fil \u00e0 de petits appareils tels que des \u00e9tiquettes\/cartes intelligentes ou des p\u00e9riph\u00e9riques PC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158311\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T18:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9989_rohm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2126\" \/>\n\t<meta property=\"og:image:height\" content=\"1535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Modules de chargeur sans fil pour appareils fins et compacts\",\"datePublished\":\"2022-01-25T18:00:35+00:00\",\"dateModified\":\"2022-01-25T18:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"New Products\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/\",\"name\":\"Modules de chargeur sans fil pour appareils fins et compacts -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2022-01-25T18:00:35+00:00\",\"dateModified\":\"2022-01-25T18:00:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modules de chargeur sans fil pour appareils fins et compacts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Modules de chargeur sans fil pour appareils fins et compacts ...","description":"ROHM a d\u00e9velopp\u00e9 des modules de chargeur sans fil compacts avec une carte d\u2019antenne int\u00e9gr\u00e9e : le BP3621 (\u00e9metteur) et le BP3622 (r\u00e9cepteur). Les...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158311\/","og_locale":"fr_FR","og_type":"article","og_title":"Modules de chargeur sans fil pour appareils fins et compacts","og_description":"ROHM a d\u00e9velopp\u00e9 des modules de chargeur sans fil compacts avec une carte d\u2019antenne int\u00e9gr\u00e9e : le BP3621 (\u00e9metteur) et le BP3622 (r\u00e9cepteur). Les nouveaux modules permettent d\u2019ajouter une fonctionnalit\u00e9 d\u2019alimentation sans fil \u00e0 de petits appareils tels que des \u00e9tiquettes\/cartes intelligentes ou des p\u00e9riph\u00e9riques PC","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158311\/","og_site_name":"EENewsEurope","article_published_time":"2022-01-25T18:00:35+00:00","og_image":[{"width":2126,"height":1535,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9989_rohm.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Modules de chargeur sans fil pour appareils fins et compacts","datePublished":"2022-01-25T18:00:35+00:00","dateModified":"2022-01-25T18:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/"},"wordCount":384,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["New Products"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/","url":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/","name":"Modules de chargeur sans fil pour appareils fins et compacts -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2022-01-25T18:00:35+00:00","dateModified":"2022-01-25T18:00:35+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/modules-de-chargeur-sans-fil-pour-appareils-fins-et-compacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Modules de chargeur sans fil pour appareils fins et compacts"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158311"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=158311"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/158311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/158312"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=158311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=158311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=158311"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=158311"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=158311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}