{"id":157585,"date":"2021-12-09T17:15:33","date_gmt":"2021-12-09T17:15:33","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/"},"modified":"2021-12-09T17:15:33","modified_gmt":"2021-12-09T17:15:33","slug":"resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/","title":{"rendered":"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W"},"content":{"rendered":"<p>Ces derni\u00e8res ann\u00e9es, l\u2019accent a \u00e9t\u00e9 mis sur les \u00e9conomies d\u2019\u00e9nergie dans les domaines industriels et grand public, avec des efforts d\u00e9ploy\u00e9s pour r\u00e9duire la consommation de courant pendant le fonctionnement de l\u2019entra\u00eenement en utilisant des onduleurs de moteur. Dans le m\u00eame temps, les circuits de protection gagnent en importance dans ces domaines \u00e0 mesure que les applications voient leur puissance s\u2019accro\u00eetre.<br \/>\nROHM a travaill\u00e9 \u00e0 \u00e9largir sa gamme consid\u00e9rable, le plus r\u00e9cemment avec la s\u00e9rie GMR320 de r\u00e9sistances de shunt \u00e0 plaque m\u00e9tallique, lanc\u00e9e en f\u00e9vrier 2021. Les appareils disposent d\u2019une puissance nominale garantie plus \u00e9lev\u00e9e allant jusqu\u2019\u00e0 10 W. Depuis avril 2018, ROHM produit la s\u00e9rie LTR50 de r\u00e9sistances de shunt \u00e0 couche \u00e9paisse \u00e0 faible valeur ohmique de 2 W. Avec ces derniers produits, ROHM a \u00e9tendu sa gamme de r\u00e9sistances de shunt \u00e0 couche \u00e9paisse pour prendre en charge une plage de puissance encore plus haute.<br \/>\nLa s\u00e9rie LTR100L r\u00e9alise la puissance nominale la plus \u00e9lev\u00e9e de 4 W dans le format 3264 (3,2 mm \u00d7 6,4 mm) \/ 1225 (0,12 pouce \u00d7 0,25 pouce) en r\u00e9visant les mat\u00e9riaux des r\u00e9sistances et en appliquant un d\u00e9classement de la temp\u00e9rature aux bornes. Cela les rend id\u00e9ales pour la d\u00e9tection de courant dans les circuits de contr\u00f4le moteur et de protection contre les surintensit\u00e9s pour les applications industrielles et grand public, qui progressent vers une puissance plus \u00e9lev\u00e9e. De plus, l\u2019optimisation de la structure de l\u2019\u00e9l\u00e9ment offre les meilleures caract\u00e9ristiques TCR (coefficient de temp\u00e9rature de r\u00e9sistance) parmi les r\u00e9sistances de shunt \u00e0 couche \u00e9paisse. En cons\u00e9quence, elles ne sont pas facilement affect\u00e9es par la temp\u00e9rature, ce qui permet une d\u00e9tection de courant de haute pr\u00e9cision et de haute fiabilit\u00e9.<\/p>\n<p><u>Outils r\u00e9duisant consid\u00e9rablement la charge de conception<\/u><br \/>\nEn novembre 2021, ROHM a lanc\u00e9 sur son site Web un environnement de simulation bas\u00e9 sur le Web permettant une simulation thermique des r\u00e9sistances de shunt en combinaison avec des appareils d\u2019alimentation et des circuits int\u00e9gr\u00e9s (en commen\u00e7ant avec la s\u00e9rie PSR). Ces simulations permettent de simuler \u00e0 l\u2019avance la conception thermique (un probl\u00e8me lors de la conception de l\u2019application), ce qui r\u00e9duit la charge de conception. ROHM propose \u00e9galement des solutions de d\u00e9tection de courant utilisant des circuits int\u00e9gr\u00e9s ainsi que des composants discrets qui contribuent \u00e0 une plus grande efficacit\u00e9 et \u00e0 la miniaturisation des circuits. \u00c0 titre d\u2019exemple, pour les circuits d\u2019entra\u00eenement moteur qui n\u00e9cessitent une d\u00e9tection de courant pour la protection contre les surintensit\u00e9s et leur contr\u00f4le, l\u2019adoption des amplificateurs op\u00e9rationnels \u00e0 faible bruit de premier ordre de ROHM ainsi que des r\u00e9sistances de shunt permettent d\u2019atteindre une d\u00e9tection de courant de haute pr\u00e9cision.<\/p>\n<p><u>Simulateur en ligne de ROHM \u00ab Simulateur de solutions ROHM \u00bb<\/u><br \/>\nIl suffit de cliquer sur l\u2019URL ci-dessous pour acc\u00e9der au site Web d\u00e9di\u00e9 et de s\u2019inscrire en tant qu\u2019utilisateur pour commencer \u00e0 utiliser le simulateur de solutions ROHM. Les documents justificatifs requis pour l\u2019utilisation sont \u00e9galement disponibles.<\/p>\n<p><a href=\"http:\/\/www.rohm.com\/solution-simulator\" target=\"_blank\" rel=\"noopener\">www.rohm.com\/solution-simulator<\/a><\/p>\n<p><a href=\"http:\/\/www.rohm.com\" target=\"notSet\" rel=\"noopener\">www.rohm.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROHM a d\u00e9velopp\u00e9 la s\u00e9rie LTR100L, des r\u00e9sistances de shunt \u00e0 couche \u00e9paisse optimis\u00e9es pour les applications industrielles et grand public. Souvent utilis\u00e9es pour d\u00e9tecter le courant dans les circuits de protection de batterie et d\u2019entra\u00eenement du moteur, les r\u00e9sistances de shunt n\u00e9cessitent une plus grande pr\u00e9cision pour am\u00e9liorer la fiabilit\u00e9 et assurer un fonctionnement \u00e0 haute efficacit\u00e9.<\/p>\n","protected":false},"author":9,"featured_media":157586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-157585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nom...<\/title>\n<meta name=\"description\" content=\"ROHM a d\u00e9velopp\u00e9 la s\u00e9rie LTR100L, des r\u00e9sistances de shunt \u00e0 couche \u00e9paisse optimis\u00e9es pour les applications industrielles et grand public. Souvent...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157585\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W\" \/>\n<meta property=\"og:description\" content=\"ROHM a d\u00e9velopp\u00e9 la s\u00e9rie LTR100L, des r\u00e9sistances de shunt \u00e0 couche \u00e9paisse optimis\u00e9es pour les applications industrielles et grand public. Souvent utilis\u00e9es pour d\u00e9tecter le courant dans les circuits de protection de batterie et d\u2019entra\u00eenement du moteur, les r\u00e9sistances de shunt n\u00e9cessitent une plus grande pr\u00e9cision pour am\u00e9liorer la fiabilit\u00e9 et assurer un fonctionnement \u00e0 haute efficacit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157585\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-09T17:15:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9916_rohm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2126\" \/>\n\t<meta property=\"og:image:height\" content=\"1535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W\",\"datePublished\":\"2021-12-09T17:15:33+00:00\",\"dateModified\":\"2021-12-09T17:15:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/\"},\"wordCount\":557,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/\",\"url\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/\",\"name\":\"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-12-09T17:15:33+00:00\",\"dateModified\":\"2021-12-09T17:15:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nom...","description":"ROHM a d\u00e9velopp\u00e9 la s\u00e9rie LTR100L, des r\u00e9sistances de shunt \u00e0 couche \u00e9paisse optimis\u00e9es pour les applications industrielles et grand public. Souvent...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157585\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W","og_description":"ROHM a d\u00e9velopp\u00e9 la s\u00e9rie LTR100L, des r\u00e9sistances de shunt \u00e0 couche \u00e9paisse optimis\u00e9es pour les applications industrielles et grand public. Souvent utilis\u00e9es pour d\u00e9tecter le courant dans les circuits de protection de batterie et d\u2019entra\u00eenement du moteur, les r\u00e9sistances de shunt n\u00e9cessitent une plus grande pr\u00e9cision pour am\u00e9liorer la fiabilit\u00e9 et assurer un fonctionnement \u00e0 haute efficacit\u00e9.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157585\/","og_site_name":"EENewsEurope","article_published_time":"2021-12-09T17:15:33+00:00","og_image":[{"width":2126,"height":1535,"url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9916_rohm.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/#article","isPartOf":{"@id":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W","datePublished":"2021-12-09T17:15:33+00:00","dateModified":"2021-12-09T17:15:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/"},"wordCount":557,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/","url":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/","name":"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-12-09T17:15:33+00:00","dateModified":"2021-12-09T17:15:33+00:00","breadcrumb":{"@id":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecinews.fr\/fr\/resistances-de-shunt-a-couche-epaisse-avec-une-puissance-nominale-de-4-w\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sistances de shunt \u00e0 couche \u00e9paisse avec une puissance nominale de 4 W"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157585"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=157585"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/157586"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=157585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=157585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=157585"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=157585"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=157585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}