{"id":157053,"date":"2021-12-12T17:21:52","date_gmt":"2021-12-12T17:21:52","guid":{"rendered":"https:\/\/eenewseurope.artwhere.co\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/"},"modified":"2021-12-12T17:21:52","modified_gmt":"2021-12-12T17:21:52","slug":"mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/","title":{"rendered":"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l&#8217;embarqu\u00e9"},"content":{"rendered":"<p>Neb Matic, Pr\u00e9sident Ex\u00e9cutif de MIKROE d\u00e9clare&nbsp;: \u00ab&nbsp;Pour les concepteurs qui sont s\u00fbrs de vouloir s&rsquo;engager dans une certaine voie au niveau mat\u00e9riel et de s&rsquo;y tenir pendant un certain temps, il peut \u00eatre pr\u00e9f\u00e9rable d&rsquo;approvisionner des <a href=\"https:\/\/www.mikroe.com\/development-boards\/8th-generation\" target=\"_blank\" rel=\"noopener\">cartes de d\u00e9veloppement Fusion<\/a>, des cartes MCU <a href=\"https:\/\/www.mikroe.com\/sibrain\" target=\"_blank\" rel=\"noopener\">SiBRAIN<\/a> et des cartes p\u00e9riph\u00e9riques <a href=\"https:\/\/www.mikroe.com\/click-boards\" target=\"_blank\" rel=\"noopener\">Click<\/a>, pour un total d\u2019environ 400&nbsp;dollars, ce qui leur permettra toujours de profiter d\u2019une grande souplesse de conception et d&rsquo;une mise sur le march\u00e9 rapide. Mais pour ceux qui souhaitent \u00e9valuer plusieurs approches mat\u00e9rielles diff\u00e9rentes, ou qui ont besoin d\u2019une dizaine de jours de d\u00e9veloppement, ils peuvent r\u00e9server du temps sur l&rsquo;une des 74&nbsp;cartes de d\u00e9veloppement des stations Planet Debug pour seulement 4&nbsp;dollars par jour. Nous la configurerons pour eux avec la combinaison MCU\/p\u00e9riph\u00e9rique\/affichage qu&rsquo;ils souhaitent \u00e9valuer, afin de pouvoir entreprendre leur d\u00e9veloppement d\u00e8s le lendemain. La beaut\u00e9 de la chose est qu\u2019avec NECTO, vous pouvez voir des images de v\u00e9ritables cartes en temps r\u00e9el, il ne s&rsquo;agit pas d&rsquo;une simulation.&nbsp;\u00bb Le service \u00ab&nbsp;hardware-as-a-service&nbsp;\u00bb Planet Debug fonctionne gr\u00e2ce \u00e0 la technologie innovante <a href=\"https:\/\/www.mikroe.com\/debuggers\/codegrip\" target=\"_blank\" rel=\"noopener\">CODEGRIP<\/a> de MIKROE, le premier dispositif au monde qui permet de programmer et de d\u00e9boguer en WiFi.<\/p>\n<p>Gr\u00e2ce \u00e0 Planet Debug, les utilisateurs gagnent du temps et de l&rsquo;argent. Ils peuvent aussi \u00ab&nbsp;essayer avant d&rsquo;acheter&nbsp;\u00bb ou changer de p\u00e9riph\u00e9rique, d&rsquo;\u00e9cran ou m\u00eame d&rsquo;unit\u00e9 centrale, sans avoir \u00e0 approvisionner de mat\u00e9riel, ni apprendre un nouveau logiciel, ni \u00e9crire un nouveau code. Planet Debug est id\u00e9al pour les \u00e9tudiants et les professionnels. Dans un environnement acad\u00e9mique, les ressources peuvent \u00eatre partag\u00e9es et aucune configuration n&rsquo;est n\u00e9cessaire pour mettre en place un syst\u00e8me. Pour un concepteur, le temps est la chose la plus pr\u00e9cieuse, et Planet Debug lui permet d&rsquo;\u00eatre op\u00e9rationnel tr\u00e8s rapidement, et de r\u00e9pondre aux besoins changeants du marketing produit. De m\u00eame, les p\u00e9nuries de puces n&rsquo;affectent pas le temps de d\u00e9veloppement.<\/p>\n<p>Actuellement, il existe des installations Planet Debug chez MIKROE, \u00e0 l&rsquo;universit\u00e9 voisine de NoviSad, aux \u00c9tats-Unis (dans le Minnesota) et au Mexique. Matic pr\u00e9voit de s\u2019installer en Asie dans un avenir proche, mais toutes les installations peuvent \u00eatre r\u00e9serv\u00e9es par n&rsquo;importe qui, partout dans le monde. Il conclut&nbsp;: \u00ab&nbsp;Hardware-as-a-service est l&rsquo;avenir de la conception.&nbsp; C\u2019est encore difficile \u00e0 appr\u00e9hender car le puzzle comporte de nombreuses pi\u00e8ces&nbsp;: les cartes p\u00e9riph\u00e9riques Click et les cartes MCU SiBRAIN bas\u00e9es sur des prises standard, ainsi que les cartes de d\u00e9veloppement Fusion, CODEGRIP et NECTO. Mais au bout du compte, nous avons toujours eu l\u2019id\u00e9e de les combiner dans une plateforme comme Planet Debug. Cela va r\u00e9volutionner la conception d\u2019embarqu\u00e9.&nbsp;\u00bb<\/p>\n<p><a href=\"http:\/\/www.mikroe.com\" target=\"_blank\" rel=\"noopener\">www.mikroe.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour permettre aux concepteurs de d\u00e9velopper et de d\u00e9boguer des syst\u00e8mes embarqu\u00e9s \u00e0 distance, sans investir dans du mat\u00e9riel, MikroElektronika propose Planet Debug une plateforme \u00ab hardware-as-a-service \u00bb (mat\u00e9riel sous forme de service). Pour seulement 4 dollars par jour, les concepteurs peuvent r\u00e9server du temps sur une station Planet Debug distante configur\u00e9e selon leurs besoins, et d\u00e9velopper et d\u00e9boguer \u00e0 distance le code de leurs propres applications gr\u00e2ce \u00e0 l\u2019IDE (Integrated Development Environment) NECTO Studio de MIKROE, sans avoir \u00e0 sourcer du mat\u00e9riel, \u00e0 attendre qu&rsquo;il soit livr\u00e9 et \u00e0 le brancher. <\/p>\n","protected":false},"author":9,"featured_media":157054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-157053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service ...<\/title>\n<meta name=\"description\" content=\"Pour permettre aux concepteurs de d\u00e9velopper et de d\u00e9boguer des syst\u00e8mes embarqu\u00e9s \u00e0 distance, sans investir dans du mat\u00e9riel, MikroElektronika propose...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157053\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l&#039;embarqu\u00e9\" \/>\n<meta property=\"og:description\" content=\"Pour permettre aux concepteurs de d\u00e9velopper et de d\u00e9boguer des syst\u00e8mes embarqu\u00e9s \u00e0 distance, sans investir dans du mat\u00e9riel, MikroElektronika propose Planet Debug une plateforme \u00ab hardware-as-a-service \u00bb (mat\u00e9riel sous forme de service). Pour seulement 4 dollars par jour, les concepteurs peuvent r\u00e9server du temps sur une station Planet Debug distante configur\u00e9e selon leurs besoins, et d\u00e9velopper et d\u00e9boguer \u00e0 distance le code de leurs propres applications gr\u00e2ce \u00e0 l\u2019IDE (Integrated Development Environment) NECTO Studio de MIKROE, sans avoir \u00e0 sourcer du mat\u00e9riel, \u00e0 attendre qu&#039;il soit livr\u00e9 et \u00e0 le brancher.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157053\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-12T17:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9922_mikroe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l&#8217;embarqu\u00e9\",\"datePublished\":\"2021-12-12T17:21:52+00:00\",\"dateModified\":\"2021-12-12T17:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/\"},\"wordCount\":521,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/\",\"name\":\"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l'embarqu\u00e9 -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-12-12T17:21:52+00:00\",\"dateModified\":\"2021-12-12T17:21:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l&#8217;embarqu\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service ...","description":"Pour permettre aux concepteurs de d\u00e9velopper et de d\u00e9boguer des syst\u00e8mes embarqu\u00e9s \u00e0 distance, sans investir dans du mat\u00e9riel, MikroElektronika propose...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157053\/","og_locale":"fr_FR","og_type":"article","og_title":"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l'embarqu\u00e9","og_description":"Pour permettre aux concepteurs de d\u00e9velopper et de d\u00e9boguer des syst\u00e8mes embarqu\u00e9s \u00e0 distance, sans investir dans du mat\u00e9riel, MikroElektronika propose Planet Debug une plateforme \u00ab hardware-as-a-service \u00bb (mat\u00e9riel sous forme de service). Pour seulement 4 dollars par jour, les concepteurs peuvent r\u00e9server du temps sur une station Planet Debug distante configur\u00e9e selon leurs besoins, et d\u00e9velopper et d\u00e9boguer \u00e0 distance le code de leurs propres applications gr\u00e2ce \u00e0 l\u2019IDE (Integrated Development Environment) NECTO Studio de MIKROE, sans avoir \u00e0 sourcer du mat\u00e9riel, \u00e0 attendre qu'il soit livr\u00e9 et \u00e0 le brancher.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157053\/","og_site_name":"EENewsEurope","article_published_time":"2021-12-12T17:21:52+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9922_mikroe.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l&#8217;embarqu\u00e9","datePublished":"2021-12-12T17:21:52+00:00","dateModified":"2021-12-12T17:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/"},"wordCount":521,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/","url":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/","name":"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l'embarqu\u00e9 -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-12-12T17:21:52+00:00","dateModified":"2021-12-12T17:21:52+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/mikroe-lance-planet-debug-le-premier-hardware-as-a-service-du-secteur-de-lembarque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"MIKROE lance Planet Debug, le premier \u00ab hardware-as-a-service \u00bb du secteur de l&#8217;embarqu\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157053"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=157053"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/157053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/157054"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=157053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=157053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=157053"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=157053"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=157053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}