{"id":155923,"date":"2021-10-20T05:49:34","date_gmt":"2021-10-20T05:49:34","guid":{"rendered":"https:\/\/\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/"},"modified":"2021-10-20T05:49:34","modified_gmt":"2021-10-20T05:49:34","slug":"apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/","title":{"rendered":"Apple lance une puce 5 nm avec 57 milliards de transistors"},"content":{"rendered":"<p>Apple a lanc\u00e9 sa puce ARM la plus complexe avec 58 processeurs, GPU et c\u0153urs de r\u00e9seau neuronal pour ses ordinateurs portables.<\/p>\n<p>Les puces M1 Max et M1 Pro utilisent la technologie N5 5 nm de TSMC avec une architecture de m\u00e9moire int\u00e9gr\u00e9e au syst\u00e8me sur la puce.&nbsp;Les puces M1 ont un processeur \u00e0 10 c\u0153urs avec huit c\u0153urs hautes performances et deux c\u0153urs \u00e0 haute efficacit\u00e9, s\u2019y ajoutent 16 c\u0153urs GPU dans le M1 Pro et 32 \u200b\u200bdans le M1 max.<\/p>\n<p>Le M1 Pro dispose de 33,7 milliards de transistors avec 200 Go\/s de bande passante m\u00e9moire avec prise en charge jusqu&rsquo;\u00e0 32 Go de m\u00e9moire int\u00e9gr\u00e9e, tandis que le M1 Max avec 57 milliards offre jusqu&rsquo;\u00e0 400 Go\/s de bande passante m\u00e9moire avec jusqu&rsquo;\u00e0 64 Go.<\/p>\n<p>Cela fait suite aux d\u00e9tails d&rsquo;une puce de serveur de 5 nm d\u00e9velopp\u00e9e par Alibaba en Chine avec 128 c\u0153urs pour prendre en charge les puces Graviton bas\u00e9es sur ARM d&rsquo;Amazon.<\/p>\n<p>Johny Srouji, vice-pr\u00e9sident senior des technologies mat\u00e9rielles d&rsquo;Apple d\u00e9clare&nbsp;: \u00ab M1 transforme nos syst\u00e8mes les plus populaires avec des performances incroyables, des technologies personnalis\u00e9es et une remarquable efficacit\u00e9 \u00e9nerg\u00e9tique.&nbsp;Avec M1 Pro et M1 Max, nous sommes les premiers \u00e0 int\u00e9grer des syst\u00e8mes sur puce \u00e0 un ordinateur professionnel. Avec des gains massifs en termes de performances de l&rsquo;unit\u00e9 centrale et du processeur graphique, une bande passante m\u00e9moire jusqu&rsquo;\u00e0 six fois sup\u00e9rieure, un nouveau moteur multim\u00e9dia, des acc\u00e9l\u00e9rateurs ProRes et d&rsquo;autres technologies avanc\u00e9es, M1 Pro et M1 Max poussent le processeur Apple encore plus loin et ne ressemblent \u00e0 rien d&rsquo;autre dans un ordinateur portable professionnel. \u00bb<\/p>\n<hr \/>\n<p>Les deux puces utilisent un moteur multim\u00e9dia con\u00e7u par Apple qui acc\u00e9l\u00e8re le traitement vid\u00e9o tout en maximisant la dur\u00e9e de vie de la batterie, ainsi qu&rsquo;une acc\u00e9l\u00e9ration d\u00e9di\u00e9e pour le codec vid\u00e9o professionnel ProRes introduit dans l&rsquo;iPhone 13.<\/p>\n<p>Les puces comprennent un moteur neuronal \u00e0 16 c\u0153urs pour acc\u00e9l\u00e9rer&nbsp;l&rsquo;apprentissage automatique sur l&rsquo;ordinateur et am\u00e9liorer&nbsp;les performances de l&rsquo;appareil photo, tandis que le processeur de signal vid\u00e9o propre \u00e0 Apple, associ\u00e9 au moteur neuronal, utilise la vid\u00e9o inum\u00e9rique pour am\u00e9liorer la qualit\u00e9 de l&rsquo;image.&nbsp;Un nouveau moteur d&rsquo;affichage pilote plusieurs \u00e9crans externes.<\/p>\n<p>Apple n&rsquo;est qu&rsquo;\u00e0 mi-chemin de sa transition de deux ans vers le silicium bas\u00e9 sur ARM, annonc\u00e9 avec une puce 3nm en d\u00e9veloppement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le M1 Pro d&rsquo;Apple affiche 57 milliards de transistors avec 58 processeurs, GPU et c\u0153urs AI produit par TSMC avec sa technologie 5 nm.<\/p>\n","protected":false},"author":11,"featured_media":155924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[906],"domains":[47],"ppma_author":[1143],"class_list":["post-155923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-mpus-mcus-fr","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Apple lance une puce 5 nm avec 57 milliards de transistors ...<\/title>\n<meta name=\"description\" content=\"Le M1 Pro d&#039;Apple affiche 57 milliards de transistors avec 58 processeurs, GPU et c\u0153urs AI produit par TSMC avec sa technologie 5 nm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155923\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple lance une puce 5 nm avec 57 milliards de transistors\" \/>\n<meta property=\"og:description\" content=\"Le M1 Pro d&#039;Apple affiche 57 milliards de transistors avec 58 processeurs, GPU et c\u0153urs AI produit par TSMC avec sa technologie 5 nm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155923\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-20T05:49:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/apple.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Cardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Apple lance une puce 5 nm avec 57 milliards de transistors\",\"datePublished\":\"2021-10-20T05:49:34+00:00\",\"dateModified\":\"2021-10-20T05:49:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/\"},\"wordCount\":445,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"keywords\":[\"MPUs\/MCUs\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/\",\"url\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/\",\"name\":\"Apple lance une puce 5 nm avec 57 milliards de transistors -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-10-20T05:49:34+00:00\",\"dateModified\":\"2021-10-20T05:49:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple lance une puce 5 nm avec 57 milliards de transistors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Apple lance une puce 5 nm avec 57 milliards de transistors ...","description":"Le M1 Pro d'Apple affiche 57 milliards de transistors avec 58 processeurs, GPU et c\u0153urs AI produit par TSMC avec sa technologie 5 nm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155923\/","og_locale":"fr_FR","og_type":"article","og_title":"Apple lance une puce 5 nm avec 57 milliards de transistors","og_description":"Le M1 Pro d'Apple affiche 57 milliards de transistors avec 58 processeurs, GPU et c\u0153urs AI produit par TSMC avec sa technologie 5 nm.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155923\/","og_site_name":"EENewsEurope","article_published_time":"2021-10-20T05:49:34+00:00","og_image":[{"width":595,"height":407,"url":"https:\/\/cdn.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/apple.jpg","type":"image\/jpeg"}],"author":"Daniel Cardon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/#article","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Apple lance une puce 5 nm avec 57 milliards de transistors","datePublished":"2021-10-20T05:49:34+00:00","dateModified":"2021-10-20T05:49:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/"},"wordCount":445,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"keywords":["MPUs\/MCUs"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/","url":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/","name":"Apple lance une puce 5 nm avec 57 milliards de transistors -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-10-20T05:49:34+00:00","dateModified":"2021-10-20T05:49:34+00:00","breadcrumb":{"@id":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cdn.eenewseurope.com\/fr\/apple-lance-une-puce-5-nm-avec-57-milliards-de-transistors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Apple lance une puce 5 nm avec 57 milliards de transistors"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155923"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=155923"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/155924"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=155923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=155923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=155923"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=155923"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=155923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}