{"id":155534,"date":"2021-11-18T19:01:55","date_gmt":"2021-11-18T19:01:55","guid":{"rendered":"https:\/\/\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/"},"modified":"2021-11-18T19:01:55","modified_gmt":"2021-11-18T19:01:55","slug":"le-cea-et-atos-lancent-le-supercalculateur-exa1","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/","title":{"rendered":"Le CEA et Atos lancent le supercalculateur EXA1"},"content":{"rendered":"<p>Con\u00e7u pour r\u00e9pondre aux besoins du programme Simulation de la Direction des applications militaires du CEA, EXA1 est le&nbsp;supercalculateur&nbsp;bas\u00e9 sur des CPU le plus puissant et le plus \u00e9conome en \u00e9nergie d\u2019Europe. Dot\u00e9 de 12 960 processeurs AMD et de 829 440 c\u0153urs de processeurs, il s\u2019agit&nbsp;du plus grand syst\u00e8me de calcul haute performance (HPC) jamais install\u00e9 dans le monde. Particuli\u00e8rement comp\u00e9titif, EXA1 affiche une puissance de calcul de 23,2 p\u00e9taflops et une consommation d\u2019\u00e9nergie de 4,96 m\u00e9gawatts.<\/p>\n<p><strong>Les b\u00e9n\u00e9fices d\u2019EXA 1<\/strong><\/p>\n<p>EXA 1 est enti\u00e8rement refroidi par de l\u2019eau gr\u00e2ce \u00e0 la solution brevet\u00e9e DLC (Direct Liquid Cooling) d\u2019Atos qui utilise de l\u2019eau ti\u00e8de. Avec un indicateur d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique PUE~1 (Power Usage Effectiveness), EXA1 enregistre les meilleures performances du march\u00e9, avec une consommation d\u2019\u00e9nergie parfaitement contr\u00f4l\u00e9e<\/p>\n<p>La premi\u00e8re partition d\u2019EXA1 est interconnect\u00e9e par la seconde g\u00e9n\u00e9ration de&nbsp;BullSequana eXascale Interconnect (BXI V2). Gr\u00e2ce au d\u00e9chargement mat\u00e9riel complet du m\u00e9canisme de communication dans le BXI V2, l\u2019utilisation du processeur est optimis\u00e9e et permet de pr\u00e9venir les interf\u00e9rences. Les performances de communication des applications HPC \u00e9tant am\u00e9lior\u00e9es par le d\u00e9chargement, les processeurs peuvent se concentrer pleinement sur les t\u00e2ches de calcul tandis que le BXI V2 g\u00e8re ind\u00e9pendamment les communications. Pour garantir des performances de communication \u00e9lev\u00e9es, le supercalculateur tient compte de la bande passante, des latences et des taux de messages.<\/p>\n<hr \/>\n<p><strong>EXA1 au service du programme Simulation du CEA<\/strong><\/p>\n<p>EXA1 r\u00e9pond aux besoins du programme Simulation de la Direction des applications militaires du CEA, dont le but est de garantir la s\u00fbret\u00e9 et la fiabilit\u00e9 des armes nucl\u00e9aires fran\u00e7aises. Ce programme repose notamment sur des simulations num\u00e9riques qui reproduisent la complexit\u00e9 du fonctionnement des armes par une mod\u00e9lisation physique tr\u00e8s pouss\u00e9e. Pour \u00eatre de plus en plus repr\u00e9sentative de ces ph\u00e9nom\u00e8nes complexes, la simulation n\u00e9cessite d\u2019accro\u00eetre en coh\u00e9rence les performances des supercalculateurs. Cela permet de conserver des temps de calcul raisonnables compatibles des d\u00e9lais des programmes de renouvellement des armes nucl\u00e9aires. Le CEA a donc besoin de calculateurs de plus en plus puissants, dimensionn\u00e9s pour satisfaire les exigences de conception et de garantie des armes nucl\u00e9aires. C\u2019est le cas de&nbsp;Tera 1000&nbsp;et d\u00e9sormais d\u2019EXA1. Ces r\u00e9sultats num\u00e9riques sont ensuite valid\u00e9s sur de grandes installations exp\u00e9rimentales de physique, comme le&nbsp;Laser M\u00e9gajoule, et sur les r\u00e9sultats des essais nucl\u00e9aires pass\u00e9s.<\/p>\n<p><a href=\"https:\/\/www.cea.fr\/\" target=\"notSet\" rel=\"noopener\">CEA<\/a><\/p>\n<p><strong>Autres articles :<\/strong>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.ecinews.fr\/news\/supercalculateur-exascale-base-sur-arm-utilise-contre-le-covid-19\" target=\"notSet\" rel=\"noopener\">Supercalculateur exascale bas\u00e9 sur ARM utilis\u00e9 contre le Covid-19<\/a><\/p>\n<p><a href=\"https:\/\/www.ecinews.fr\/news\/un-acces-prioritaire-au-supercalculateur-jean-zay-pour-lutter-contre-le-covid19\" target=\"notSet\" rel=\"noopener\">Un acc\u00e8s prioritaire au supercalculateur Jean Zay pour lutter contre le COVID19<\/a><\/p>\n<p><a href=\"https:\/\/www.ecinews.fr\/news\/le-cea-tera1000-bull-sequana-datos-entre-dans-le-top500-des-supercalculateurs-les-plus\" target=\"notSet\" rel=\"noopener\">Le CEA Tera1000 Bull sequana d\u2019Atos entre dans le TOP500 des supercalculateurs les plus puissants au monde<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le CEA et Atos lancent la premi\u00e8re partition du supercalculateur EXA1. Celle-ci est class\u00e9e en 14\u00e8me\u00a0position du Top 500. Fruit de l\u2019expertise de la Direction des applications militaires du CEA et de l\u2019\u00e9quipe HPC d\u2019Atos, EXA1 est le quatri\u00e8me supercalculateur cod\u00e9velopp\u00e9 par les deux entreprises.<\/p>\n","protected":false},"author":11,"featured_media":155535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"domains":[47],"ppma_author":[1143],"class_list":["post-155534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Le CEA et Atos lancent le supercalculateur EXA1 ...<\/title>\n<meta name=\"description\" content=\"Le CEA et Atos lancent la premi\u00e8re partition du supercalculateur EXA1. Celle-ci est class\u00e9e en 14\u00e8me\u00a0position du Top 500. Fruit de l\u2019expertise de la...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155534\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le CEA et Atos lancent le supercalculateur EXA1\" \/>\n<meta property=\"og:description\" content=\"Le CEA et Atos lancent la premi\u00e8re partition du supercalculateur EXA1. Celle-ci est class\u00e9e en 14\u00e8me\u00a0position du Top 500. Fruit de l\u2019expertise de la Direction des applications militaires du CEA et de l\u2019\u00e9quipe HPC d\u2019Atos, EXA1 est le quatri\u00e8me supercalculateur cod\u00e9velopp\u00e9 par les deux entreprises.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155534\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T19:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/ces_exa_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"535\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Cardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Cardon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/\"},\"author\":{\"name\":\"Daniel Cardon\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\"},\"headline\":\"Le CEA et Atos lancent le supercalculateur EXA1\",\"datePublished\":\"2021-11-18T19:01:55+00:00\",\"dateModified\":\"2021-11-18T19:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/\"},\"wordCount\":508,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/\",\"name\":\"Le CEA et Atos lancent le supercalculateur EXA1 -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-11-18T19:01:55+00:00\",\"dateModified\":\"2021-11-18T19:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le CEA et Atos lancent le supercalculateur EXA1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17\",\"name\":\"Daniel Cardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g\",\"caption\":\"Daniel Cardon\"}}]}<\/script>","yoast_head_json":{"title":"Le CEA et Atos lancent le supercalculateur EXA1 ...","description":"Le CEA et Atos lancent la premi\u00e8re partition du supercalculateur EXA1. Celle-ci est class\u00e9e en 14\u00e8me\u00a0position du Top 500. Fruit de l\u2019expertise de la...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155534\/","og_locale":"fr_FR","og_type":"article","og_title":"Le CEA et Atos lancent le supercalculateur EXA1","og_description":"Le CEA et Atos lancent la premi\u00e8re partition du supercalculateur EXA1. Celle-ci est class\u00e9e en 14\u00e8me\u00a0position du Top 500. Fruit de l\u2019expertise de la Direction des applications militaires du CEA et de l\u2019\u00e9quipe HPC d\u2019Atos, EXA1 est le quatri\u00e8me supercalculateur cod\u00e9velopp\u00e9 par les deux entreprises.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155534\/","og_site_name":"EENewsEurope","article_published_time":"2021-11-18T19:01:55+00:00","og_image":[{"width":535,"height":340,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/ces_exa_1.jpg","type":"image\/jpeg"}],"author":"Daniel Cardon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Cardon","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/"},"author":{"name":"Daniel Cardon","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17"},"headline":"Le CEA et Atos lancent le supercalculateur EXA1","datePublished":"2021-11-18T19:01:55+00:00","dateModified":"2021-11-18T19:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/"},"wordCount":508,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/","url":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/","name":"Le CEA et Atos lancent le supercalculateur EXA1 -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-11-18T19:01:55+00:00","dateModified":"2021-11-18T19:01:55+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/le-cea-et-atos-lancent-le-supercalculateur-exa1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Le CEA et Atos lancent le supercalculateur EXA1"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/93c44cde463762f40a8236eaa44c1c17","name":"Daniel Cardon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/2b243f6bcc1cff7d86aadfb2cd0bd870","url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","caption":"Daniel Cardon"}}]}},"authors":[{"term_id":1143,"user_id":11,"is_guest":0,"slug":"danielcardon","display_name":"Daniel Cardon","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/de9edc136dfc061ad4778e04635baefa?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155534"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=155534"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/155534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/155535"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=155534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=155534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=155534"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=155534"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=155534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}