{"id":13599,"date":"2021-04-27T22:00:29","date_gmt":"2021-04-27T22:00:29","guid":{"rendered":"https:\/\/\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/"},"modified":"2021-04-27T22:00:29","modified_gmt":"2021-04-27T22:00:29","slug":"nouvelles-led-a-puce-blanche-20-cd-en-format-1608","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/","title":{"rendered":"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"vertical-align:top\"><span>Ces derni\u00e8res ann\u00e9es, des LED blanches \u00e0 haute intensit\u00e9 lumineuse sont de plus en plus adopt\u00e9es pour am\u00e9liorer la visibilit\u00e9 dans une gamme d\u2019applications dans les secteurs de l\u2019\u00e9lectronique grand public et de l\u2019automobile. Dans le m\u00eame temps, l\u2019\u00e9mergence d\u2019applications incluant le montage de plusieurs LED dans un petit espace, telles que les appareils IdO et les drones, n\u00e9cessite un montage \u00e0 haute densit\u00e9. Il est donc difficile d\u2019obtenir une luminosit\u00e9 \u00e9lev\u00e9e dans un encombrement compact.<\/p>\n<p><span>Une luminosit\u00e9 \u00e9lev\u00e9e dans une taille ultra-compacte am\u00e9liore la flexibilit\u00e9 de conception<\/span><br \/>\nLa s\u00e9rie CSL1104WB r\u00e9alise une haute intensit\u00e9 lumineuse de 2,0 cd dans un format ultra-compact 1608 (1,6 mm x 0,8 mm) qui \u00e9tait auparavant difficile \u00e0 r\u00e9aliser. Il en r\u00e9sulte la m\u00eame luminosit\u00e9 que l\u2019actuel format de bo\u00eetier grand public PLCC 3528 (3,5 mm x 2,8 mm) mais dans un facteur de forme 87 % plus petit.<\/p>\n<p><u><span>Une chromaticit\u00e9 de couleur blanche, fine et pr\u00e9cise<\/span><\/u><br \/>\nDe plus, la variation de couleur est consid\u00e9rablement am\u00e9lior\u00e9e, ce qui simplifie le processus d\u2019ajustement de couleurs tout en assurant la pr\u00e9cision de la chromaticit\u00e9 de couleur blanche. En plus de contribuer \u00e0 une plus grande \u00e9conomie d\u2019espace d\u2019application, cela am\u00e9liore la flexibilit\u00e9 de conception ainsi que la visibilit\u00e9 gr\u00e2ce au montage \u00e0 haute densit\u00e9 de LED \u00e0 haute luminosit\u00e9, r\u00e9duisant consid\u00e9rablement la charge de d\u00e9veloppement. De plus, la qualification selon la norme de fiabilit\u00e9 automobile AEC-Q102 sp\u00e9cifiquement d\u00e9velopp\u00e9e pour les dispositifs optiques est pr\u00e9vue, permettant une application fluide \u00e0 l\u2019int\u00e9rieur des \u00e9quipements industriels et des applications automobiles expos\u00e9s \u00e0 des environnements difficiles.<\/span><\/p>\n<p class=\"MsoNormal\"><a href=\"http:\/\/www.rohm.com\"><span>www.rohm.com<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROHM a d\u00e9velopp\u00e9 des LED \u00e0 puce blanche ultra-compactes \u00e0 haute intensit\u00e9 lumineuse, les CSL1104WB. Ces produits sont optimis\u00e9s pour les applications n\u00e9cessitant des \u00e9missions de lumi\u00e8re blanche \u00e0 haute luminosit\u00e9, telles que les appareils IdO, les drones et autres applications \u00e9quip\u00e9es de batteries&#8230;. <\/p>\n","protected":false},"author":9,"featured_media":13600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-13599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608 ...<\/title>\n<meta name=\"description\" content=\"ROHM a d\u00e9velopp\u00e9 des LED \u00e0 puce blanche ultra-compactes \u00e0 haute intensit\u00e9 lumineuse, les CSL1104WB. Ces produits sont optimis\u00e9s pour les applications...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/13599\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608\" \/>\n<meta property=\"og:description\" content=\"ROHM a d\u00e9velopp\u00e9 des LED \u00e0 puce blanche ultra-compactes \u00e0 haute intensit\u00e9 lumineuse, les CSL1104WB. Ces produits sont optimis\u00e9s pour les applications n\u00e9cessitant des \u00e9missions de lumi\u00e8re blanche \u00e0 haute luminosit\u00e9, telles que les appareils IdO, les drones et autres applications \u00e9quip\u00e9es de batteries....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/13599\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T22:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9215_rohm-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608\",\"datePublished\":\"2021-04-27T22:00:29+00:00\",\"dateModified\":\"2021-04-27T22:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/\",\"url\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/\",\"name\":\"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608 -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-04-27T22:00:29+00:00\",\"dateModified\":\"2021-04-27T22:00:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608 ...","description":"ROHM a d\u00e9velopp\u00e9 des LED \u00e0 puce blanche ultra-compactes \u00e0 haute intensit\u00e9 lumineuse, les CSL1104WB. Ces produits sont optimis\u00e9s pour les applications...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/13599\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608","og_description":"ROHM a d\u00e9velopp\u00e9 des LED \u00e0 puce blanche ultra-compactes \u00e0 haute intensit\u00e9 lumineuse, les CSL1104WB. Ces produits sont optimis\u00e9s pour les applications n\u00e9cessitant des \u00e9missions de lumi\u00e8re blanche \u00e0 haute luminosit\u00e9, telles que les appareils IdO, les drones et autres applications \u00e9quip\u00e9es de batteries....","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/13599\/","og_site_name":"EENewsEurope","article_published_time":"2021-04-27T22:00:29+00:00","og_image":[{"width":2560,"height":1849,"url":"https:\/\/test.ecinews.fr\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9215_rohm-scaled.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#article","isPartOf":{"@id":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608","datePublished":"2021-04-27T22:00:29+00:00","dateModified":"2021-04-27T22:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/","url":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/","name":"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608 -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-04-27T22:00:29+00:00","dateModified":"2021-04-27T22:00:29+00:00","breadcrumb":{"@id":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.ecinews.fr\/fr\/nouvelles-led-a-puce-blanche-20-cd-en-format-1608\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles LED \u00e0 puce blanche 2,0 cd en format 1608"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/13599"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=13599"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/13599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/13600"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=13599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=13599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=13599"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=13599"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=13599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}