{"id":12395,"date":"2021-05-12T07:40:08","date_gmt":"2021-05-12T07:40:08","guid":{"rendered":"https:\/\/\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/"},"modified":"2021-05-12T07:40:08","modified_gmt":"2021-05-12T07:40:08","slug":"regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/","title":{"rendered":"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique"},"content":{"rendered":"<p class=\"Lead\" style=\"line-height:normal\"><span style=\"font-weight:normal\">Disponibles sous 3 tensions de sortie&nbsp;: 3,3, 5,0 et 12&nbsp;V&nbsp;CC, leur conception efficace permet le fonctionnement \u00e0 pleine charge jusqu\u2019\u00e0 une temp\u00e9rature ambiante de +85&nbsp;\u00b0C sans radiateur ni ventilation forc\u00e9e.<br \/>\nLes r\u00e9gulateurs TSR&nbsp;1.5E offrent d\u2019autres avantages significatifs sur les r\u00e9gulateurs lin\u00e9aires&nbsp;: plus grande pr\u00e9cision, moins de courant d\u2019attente et aucun besoin de condensateurs externes. La gamme TSR&nbsp;1.5E s\u2019adapte \u00e0 un large \u00e9ventail d\u2019applications dans de nombreux environnements. Elle convient particuli\u00e8rement aux projets \u00e0 gros volume pour lesquels elle favorise la r\u00e9duction des co\u00fbts de production en offrant une solution non seulement particuli\u00e8rement \u00e9conomique, mais \u00e9galement parfaitement fiable.<\/span><span style=\"font-weight:normal\"><\/span><\/p>\n<p class=\"Lead\" style=\"line-height:normal\"><span class=\"MsoHyperlink\"><span style=\"font-weight:normal\"><a href=\"http:\/\/www.tracopower.com\">www.tracopower.com<\/a><\/span><\/span><span style=\"font-weight:normal\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Propos\u00e9e par Traco Power, la gamme de r\u00e9gulateurs abaisseurs \u00e0 d\u00e9coupage 1,5 A TSR 1.5E permet de remplacer directement les r\u00e9gulateurs inefficaces LM78xx. Ces r\u00e9gulateurs sont mont\u00e9s d\u2019origine sous bo\u00eetiers ouverts SIP-3 et compl\u00e8tent le catalogue Traco Power de r\u00e9gulateurs POL par une gamme centr\u00e9e sur une conception particuli\u00e8rement \u00e9conomique mais qui reste conforme aux normes de qualit\u00e9.<\/p>\n","protected":false},"author":9,"featured_media":12396,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-12395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9con...<\/title>\n<meta name=\"description\" content=\"Propos\u00e9e par Traco Power, la gamme de r\u00e9gulateurs abaisseurs \u00e0 d\u00e9coupage 1,5 A TSR 1.5E permet de remplacer directement les r\u00e9gulateurs inefficaces...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/12395\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique\" \/>\n<meta property=\"og:description\" content=\"Propos\u00e9e par Traco Power, la gamme de r\u00e9gulateurs abaisseurs \u00e0 d\u00e9coupage 1,5 A TSR 1.5E permet de remplacer directement les r\u00e9gulateurs inefficaces LM78xx. Ces r\u00e9gulateurs sont mont\u00e9s d\u2019origine sous bo\u00eetiers ouverts SIP-3 et compl\u00e8tent le catalogue Traco Power de r\u00e9gulateurs POL par une gamme centr\u00e9e sur une conception particuli\u00e8rement \u00e9conomique mais qui reste conforme aux normes de qualit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/12395\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-12T07:40:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9242_traco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"802\" \/>\n\t<meta property=\"og:image:height\" content=\"596\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique\",\"datePublished\":\"2021-05-12T07:40:08+00:00\",\"dateModified\":\"2021-05-12T07:40:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/\"},\"wordCount\":129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/\",\"name\":\"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-05-12T07:40:08+00:00\",\"dateModified\":\"2021-05-12T07:40:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9con...","description":"Propos\u00e9e par Traco Power, la gamme de r\u00e9gulateurs abaisseurs \u00e0 d\u00e9coupage 1,5 A TSR 1.5E permet de remplacer directement les r\u00e9gulateurs inefficaces...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/12395\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique","og_description":"Propos\u00e9e par Traco Power, la gamme de r\u00e9gulateurs abaisseurs \u00e0 d\u00e9coupage 1,5 A TSR 1.5E permet de remplacer directement les r\u00e9gulateurs inefficaces LM78xx. Ces r\u00e9gulateurs sont mont\u00e9s d\u2019origine sous bo\u00eetiers ouverts SIP-3 et compl\u00e8tent le catalogue Traco Power de r\u00e9gulateurs POL par une gamme centr\u00e9e sur une conception particuli\u00e8rement \u00e9conomique mais qui reste conforme aux normes de qualit\u00e9.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/12395\/","og_site_name":"EENewsEurope","article_published_time":"2021-05-12T07:40:08+00:00","og_image":[{"width":802,"height":596,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9242_traco.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique","datePublished":"2021-05-12T07:40:08+00:00","dateModified":"2021-05-12T07:40:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/"},"wordCount":129,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/","url":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/","name":"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-05-12T07:40:08+00:00","dateModified":"2021-05-12T07:40:08+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/regulateurs-a-decoupage-pol-15-a-sous-boitier-ouvert-economique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9gulateurs \u00e0 d\u00e9coupage POL 1,5 A sous bo\u00eetier ouvert \u00e9conomique"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/12395"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=12395"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/12395\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/12396"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=12395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=12395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=12395"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=12395"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=12395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}