{"id":10095,"date":"2021-06-17T05:32:58","date_gmt":"2021-06-17T05:32:58","guid":{"rendered":"https:\/\/\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/"},"modified":"2021-06-17T05:32:58","modified_gmt":"2021-06-17T05:32:58","slug":"commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies","status":"publish","type":"post","link":"https:\/\/www.ecinews.fr\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/","title":{"rendered":"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s"},"content":{"rendered":"<p>Les commutateurs faibles course pour tensions de commutation AC de 250 V et tensions de commutation DC de 12 V \u00e0 50 V dispensent du montage de commutateurs de r\u00e9seau normaux et \u00e9vitent ainsi les ouvertures dans les rev\u00eatements s\u00e9rigraphi\u00e9s qui garantissent une \u00e9tanch\u00e9it\u00e9 compl\u00e8te en facade. Pour les tensions de commutation DC, leur courant nominal est de 6 A. Les commutateurs KN 19 sont disponibles en version \u00e0 un p\u00f4le avec un contact de rupture et un contact de fermeture ainsi qu\u2019en version \u00e0 deux p\u00f4les avec deux contacts de fermeture. Alternativement au montage sous films, les commutateurs peuvent \u00e9galement \u00eatre \u00e9quip\u00e9s de capots de s\u00e9rie RK 90 de RAFI. Gr\u00e2ce \u00e0 la hauteur de construction standard de 9,7 mm, les KN 19 peuvent \u00eatre combin\u00e9s \u00e0 d\u2019autres boutons-poussoirs \u00e0 faible course et composants \u00e9lectroniques RAFI sur des circuits imprim\u00e9s communs. Le fabricant propose les commutateurs pour le pas 19,05 mm x 38,1 mm \u00e9galement dans des variantes \u00e9clairables.<br \/>\n&nbsp;<br \/>\n<a href=\"http:\/\/www.rafi-france.fr\">www.rafi-france.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce \u00e0 leur structure extr\u00eamement compacte et leur course singuli\u00e8rement courte d\u2019\u00e0 peine 0,55 mm, les commutateurs de r\u00e9seau sous films de la s\u00e9rie KN 19 de RAFI permettent une int\u00e9gration directe dans des syst\u00e8mes de saisie plats. <\/p>\n","protected":false},"author":9,"featured_media":10096,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[881],"tags":[],"domains":[47],"ppma_author":[1141],"class_list":["post-10095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveaux-produits","domains-electronique-eci"],"acf":[],"yoast_head":"<title>Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatem...<\/title>\n<meta name=\"description\" content=\"Gr\u00e2ce \u00e0 leur structure extr\u00eamement compacte et leur course singuli\u00e8rement courte d\u2019\u00e0 peine 0,55 mm, les commutateurs de r\u00e9seau sous films de la...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/10095\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e2ce \u00e0 leur structure extr\u00eamement compacte et leur course singuli\u00e8rement courte d\u2019\u00e0 peine 0,55 mm, les commutateurs de r\u00e9seau sous films de la s\u00e9rie KN 19 de RAFI permettent une int\u00e9gration directe dans des syst\u00e8mes de saisie plats.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/10095\/\" \/>\n<meta property=\"og:site_name\" content=\"EENewsEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T05:32:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9319_rafi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1313\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alain Dieul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alain Dieul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/\"},\"author\":{\"name\":\"Alain Dieul\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\"},\"headline\":\"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s\",\"datePublished\":\"2021-06-17T05:32:58+00:00\",\"dateModified\":\"2021-06-17T05:32:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/\"},\"wordCount\":177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"articleSection\":[\"Nouveaux produits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/\",\"url\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/\",\"name\":\"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s -\",\"isPartOf\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\"},\"datePublished\":\"2021-06-17T05:32:58+00:00\",\"dateModified\":\"2021-06-17T05:32:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecinews.fr\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#website\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"name\":\"EENewsEurope\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#organization\",\"name\":\"EENewsEurope\",\"url\":\"https:\/\/cdn.eenewseurope.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg\",\"width\":283,\"height\":113,\"caption\":\"EENewsEurope\"},\"image\":{\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf\",\"name\":\"Alain Dieul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g\",\"caption\":\"Alain Dieul\"}}]}<\/script>","yoast_head_json":{"title":"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatem...","description":"Gr\u00e2ce \u00e0 leur structure extr\u00eamement compacte et leur course singuli\u00e8rement courte d\u2019\u00e0 peine 0,55 mm, les commutateurs de r\u00e9seau sous films de la...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/10095\/","og_locale":"fr_FR","og_type":"article","og_title":"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s","og_description":"Gr\u00e2ce \u00e0 leur structure extr\u00eamement compacte et leur course singuli\u00e8rement courte d\u2019\u00e0 peine 0,55 mm, les commutateurs de r\u00e9seau sous films de la s\u00e9rie KN 19 de RAFI permettent une int\u00e9gration directe dans des syst\u00e8mes de saisie plats.","og_url":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/10095\/","og_site_name":"EENewsEurope","article_published_time":"2021-06-17T05:32:58+00:00","og_image":[{"width":1313,"height":1500,"url":"https:\/\/www.eenewseurope.com\/wp-content\/uploads\/import\/default\/files\/sites\/default\/files\/images\/eci9319_rafi.jpg","type":"image\/jpeg"}],"author":"Alain Dieul","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alain Dieul","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#article","isPartOf":{"@id":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/"},"author":{"name":"Alain Dieul","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf"},"headline":"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s","datePublished":"2021-06-17T05:32:58+00:00","dateModified":"2021-06-17T05:32:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/"},"wordCount":177,"commentCount":0,"publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"articleSection":["Nouveaux produits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/","url":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/","name":"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s -","isPartOf":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#website"},"datePublished":"2021-06-17T05:32:58+00:00","dateModified":"2021-06-17T05:32:58+00:00","breadcrumb":{"@id":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eenewseurope.com\/fr\/commutateur-de-reseau-faible-course-pour-montage-sous-revetements-serigraphies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecinews.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Commutateur de r\u00e9seau faible course pour montage sous rev\u00eatements s\u00e9rigraphi\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/cdn.eenewseurope.com\/en\/#website","url":"https:\/\/cdn.eenewseurope.com\/en\/","name":"EENewsEurope","description":"Just another WordPress site","publisher":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdn.eenewseurope.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cdn.eenewseurope.com\/en\/#organization","name":"EENewsEurope","url":"https:\/\/cdn.eenewseurope.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","contentUrl":"https:\/\/www.ecinews.fr\/wp-content\/uploads\/2022\/02\/logo-1.jpg","width":283,"height":113,"caption":"EENewsEurope"},"image":{"@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/568c789a4794bd460460501ba91f5daf","name":"Alain Dieul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cdn.eenewseurope.com\/en\/#\/schema\/person\/image\/6d32dc651fbcef3b338066625b118364","url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","caption":"Alain Dieul"}}]}},"authors":[{"term_id":1141,"user_id":9,"is_guest":0,"slug":"alaindieul","display_name":"Alain Dieul","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/93708ec89b35deb10f4cfbfe144b4e07?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/10095"}],"collection":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/comments?post=10095"}],"version-history":[{"count":0,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/posts\/10095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media\/10096"}],"wp:attachment":[{"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/media?parent=10095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/categories?post=10095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/tags?post=10095"},{"taxonomy":"domains","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/domains?post=10095"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ecinews.fr\/fr\/wp-json\/wp\/v2\/ppma_author?post=10095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}